{"id":73892,"date":"2026-03-18T06:38:10","date_gmt":"2026-03-18T06:38:10","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/melia-sallie-a-tcc-land-asset-world-afin-douvrir-trois-hotels-en-thailande-2\/"},"modified":"2026-08-21T04:14:33","modified_gmt":"2026-08-21T04:14:33","slug":"melia-sallie-a-tcc-land-asset-world-afin-douvrir-trois-hotels-en-thailande-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/melia-sallie-a-tcc-land-asset-world-afin-douvrir-trois-hotels-en-thailande-2\/","title":{"rendered":"Meli\u00e1 s\u2019allie \u00e0 TCC Land Asset World afin d\u2019ouvrir trois h\u00f4tels en Tha\u00eflande"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Madrid, 29 oct. (EP)  Meli\u00e1 Hotels International a sign\u00e9 un accord strat\u00e9gique avec TCC Land Asset World, groupe d\u2019entreprises leader en Tha\u00eflande et membre de TCC Group, afin d\u2019ouvrir ses trois premiers h\u00f4tels dans le pays d\u2019ici trois ans, a inform\u00e9 la cha\u00eene Majorquine.  Gr\u00e2ce \u00e0 cette entr\u00e9e dans le deuxi\u00e8me pays le plus visit\u00e9 du sud-est asiatique, Meli\u00e1 concentre d\u00e9j\u00e0 40% de ses futurs projets en Asie, stimule son expansion dans la r\u00e9gion et ach\u00e8ve sa tourn\u00e9e dans le continent asiatique.  Meli\u00e1 et TCC Land Asset World sont d\u00e9j\u00e0 forts d\u2019une longue trajectoire en collaboration initi\u00e9e avec l\u2019h\u00f4tel Meli\u00e1 \u00e0 Hanoi, qui culmine gr\u00e2ce \u00e0 la signature de cet accord strat\u00e9gique.  En vertu de celui-ci, au cours de cette premi\u00e8re phase de trois ans, les deux soci\u00e9t\u00e9s d\u00e9velopperont trois h\u00f4tels : un resort de la marque &lsquo;Sol Beach House&rsquo; \u00e0 Koh Samui, la troisi\u00e8me plus grande \u00eele du pays, qui re\u00e7oit annuellement 1,5 million de touristes.  Cet \u00e9tablissement sera issu de la transformation de l\u2019actuel Imperial Boat Koh Samui, qui ouvrira ses portes dans un d\u00e9lai de deux ans.  Puis, un deuxi\u00e8me h\u00f4tel de la marque MW by Meli\u00e1 \u00e0 Bangkok et un resort de la marque Paradisus, adress\u00e9 au segment vacances de luxe tout compris, dans un emplacement non encore annonc\u00e9.  L\u2019accord pr\u00e9voit une croissance plus importante \u00e0 l\u2019avenir, aussi bien \u00e0 l\u2019int\u00e9rieur qu\u2019\u00e0 l\u2019ext\u00e9rieur de la Tha\u00eflande, dans les meilleures destinations telles que Bangkok, Phuket, Koh Samui ou Pattaya.  L\u2019expansion dans la r\u00e9gion Asie-Pacifique est strat\u00e9gique pour Meli\u00e1, une destination vedette pour des march\u00e9s comme l\u2019Allemagne, la Russie ou l\u2019Europe de l\u2019Est.  EUROPA PRESS &#8211; Le Courrier d&rsquo;Espagne avec Sol Marzellier de Pablo (www.smtraductores.com)<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 29 oct. (EP) Meli\u00e1 Hotels International a sign\u00e9 un accord strat\u00e9gique avec TCC Land Asset World, groupe d\u2019entreprises leader en Tha\u00eflande et membre de TCC Group, afin d\u2019ouvrir ses trois premiers h\u00f4tels dans le pays d\u2019ici trois ans, a inform\u00e9 la cha\u00eene Majorquine. Gr\u00e2ce \u00e0 cette entr\u00e9e dans le deuxi\u00e8me pays le plus visit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":41836,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[384,799,660],"class_list":["post-73892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-business","tag-hotellerie","tag-tourisme"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=73892"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/41836"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=73892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=73892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=73892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}