{"id":73655,"date":"2026-03-18T02:12:38","date_gmt":"2026-03-18T02:12:38","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/recette-croquettes-de-jambon-2\/"},"modified":"2026-07-13T11:49:56","modified_gmt":"2026-07-13T11:49:56","slug":"recette-croquettes-de-jambon-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/18\/recette-croquettes-de-jambon-2\/","title":{"rendered":"Recette croquettes de jambon"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Les recettes reviennent avec une id\u00e9e de tapas qui plait aux petits comme aux grands !<\/p>\n<p><span style=\"text-decoration: underline\">Ingr\u00e9dients :<\/span><\/p>\n<ul>\n<li>200g de jambon serrano<\/li>\n<li>1 oignon<\/li>\n<li>1 gousse d&rsquo;ail<\/li>\n<li>100g de farine<\/li>\n<li>100g de beurre (peut \u00eatre remplac\u00e9 par 100ml d&rsquo;huile d&rsquo;olive)<\/li>\n<li>1 L de lait<\/li>\n<li>Persil hach\u00e9<\/li>\n<\/ul>\n<p>Pour la friture :<\/p>\n<ul>\n<li>Farine<\/li>\n<li>3 oeufs<\/li>\n<li>Chapelure<\/li>\n<li>Huile d&rsquo;olive<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline\">La r\u00e9alisation :<\/span><\/p>\n<p>1. Couper le beurre en morceaux et le faire fondre dans une casserole.<\/p>\n<p>2. H\u00e2cher finement l&rsquo;oignon et la gousse d&rsquo;ail, puis l&rsquo;ajouter au beurre dans la casserole.<\/p>\n<p>3. Attendre 5 \u00e0 6 minutes puis incorporer le jambon hach\u00e9 et le faire revenir.<\/p>\n<p>4. Ajouter les 100g de farine.<\/p>\n<p>5. Ajouter le lait petit \u00e0 petit tout en remuant.<\/p>\n<p>6. Faire cuire pendant 20 minutes en remuant constamment.<\/p>\n<p>7. Saupoudrer de persil hach\u00e9<\/p>\n<p>8. Etaler la p\u00e2te sur un plat et la laisser refroidir.<\/p>\n<p>9. Une fois la p\u00e2te refroidie, couper et former les croquettes.<\/p>\n<p>10. Dans une\u00a0po\u00eale, faire chauffer de l&rsquo;huile.<\/p>\n<p>11. Enrouler les croquettes de la farine, des oeufs battus et de la chapelure avant de les faire baigner dans l&rsquo;huile bien chaude.<\/p>\n<p>12. Quand elles sont bien frites, retirer de la po\u00eale\u00a0et enlever l&rsquo;exc\u00e8s d&rsquo;huile.<\/p>\n<p style=\"text-align: center\">Vous pouvez servir !<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les recettes reviennent avec une id\u00e9e de tapas qui plait aux petits comme aux grands ! Ingr\u00e9dients : 200g de jambon serrano 1 oignon 1 gousse d&rsquo;ail 100g de farine 100g de beurre (peut \u00eatre remplac\u00e9 par 100ml d&rsquo;huile d&rsquo;olive) 1 L de lait Persil hach\u00e9 Pour la friture : Farine 3 oeufs Chapelure Huile [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":41015,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4440],"tags":[],"class_list":["post-73655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-networking"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=73655"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/73655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/41015"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=73655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=73655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=73655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}