{"id":71916,"date":"2026-03-10T05:25:52","date_gmt":"2026-03-10T05:25:52","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/dazia-120-millions-deuros-en-2020-pour-se-renforcer-a-madrid-et-sur-la-costa-del-sol-2\/"},"modified":"2026-07-12T09:01:52","modified_gmt":"2026-07-12T09:01:52","slug":"dazia-120-millions-deuros-en-2020-pour-se-renforcer-a-madrid-et-sur-la-costa-del-sol-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/dazia-120-millions-deuros-en-2020-pour-se-renforcer-a-madrid-et-sur-la-costa-del-sol-2\/","title":{"rendered":"Dazia : 120 millions d&rsquo;euros en 2020 pour se renforcer \u00e0 Madrid et sur la Costa del Sol"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"long\"><span style=\"font-weight: 400\">Le groupe immobilier concentrera ses efforts sur le march\u00e9 r\u00e9sidentiel de Madrid et de la Costa del Sol, tout en scellant son entr\u00e9e sur le march\u00e9 de Barcelone. (EjePrime)<br \/>\n<\/span><\/p>\n<p class=\"long\"><span class=\"times-dropcap\">D<\/span>azia augmente son investissement. Le groupe immobilier dirig\u00e9 par Daniel Mazin pr\u00e9voit d&rsquo;investir 120 millions d&rsquo;euros dans les ann\u00e9es \u00e0 venir \u00a0\u00bb bien que si nous pouvons le faire d\u00e8s 2020, nous le ferons \u00ab\u00a0, comme l&rsquo;a expliqu\u00e9 le dirigeant. L&rsquo;objectif de la soci\u00e9t\u00e9 est de poursuivre ses efforts sur le march\u00e9 r\u00e9sidentiel de Madrid et de la Costa del Sol, auquel elle pr\u00e9voit d&rsquo;ajouter Barcelone. La capitale catalane \u00a0\u00bb est un march\u00e9 tr\u00e8s puissant et int\u00e9ressant \u00ab\u00a0, affirme M. Mazin, qui admet que \u00a0\u00bb nous restons tout de m\u00eame tr\u00e8s prudents \u00a0\u00bb en raison des difficult\u00e9s r\u00e9glementaires qui r\u00e9gissent le march\u00e9 de Barcelone.<\/p>\n<p>Le groupe immobilier ratisse le march\u00e9 \u00e0 la recherche de propri\u00e9t\u00e9s \u00e0 r\u00e9habiliter, d&rsquo;immeubles avec et sans locataires ou de terrains o\u00f9 lever de nouveaux actifs immobiliers par l&rsquo;interm\u00e9diaire de sa filiale Darya Homes.<\/p>\n<h4>Dazia Capital commercialisera quatre projets r\u00e9sidentiels \u00e0 Madrid \u00e0 partir du mois de mars<\/h4>\n<p>Mazin dit qu&rsquo;ils ont \u00e9galement un \u0153il sur le march\u00e9 des bureaux, la soci\u00e9t\u00e9 s&rsquo;y est d\u00e9j\u00e0 immisc\u00e9e tout au long de 2019. \u00ab\u00a0Nous pourrions investir \u00e0 nouveau dans ce segment, bien que le march\u00e9 r\u00e9sidentiel reste notre priorit\u00e9.\u00a0\u00bb<\/p>\n<p>D&rsquo;autre part, le directeur de la soci\u00e9t\u00e9 a expliqu\u00e9 qu&rsquo;elle lancera en mars la commercialisation de quatre nouveaux projets r\u00e9sidentiels \u00e0 Madrid. Plus pr\u00e9cis\u00e9ment, il s&rsquo;agit des immeubles situ\u00e9s aux num\u00e9ros 3 et 129 de la rue Santa Engracia, au num\u00e9ro 9 de la rue Santa Isabel et au num\u00e9ro 107 de la rue Embajadores.<\/p>\n<p>\u00ab\u00a0A Madrid, la demande continue d&rsquo;\u00eatre bonne \u00ab\u00a0, assure Mazin, qui pr\u00e9voit une stabilisation des prix. \u00ab\u00a0Dans certaines zones \u00e0 la p\u00e9riph\u00e9rie du centre, cela va continuer \u00e0 augmenter, mais \u00e0 l&rsquo;int\u00e9rieur de la M30 cela se maintiendra comme aujourd&rsquo;hui\u00a0\u00bb, a-t-il dit.<\/p>\n<hr \/>\n<div>Source et suite : <a href=\"https:\/\/www.ejeprime.com\/empresa\/dazia-homes-120-millones-de-euros-en-2020-para-hacerse-fuerte-en-madrid-y-costa-del-sol.html\">EjePrime\u00a0<\/a><\/div>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe immobilier concentrera ses efforts sur le march\u00e9 r\u00e9sidentiel de Madrid et de la Costa del Sol, tout en scellant son entr\u00e9e sur le march\u00e9 de Barcelone. (EjePrime) Dazia augmente son investissement. Le groupe immobilier dirig\u00e9 par Daniel Mazin pr\u00e9voit d&rsquo;investir 120 millions d&rsquo;euros dans les ann\u00e9es \u00e0 venir \u00a0\u00bb bien que si nous [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":34066,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1083,701,1013],"class_list":["post-71916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-dazia","tag-immobilier","tag-immobilier-en-espagne"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=71916"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/34066"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=71916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=71916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=71916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}