{"id":71751,"date":"2026-03-10T02:37:58","date_gmt":"2026-03-10T02:37:58","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/le-coronavirus-donne-des-ailes-aux-bureaux-flex-pour-diversifier-les-risques-2\/"},"modified":"2026-07-12T06:05:44","modified_gmt":"2026-07-12T06:05:44","slug":"le-coronavirus-donne-des-ailes-aux-bureaux-flex-pour-diversifier-les-risques-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/le-coronavirus-donne-des-ailes-aux-bureaux-flex-pour-diversifier-les-risques-2\/","title":{"rendered":"Le coronavirus donne des ailes aux bureaux \u00abflex\u00bb pour diversifier les risques"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"long\">La crise provoqu\u00e9e par le Covid-19 peut conduire les entreprises \u00e0 parier sur ce type d&rsquo;espace en raison de la r\u00e9duction des risques que cela comporte en ayant des contrats plus courts.<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">L<\/span>e coronavirus donne des ailes aux bureaux \u00abflex\u00bb pour diversifier les risques Flex gagne en attractivit\u00e9 gr\u00e2ce au coronavirus. Dans une soci\u00e9t\u00e9 o\u00f9 le paiement par r\u00e9partition se g\u00e9n\u00e9ralise, la crise provoqu\u00e9e par le Covid-19 pourrait conduire cette tendance \u00e0 la location de bureaux.<\/p>\n<p class=\"\">Les entreprises peuvent consid\u00e9rer les espaces de travail flexibles comme une alternative attrayante qui leur permet de diversifier les risques et de pouvoir prendre des d\u00e9cisions plus rapidement.<\/p>\n<p class=\"\">Le ralentissement \u00e9conomique connu le mois dernier, qui a conduit de nombreuses entreprises \u00e0 d\u00e9poser des dossiers de r\u00e9glementation du travail temporaire (Erte), ajout\u00e9 \u00e0 l&rsquo;isolement obligatoire pour la majeure partie de la population, a entra\u00een\u00e9 la vacance des bureaux pendant que leurs locataires ils doivent continuer \u00e0 payer les loyers.<\/p>\n<p class=\"\">En ce sens, le PDG de Merlin, Ismael Clemente, a expliqu\u00e9 au cours d&rsquo;un webinaire organis\u00e9 par EjePrime que les entreprises \u00ab\u00a0se sentiront d\u00e9sormais plus tent\u00e9es de se lancer dans le flex, car le contrat va de mois en mois et cela supprime des co\u00fbts fixe \u00e0 garantir.<\/p>\n<p>Source et suite <a href=\"https:\/\/www.ejeprime.com\/empresa\/el-coronavirus-da-alas-a-las-oficinas-flex-para-diversificar-riesgos.html\">Ejeprime<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crise provoqu\u00e9e par le Covid-19 peut conduire les entreprises \u00e0 parier sur ce type d&rsquo;espace en raison de la r\u00e9duction des risques que cela comporte en ayant des contrats plus courts. Le coronavirus donne des ailes aux bureaux \u00abflex\u00bb pour diversifier les risques Flex gagne en attractivit\u00e9 gr\u00e2ce au coronavirus. Dans une soci\u00e9t\u00e9 o\u00f9 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":33280,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,4504],"tags":[1207,857],"class_list":["post-71751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-resilience-agri","tag-bureaux-immobilier-espagne","tag-networking"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=71751"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/33280"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=71751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=71751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=71751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}