{"id":71746,"date":"2026-03-10T02:33:59","date_gmt":"2026-03-10T02:33:59","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/lhotel-puerta-de-america-madrid-est-sur-le-marche-pour-60-millions-deuros-2\/"},"modified":"2026-07-12T06:00:49","modified_gmt":"2026-07-12T06:00:49","slug":"lhotel-puerta-de-america-madrid-est-sur-le-marche-pour-60-millions-deuros-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/lhotel-puerta-de-america-madrid-est-sur-le-marche-pour-60-millions-deuros-2\/","title":{"rendered":"L&rsquo;h\u00f4tel Puerta de Am\u00e9rica (Madrid) est sur le march\u00e9 pour 60 millions d&rsquo;euros"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"long\">Bank of America Corporation envisage de vendre l&rsquo;h\u00f4tel Puerta de Am\u00e9rica \u00e0 Madrid pour environ 60 millions d&rsquo;euros. (idealista\/news)<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">L<\/span>e propri\u00e9taire de l&rsquo;actif pr\u00e9voit d&rsquo;\u00e9tablir un processus r\u00e9glement\u00e9 de d\u00e9sinvestissement dans cet immeuble embl\u00e9matique de la capitale, apr\u00e8s l&rsquo;avoir achet\u00e9 il y a trois ans pour 16,3 millions, selon <em>El Economista<\/em>.<\/p>\n<p>Aux alentours de l&rsquo;entr\u00e9e nord de la capitale -par la route- est \u00e9rig\u00e9 un b\u00e2timent qui parvient imm\u00e9diatement \u00e0 capter l&rsquo;attention de tous. C&rsquo;est l&rsquo;h\u00f4tel Puerta de Am\u00e9rica et il vient d&rsquo;accrocher le panneau \u00ab\u00a0\u00e0 vendre\u00a0\u00bb. Le complexe compte 315 pi\u00e8ces, et avant d&rsquo;\u00eatre vendu \u00e0 Bank of America, il \u00e9tait l&rsquo;actif le plus important de la soci\u00e9t\u00e9 espagnole Urvasco. Cette soci\u00e9t\u00e9 l&rsquo;a c\u00e9d\u00e9 en mars 2017 pour 16,3 millions d&rsquo;euros et les nouveaux propri\u00e9taires ont maintenant l&rsquo;intention de faire environ quatre fois plus de b\u00e9n\u00e9fices.<\/p>\n<p>Cette op\u00e9ration, pr\u00e9vue par Bank of America, a d\u00e9j\u00e0 \u00e9t\u00e9 r\u00e9alis\u00e9e avec un autre bien acquis pr\u00e9c\u00e9demment aupr\u00e8s d&rsquo;Urvasco. Il s&rsquo;agit de l&rsquo;ancien h\u00f4tel Silken Diagonal (Barcelone) que le groupe am\u00e9ricain a achet\u00e9 \u00e0 la soci\u00e9t\u00e9 basque en 2015, puis vendu un an plus tard pour obtenir une plus-value de 50 millions d&rsquo;euros.<\/p>\n<p>Toutefois, le cas de l&rsquo;h\u00f4tel Puerta de America est diff\u00e9rent, car l&rsquo;\u00e9tablissement avait besoin d&rsquo;une s\u00e9rie de r\u00e9formes pour \u00eatre plus efficace d&rsquo;un point de vue op\u00e9rationnel avant de pouvoir \u00eatre vendu. Valnest Hospitality a jou\u00e9 un r\u00f4le majeur dans ce travail d&rsquo;am\u00e9lioration des co\u00fbts de fonctionnement et a \u00e9t\u00e9 responsable de la gestion de ce domaine ces derni\u00e8res ann\u00e9es.<\/p>\n<p>Aujourd&rsquo;hui, apr\u00e8s avoir proc\u00e9d\u00e9 \u00e0 ces changements, Bank of America a commenc\u00e9 \u00e0 \u00e9tudier le march\u00e9 pour aiguiser l&rsquo;app\u00e9tit des investisseurs. Le probl\u00e8me est qu&rsquo;il s&rsquo;est trouv\u00e9 &#8211; comme tous les agents du secteur &#8211; dans un sc\u00e9nario d&rsquo;incertitude g\u00e9n\u00e9r\u00e9 par le coronavirus. En outre, l&rsquo;h\u00f4tel pr\u00e9sente un autre inconv\u00e9nient bureaucratique qui pourrait compromettre le d\u00e9sinvestissement. Le complexe est construit sur un site appartenant \u00e0 la Fundaci\u00f3n Ap\u00f3stol Santiago &#8211; c&rsquo;est-\u00e0-dire qu&rsquo;il s&rsquo;agit d&rsquo;une concession &#8211; et cela pourrait effrayer les investisseurs.<\/p>\n<hr \/>\n<p>Source et suite : <a href=\"https:\/\/www.idealista.com\/news\/inmobiliario\/empresas\/2020\/04\/08\/781659-el-hotel-puerta-de-america-madrid-esta-en-el-mercado-por-60-millones-de-euros\">idealista\/news<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bank of America Corporation envisage de vendre l&rsquo;h\u00f4tel Puerta de Am\u00e9rica \u00e0 Madrid pour environ 60 millions d&rsquo;euros. (idealista\/news) Le propri\u00e9taire de l&rsquo;actif pr\u00e9voit d&rsquo;\u00e9tablir un processus r\u00e9glement\u00e9 de d\u00e9sinvestissement dans cet immeuble embl\u00e9matique de la capitale, apr\u00e8s l&rsquo;avoir achet\u00e9 il y a trois ans pour 16,3 millions, selon El Economista. Aux alentours de l&rsquo;entr\u00e9e [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":33252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1205,1037,375],"class_list":["post-71746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-hotel-puerta-de-america","tag-hotels-en-espagne","tag-madrid"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=71746"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/33252"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=71746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=71746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=71746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}