{"id":71627,"date":"2026-03-10T00:47:34","date_gmt":"2026-03-10T00:47:34","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/pas-de-maison-sur-la-plage-a-cause-du-covid-19-2\/"},"modified":"2026-07-12T04:13:48","modified_gmt":"2026-07-12T04:13:48","slug":"pas-de-maison-sur-la-plage-a-cause-du-covid-19-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/pas-de-maison-sur-la-plage-a-cause-du-covid-19-2\/","title":{"rendered":"Pas de maison sur la plage \u00e0 cause du Covid-19"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"long\">Banco de Espa\u00f1a annule la location des appartements de vacances de ses employ\u00e9s en raison du coronavirus. (EjePrime)<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">P<\/span>as d&rsquo;appartement de vacances \u00e0 cause du coronavirus. La Banque d&rsquo;Espagne a d\u00e9clar\u00e9 non viable l&rsquo;appel d&rsquo;offres d&rsquo;un million d&rsquo;euros annonc\u00e9 en d\u00e9but d&rsquo;ann\u00e9e pour la location de 123 appartements sur la c\u00f4te afin que ses employ\u00e9s puissent passer leurs vacances d&rsquo;\u00e9t\u00e9.<\/p>\n<p>L&rsquo;entit\u00e9 a invoqu\u00e9 l&rsquo;incertitude g\u00e9n\u00e9r\u00e9e par le coronavirus et les limites de la mobilit\u00e9 entre les provinces pour les loisirs comme raisons pour ne pas aller de l&rsquo;avant avec le processus, pour lequel quatre entreprises avaient soumissionn\u00e9.<\/p>\n<p>La p\u00e9riode pr\u00e9vue d&rsquo;occupation des foyers se situait entre juin et septembre et devait \u00eatre r\u00e9partie en s\u00e9jours de quinze jours entre les employ\u00e9s ayant obtenu le plus de points, en tenant compte de leur situation familiale, de leur rang au sein de la Banque d&rsquo;Espagne et de leur anciennet\u00e9.<\/p>\n<hr \/>\n<p>Source et suite\u00a0: <a href=\"https:\/\/www.ejeprime.com\/m2\/sin-casa-en-la-playa-por-el-covid-19.html\">EjePrime<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Banco de Espa\u00f1a annule la location des appartements de vacances de ses employ\u00e9s en raison du coronavirus. (EjePrime) Pas d&rsquo;appartement de vacances \u00e0 cause du coronavirus. La Banque d&rsquo;Espagne a d\u00e9clar\u00e9 non viable l&rsquo;appel d&rsquo;offres d&rsquo;un million d&rsquo;euros annonc\u00e9 en d\u00e9but d&rsquo;ann\u00e9e pour la location de 123 appartements sur la c\u00f4te afin que ses employ\u00e9s [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":32790,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,4504],"tags":[1103,1005],"class_list":["post-71627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-resilience-agri","tag-banco-de-espana","tag-vacances"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=71627"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/32790"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=71627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=71627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=71627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}