{"id":71626,"date":"2026-03-10T00:47:27","date_gmt":"2026-03-10T00:47:27","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/reuben-achete-un-terrain-dans-le-domaine-de-san-juan-pour-y-construire-650-maisons-et-un-hotel-2\/"},"modified":"2026-07-12T04:13:42","modified_gmt":"2026-07-12T04:13:42","slug":"reuben-achete-un-terrain-dans-le-domaine-de-san-juan-pour-y-construire-650-maisons-et-un-hotel-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/reuben-achete-un-terrain-dans-le-domaine-de-san-juan-pour-y-construire-650-maisons-et-un-hotel-2\/","title":{"rendered":"Reuben ach\u00e8te un terrain dans le domaine de San Juan pour y construire 650 maisons et un h\u00f4tel"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Le secteur r\u00e9sidentiel reprend petit \u00e0 petit le dessus. (idealista\/news)<\/p>\n<p><span class=\"times-dropcap\">L<\/span>e secteur r\u00e9sidentiel reprend lentement le dessus. Reuben Brothers, une soci\u00e9t\u00e9 d&rsquo;investissement priv\u00e9 et immobili\u00e8re, a annonc\u00e9 l&rsquo;acquisition de 250 hectares dans la municipalit\u00e9 de San Mart\u00edn de Valdeiglesias, \u00e0 c\u00f4t\u00e9 du domaine de San Juan, l&rsquo;une des plus grandes zones de d\u00e9veloppement urbain de la Communaut\u00e9 de Madrid.<\/p>\n<p>Environ 90 hectares de ce terrain ont \u00e9t\u00e9 class\u00e9s comme terrain urbain \u00e0 usage r\u00e9sidentiel et h\u00f4telier, ce qui signifie que pr\u00e8s de 147.000 m2 pourront \u00eatre utilis\u00e9s pour la construction de 650 maisons et d&rsquo;un h\u00f4tel de 7.350 m2.<\/p>\n<p>Ce territoire, plus vaste que la Principaut\u00e9 de Monaco, est bord\u00e9 par le barrage de San Juan, le seul barrage navigable \u00e0 moteur et \u00e0 voile de la Communaut\u00e9 de Madrid, o\u00f9 se trouve \u00e9galement la plage de la Virgen de la Nueva, premi\u00e8re plage de la Communaut\u00e9 de Madrid \u00e0 avoir obtenu le drapeau bleu.<\/p>\n<p>Ces derni\u00e8res ann\u00e9es, la zone a \u00e9t\u00e9 choisie comme r\u00e9sidence secondaire par plusieurs personnes et familles c\u00e9l\u00e8bres de haut niveau social, car il s&rsquo;agit d&rsquo;une zone d\u00e9velopp\u00e9e, proche de la capitale espagnole et o\u00f9 l&rsquo;on peut pratiquer un grand nombre d&rsquo;activit\u00e9s telles que le bateau \u00e0 voile ou \u00e0 moteur, le ski nautique, le wakeboard, les sports de moto, l&rsquo;\u00e9quitation, la randonn\u00e9e ou encore le <em>flyboard<\/em>, etc.<\/p>\n<p>Parmi les personnes c\u00e9l\u00e8bres qui ont leur r\u00e9sidence secondaire dans la r\u00e9gion, citons le pilote de Formule 1 Carlos Sainz, l&rsquo;entra\u00eeneur du Real Madrid et ancien joueur de football Zinedine Zidane, le pr\u00e9sident de l&rsquo;Atl\u00e9tico de Madrid Enrique Cerezo et la famille royale bulgare, entre autres.<\/p>\n<p>De plus, le terrain est strat\u00e9giquement situ\u00e9 \u00e0 moins d&rsquo;une heure de route de Madrid (\u00e0 environ 74 km), ainsi que d&rsquo;Avila (54 km) et de Tol\u00e8de (79 km), deux villes inscrites au patrimoine mondial.<\/p>\n<p>\u00ab\u00a0Nous nous sommes engag\u00e9s \u00e0 investir en Espagne dans le secteur immobilier, en mettant l&rsquo;accent sur les actifs de qualit\u00e9 et le d\u00e9veloppement de nouveaux projets \u00e0 valeur ajout\u00e9e. Nous sommes heureux d&rsquo;avoir trouv\u00e9 un site appropri\u00e9 dans un endroit aussi exceptionnel, si proche de la capitale. Nous sommes convaincus que le d\u00e9veloppement de Canto Redondo sera un nouveau succ\u00e8s qui viendra compl\u00e9ter notre portefeuille, alors que nous continuons \u00e0 explorer de nouvelles opportunit\u00e9s sur le march\u00e9 espagnol\u00a0\u00bb, a d\u00e9clar\u00e9 un porte-parole de Reuben Brothers.<\/p>\n<hr \/>\n<p>Source et suite\u00a0: <a href=\"https:\/\/www.idealista.com\/news\/inmobiliario\/vivienda\/2020\/05\/27\/783199-los-reuben-compran-suelo-en-el-pantano-de-san-juan-para-650-viviendas-y-un-hotel\">idealista\/news<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secteur r\u00e9sidentiel reprend petit \u00e0 petit le dessus. (idealista\/news) Le secteur r\u00e9sidentiel reprend lentement le dessus. Reuben Brothers, une soci\u00e9t\u00e9 d&rsquo;investissement priv\u00e9 et immobili\u00e8re, a annonc\u00e9 l&rsquo;acquisition de 250 hectares dans la municipalit\u00e9 de San Mart\u00edn de Valdeiglesias, \u00e0 c\u00f4t\u00e9 du domaine de San Juan, l&rsquo;une des plus grandes zones de d\u00e9veloppement urbain de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":32786,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,4506],"tags":[1071,1013,1101,1102],"class_list":["post-71626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-projets-immo","tag-construction","tag-immobilier-en-espagne","tag-reuben-brothers","tag-san-juan"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=71626"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/32786"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=71626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=71626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=71626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}