{"id":71591,"date":"2026-03-10T00:17:03","date_gmt":"2026-03-10T00:17:03","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/le-hard-rock-cafe-ferme-ses-portes-a-madrid-le-31-juillet-2\/"},"modified":"2026-07-12T03:41:45","modified_gmt":"2026-07-12T03:41:45","slug":"le-hard-rock-cafe-ferme-ses-portes-a-madrid-le-31-juillet-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/le-hard-rock-cafe-ferme-ses-portes-a-madrid-le-31-juillet-2\/","title":{"rendered":"Le Hard Rock Caf\u00e9 ferme ses portes \u00e0 Madrid le 31 juillet"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"long\">La cha\u00eene de restaurants occupe le num\u00e9ro 2 du Paseo de la Castellana depuis son inauguration en 1994. (EjePrime)<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">L<\/span>e Hard Rock Caf\u00e9 quitte Madrid. La cha\u00eene de restaurants fermera les portes de ses locaux, situ\u00e9s au num\u00e9ro 2 du Paseo de la Castellana, le 31 juillet, \u00e0 l&rsquo;expiration de son bail.<\/p>\n<p>\u00ab\u00a0Madrid reste une ville importante pour notre marque et nous esp\u00e9rons revenir bient\u00f4t sur ce march\u00e9\u00a0\u00bb, a d\u00e9clar\u00e9 le pr\u00e9sident des op\u00e9rations du Hard Rock Caf\u00e9 International, Stephen K. Judge, selon <em>Europa Press<\/em>.<\/p>\n<p>Jusqu&rsquo;au 12 juillet, seul le magasin de la soci\u00e9t\u00e9 restera ouvert, tandis que le restaurant restera ferm\u00e9. La marque poss\u00e8de des restaurants situ\u00e9s dans d&rsquo;autres villes d&rsquo;Espagne comme Barcelone, Ibiza et Marbella, entre autres.<\/p>\n<hr \/>\n<p>Source et suite\u00a0: <a href=\"https:\/\/www.ejeprime.com\/comercial\/hard-rock-cafe-cierra-sus-puertas-en-madrid-el-31-de-julio.html\">EjePrime<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cha\u00eene de restaurants occupe le num\u00e9ro 2 du Paseo de la Castellana depuis son inauguration en 1994. (EjePrime) Le Hard Rock Caf\u00e9 quitte Madrid. La cha\u00eene de restaurants fermera les portes de ses locaux, situ\u00e9s au num\u00e9ro 2 du Paseo de la Castellana, le 31 juillet, \u00e0 l&rsquo;expiration de son bail. \u00ab\u00a0Madrid reste une [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":32682,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1063,375,1064],"class_list":["post-71591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-hard-rock-cafe","tag-madrid","tag-restauration"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=71591"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/32682"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=71591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=71591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=71591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}