{"id":71589,"date":"2026-03-10T00:12:56","date_gmt":"2026-03-10T00:12:56","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/le-marche-de-madrid-se-reactive-apres-le-covid-19-la-residence-wunderhouse-est-mise-en-vente-2\/"},"modified":"2026-07-12T03:40:43","modified_gmt":"2026-07-12T03:40:43","slug":"le-marche-de-madrid-se-reactive-apres-le-covid-19-la-residence-wunderhouse-est-mise-en-vente-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/le-marche-de-madrid-se-reactive-apres-le-covid-19-la-residence-wunderhouse-est-mise-en-vente-2\/","title":{"rendered":"Le march\u00e9 de Madrid se r\u00e9active apr\u00e8s le Covid-19 : la r\u00e9sidence Wunderhouse est mise en vente"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"long\">Le fonds britannique Heady Creek a remis sur le march\u00e9 l&rsquo;ancienne r\u00e9sidence du marquis de Villa Magna, situ\u00e9e dans le quartier de Chueca. (EjePrime)<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">L<\/span>e march\u00e9 de Madrid est relanc\u00e9. La r\u00e9sidence \u00e9tudiante Wunderhouse, propri\u00e9t\u00e9 du fonds britannique Heady Creek, a \u00e9t\u00e9 remise en vente apr\u00e8s avoir \u00e9t\u00e9 suspendue par le coronavirus.<\/p>\n<p>La soci\u00e9t\u00e9 avait fix\u00e9 au 25 mars la date de pr\u00e9sentation des premi\u00e8res offres pour l&rsquo;actif, mais apr\u00e8s la suspension des visites en raison de la crise sanitaire, la commercialisation de la r\u00e9sidence a \u00e9t\u00e9 report\u00e9e jusqu&rsquo;au retour \u00e0 la normale.<\/p>\n<p>Selon <em>El Confidencial<\/em>, l&rsquo;actif est situ\u00e9 au 20, rue San Lorenzo, dans le quartier Chueca de Madrid et est autoris\u00e9 \u00e0 devenir un b\u00e2timent r\u00e9sidentiel ou commercial, un lieu de <em>coworking <\/em>ou une r\u00e9sidence \u00e9tudiante.<\/p>\n<p>La r\u00e9sidence est commercialis\u00e9e par Knight Frank et a un prix de d\u00e9part de douze millions d&rsquo;euros. Actuellement, le b\u00e2timent compte 67 appartements individuels pour les \u00e9tudiants et des salles communes pour l&rsquo;\u00e9tude, une salle de gym et un jardin int\u00e9rieur, entre autres.<\/p>\n<hr \/>\n<p>Source et suite\u00a0: <a href=\"https:\/\/www.ejeprime.com\/mercado\/el-mercado-madrileno-se-despierta-tras-el-covid-19-la-residencia-wunderhouse-sale-a-la-venta.html\">EjePrime<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fonds britannique Heady Creek a remis sur le march\u00e9 l&rsquo;ancienne r\u00e9sidence du marquis de Villa Magna, situ\u00e9e dans le quartier de Chueca. (EjePrime) Le march\u00e9 de Madrid est relanc\u00e9. La r\u00e9sidence \u00e9tudiante Wunderhouse, propri\u00e9t\u00e9 du fonds britannique Heady Creek, a \u00e9t\u00e9 remise en vente apr\u00e8s avoir \u00e9t\u00e9 suspendue par le coronavirus. La soci\u00e9t\u00e9 avait [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":32678,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1062,390,375,801],"class_list":["post-71589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-chueca","tag-immobilier-madrid","tag-madrid","tag-residence-etudiante"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=71589"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71589\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/32678"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=71589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=71589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=71589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}