{"id":71587,"date":"2026-03-10T00:12:38","date_gmt":"2026-03-10T00:12:38","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/inditex-prevoit-1-200-fermetures-jusquen-2021-avec-300-magasins-de-moins-en-espagne-2\/"},"modified":"2026-07-12T03:40:31","modified_gmt":"2026-07-12T03:40:31","slug":"inditex-prevoit-1-200-fermetures-jusquen-2021-avec-300-magasins-de-moins-en-espagne-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/10\/inditex-prevoit-1-200-fermetures-jusquen-2021-avec-300-magasins-de-moins-en-espagne-2\/","title":{"rendered":"Inditex pr\u00e9voit 1.200 fermetures jusqu&rsquo;en 2021, avec 300 magasins de moins en Espagne"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"long\">La soci\u00e9t\u00e9 m\u00e8re de Zara intensifie l&rsquo;ajustement de son r\u00e9seau de distribution, qui se concentrera sur les magasins plus anciens des cha\u00eenes autres que Zara, et mise sur des magasins plus grands. (Modaes)<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">D<\/span>es magasins plus rentables qui forment un r\u00e9seau int\u00e9gr\u00e9 \u00ab\u00a0plus agile et plus durable\u00a0\u00bb. C&rsquo;est l&rsquo;un des principaux axes du nouveau plan strat\u00e9gique qu&rsquo;Inditex s&rsquo;est fix\u00e9 et que la soci\u00e9t\u00e9 a rendu public aujourd&rsquo;hui \u00e0 l&rsquo;occasion de la pr\u00e9sentation des r\u00e9sultats du premier trimestre exceptionnel de l&rsquo;exercice 2020. Pour y parvenir, le groupe pr\u00e9voit jusqu&rsquo;\u00e0 1.200 fermetures de magasins dans le monde, dont une sur quatre (jusqu&rsquo;\u00e0 300 magasins) en Espagne, jusqu&rsquo;en 2021.<\/p>\n<p>Inditex recherche un r\u00e9seau de magasins ayant une surface moyenne plus importante et, surtout, des \u00ab\u00a0niveaux de rentabilit\u00e9 plus \u00e9lev\u00e9s\u00a0\u00bb. Le nouveau plan strat\u00e9gique con\u00e7u par le groupe pr\u00e9voit que l&rsquo;entreprise atteindra un r\u00e9seau de 6.700 \u00e0 6.900 magasins dans le monde, apr\u00e8s avoir ouvert 450 magasins et absorb\u00e9 entre 1.000 et 1.200 magasins plus petits cette ann\u00e9e et l&rsquo;ann\u00e9e prochaine. Malgr\u00e9 la baisse du nombre absolu d&rsquo;unit\u00e9s, la croissance annuelle brute de l&rsquo;espace devrait \u00eatre de 2,5 %.<\/p>\n<p>Les magasins \u00e0 fermer, selon Inditex, repr\u00e9sentent entre 5 et 6 % des ventes totales et ont donc \u00ab\u00a0une capacit\u00e9 moindre \u00e0 fournir les nouveaux services au client\u00a0\u00bb, et leur fermeture n&rsquo;est pas due au fait qu&rsquo;ils g\u00e9n\u00e8rent des pertes. \u00ab\u00a0Ces unit\u00e9s correspondent principalement aux plus anciens magasins des cha\u00eenes autres que Zara\u00a0\u00bb, pr\u00e9cise le groupe.<\/p>\n<p>Le plan de reprise des magasins pour la p\u00e9riode 2020-2021 comprend entre 500 et 600 unit\u00e9s par an et aura une valeur comptable nette de 308 millions d&rsquo;euros, qui a \u00e9t\u00e9 provisionn\u00e9e dans les r\u00e9sultats du premier trimestre 2020. \u00ab\u00a0Le plan d&rsquo;optimisation se concentre sur les magasins en fin de vie, en particulier les formats jeunes et dont les ventes peuvent \u00eatre r\u00e9cup\u00e9r\u00e9es dans les magasins de proximit\u00e9 et en ligne\u00a0\u00bb, insiste le groupe.<\/p>\n<hr \/>\n<p>Source et suite\u00a0: <a href=\"https:\/\/www.modaes.es\/empresa\/inditex-planea-1200-cierres-hasta-2021-con-300-tiendas-menos-en-espana.html\">Modaes<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 m\u00e8re de Zara intensifie l&rsquo;ajustement de son r\u00e9seau de distribution, qui se concentrera sur les magasins plus anciens des cha\u00eenes autres que Zara, et mise sur des magasins plus grands. (Modaes) Des magasins plus rentables qui forment un r\u00e9seau int\u00e9gr\u00e9 \u00ab\u00a0plus agile et plus durable\u00a0\u00bb. C&rsquo;est l&rsquo;un des principaux axes du nouveau plan [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":32674,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,234],"tags":[1057,458,1058],"class_list":["post-71587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-logistique-retail","tag-inditex","tag-retail","tag-zara"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=71587"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/71587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/32674"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=71587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=71587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=71587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}