{"id":70426,"date":"2026-03-09T10:13:28","date_gmt":"2026-03-09T10:13:28","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/poulpe-a-la-galicienne-avec-risotto-et-asperges-vertes-2\/"},"modified":"2026-09-01T06:09:05","modified_gmt":"2026-09-01T06:09:05","slug":"poulpe-a-la-galicienne-avec-risotto-et-asperges-vertes-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/poulpe-a-la-galicienne-avec-risotto-et-asperges-vertes-2\/","title":{"rendered":"Poulpe \u00e0 la galicienne avec risotto et asperges vertes"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/lacocinadefrabisa.lavozdegalicia.es\/author\/frabisa\/\">Frabisa<\/a>, La Voz de Galicia<\/p>\n<p class=\"wp-block-paragraph\">Le poulpe \u00e0 la galicienne avec risotto et asperges vertes est un plat d\u00e9licieux dans lequel le produit est fondamental pour obtenir un r\u00e9sultat fantastique.<\/p>\n<p class=\"wp-block-paragraph\">Un plat \u00e0 d\u00e9guster entre amis ou en famille en sachant d&rsquo;avance que ce sera un succ\u00e8s. Si vous vous organisez bien, vous pourrez profiter de vos invit\u00e9s presque tout le temps, vous pouvez avoir tout \u00e0 moiti\u00e9 pr\u00e9par\u00e9 et la seule chose que vous aurez \u00e0 faire quelques instants avant sera le riz.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/pulpo-con-aceite-de-pimenton-1.jpg\"><\/figure>\n<\/div>\n<h3 class=\"wp-block-heading\"><strong>Recette : <\/strong><\/h3>\n<p class=\"wp-block-paragraph\">6 personnes<\/p>\n<p class=\"wp-block-paragraph\">Cuisine : Galicienne <\/p>\n<p class=\"wp-block-paragraph\">\n<p class=\"wp-block-paragraph\"><strong>Ingr\u00e9dients<\/strong><\/p>\n<ul class=\"wp-block-list\">\n<li>1 poulpe congel\u00e9 (le meilleur est de Galice) d&rsquo;environ 1,5kg<\/li>\n<li><strong><a href=\"https:\/\/lacocinadefrabisa.lavozdegalicia.es\/aceite-de-pimenton\/\">Aceite de piment\u00f3n<\/a><\/strong> (huile de paprika) (250 ml d&rsquo;huile d&rsquo;olive extra vierge + 20 g de paprika doux)<\/li>\n<li>Gros sel<\/li>\n<li>Risotto<\/li>\n<li>1 botte d&rsquo;asperges vertes<\/li>\n<li>400g de riz (arborio)<\/li>\n<li>1 oignon moyen<\/li>\n<li>1 gousse d&rsquo;ail<\/li>\n<li>1 cuill\u00e8re \u00e0 soupe d&rsquo;huile d&rsquo;olive extra vierge<\/li>\n<li>Sel et poivre noir<\/li>\n<li>2 bo\u00eetes de conserves de coques\n<p><strong>Instructions<\/strong><\/li>\n<\/ul>\n<ol class=\"wp-block-list\">\n<li>Sortez le poulpe du cong\u00e9lateur la veille et laissez le dans un bol au r\u00e9frig\u00e9rateur pour qu&rsquo;il d\u00e9cong\u00e8le lentement.<\/li>\n<li>Faites chauffer l&rsquo;eau dans une casserole haute (sans sel, le poulpe sera sal\u00e9 une fois cuit). Lorsque l&rsquo;eau est chaude mais pas bouillante, rafra\u00eechissez le poulpe en le mettant et en le sortant (en le tenant par la t\u00eate) trois fois dans l&rsquo;eau jusqu&rsquo;\u00e0 ce que vous le laissiez finalement dans l&rsquo;eau pour commencer la cuisson.<\/li>\n<li>Une fois que \u00e7a commence \u00e0 bouillir, on compte 30-35 minutes.<\/li>\n<li>Apr\u00e8s ce temps, piquez la partie \u00e9paisse des tentacules avec une fourchette, exactement l\u00e0 o\u00f9 elle touche presque la t\u00eate, et v\u00e9rifiez si elle est dure ou si elle est pr\u00eate. En fonction de l&rsquo;un ou l&rsquo;autre, laissez reposer quelques minutes de plus.<\/li>\n<li>Lorsqu&rsquo;il est cuit, mettez le dans un plat de service. Mettez de c\u00f4t\u00e9.<\/li>\n<li><strong>Aceite de piment\u00f3n<\/strong> <\/li>\n<li>Mettre l&rsquo;huile et le paprika dans une casserole ou une po\u00eale, porter \u00e0 une temp\u00e9rature de 60\u00ba, \u00e9teindre le feu, laisser refroidir et filtrer sur un tissu en coton pour \u00e9liminer les particules de paprika et obtenir une huile cristalline. Mettez de c\u00f4t\u00e9.<\/li>\n<li><strong>Risotto<\/strong><\/li>\n<li>Faites chauffer le bouillon dans une casserole et gardez le au chaud \u00e0 feu doux jusqu&rsquo;\u00e0 ce que vous en ayez besoin.<\/li>\n<li>Laver les asperges, couper les extr\u00e9mit\u00e9s qui sont toujours plus dures, couper les jaunes et les mettre de c\u00f4t\u00e9, le reste des parties tendres les couper en morceaux d&rsquo;environ 1 cm. Mettez de c\u00f4t\u00e9.<\/li>\n<li>Faites fondre le beurre dans une casserole, ajoutez la cuill\u00e8re \u00e0 soupe d&rsquo;huile et faites revenir l&rsquo;oignon et la gousse d&rsquo;ail finement hach\u00e9e.<\/li>\n<li>Ajoutez le riz et les asperges et faites les sauter, saupoudrez de sel et de poivre noir.<\/li>\n<li>Ajoutez une tasse de bouillon et remuez.<\/li>\n<li>Ajoutez le reste du bouillon par tasses, en attendant que le contenu de la pr\u00e9c\u00e9dente soit absorb\u00e9 par le riz et en remuant \u00e0 chaque fois.<\/li>\n<li>Apr\u00e8s 10 minutes de cuisson, ajouter les pointes d&rsquo;asperges, assaisonner et poursuivre la cuisson en ajoutant du bouillon pendant 8 minutes suppl\u00e9mentaires. Il n&rsquo;est pas n\u00e9cessaire d&rsquo;ajouter tout le bouillon si le riz n&rsquo;en a pas besoin.<\/li>\n<li>Retirez le riz du feu lorsque les grains sont al dente. Retirer quelques pointes d&rsquo;asperges de la surface et les mettre de c\u00f4t\u00e9 pour le service.<\/li>\n<li>Ajoutez le parmesan, les coques \u00e9goutt\u00e9es et remuez. Laissez reposer pendant 5 minutes.<\/li>\n<li>Faites chauffer un peu le poulpe dans l&rsquo;eau de cuisson.<\/li>\n<li><strong>Placage<\/strong><\/li>\n<li>Disposez le risotto et les asperges d&rsquo;un c\u00f4t\u00e9 de l&rsquo;assiette et au milieu, une partie de la cuisse enti\u00e8re et l&rsquo;autre partie coup\u00e9e en morceaux ou toute coup\u00e9e, selon votre go\u00fbt. Arrosez d&rsquo;huile au paprika et saupoudrez de gros sel.<\/li>\n<\/ol>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/pulpo-con-berberechos-1.jpg\"><\/figure>\n<\/div>\n<h4 class=\"wp-block-heading\"><strong>Frabiconsejos<\/strong><\/h4>\n<p class=\"wp-block-paragraph\">Vous pouvez attacher 2 ou 3 pointes d&rsquo;asperges et d\u00e9corer l&rsquo;assiette avec un brin de ciboulette.<\/p>\n<p class=\"wp-block-paragraph\">Source <a href=\"https:\/\/lacocinadefrabisa.lavozdegalicia.es\/pulpo-a-la-gallega-con-risotto-y-esparragos-verdes\/\">La Voz de Galicia<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frabisa, La Voz de Galicia Le poulpe \u00e0 la galicienne avec risotto et asperges vertes est un plat d\u00e9licieux dans lequel le produit est fondamental pour obtenir un r\u00e9sultat fantastique. Un plat \u00e0 d\u00e9guster entre amis ou en famille en sachant d&rsquo;avance que ce sera un succ\u00e8s. Si vous vous organisez bien, vous pourrez profiter [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":28300,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4440],"tags":[],"class_list":["post-70426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-networking"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=70426"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70426\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/28300"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=70426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=70426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=70426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}