{"id":70201,"date":"2026-03-09T08:05:56","date_gmt":"2026-03-09T08:05:56","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/nouvelle-reduction-du-prix-demande-pour-un-village-des-asturies-avec-vue-sur-les-picos-de-europa-2\/"},"modified":"2026-08-31T23:14:36","modified_gmt":"2026-08-31T23:14:36","slug":"nouvelle-reduction-du-prix-demande-pour-un-village-des-asturies-avec-vue-sur-les-picos-de-europa-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/nouvelle-reduction-du-prix-demande-pour-un-village-des-asturies-avec-vue-sur-les-picos-de-europa-2\/","title":{"rendered":"Nouvelle r\u00e9duction du prix demand\u00e9 pour un village des Asturies avec vue sur les Picos de Europa"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><strong><em>Le Mortorio a \u00e9t\u00e9 mis sur le march\u00e9 pour 2,37 millions, bien qu&rsquo;en 2020 le prix ait baiss\u00e9 de 21 % et maintenant de 9 % suppl\u00e9mentaires \u00e0 1,7 million.<\/em><\/strong><\/p>\n<p class=\"wp-block-paragraph\">Idealista\/News, 12 mai 2022<\/p>\n<p class=\"wp-block-paragraph\">Un petit village au c\u0153ur des Asturies n&rsquo;a pas encore trouv\u00e9 de nouveau propri\u00e9taire. C&rsquo;est <strong>El Mortorio<\/strong>, dont le prix demand\u00e9 a encore baiss\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">Le village a \u00e9t\u00e9 mis sur le march\u00e9 pour <strong>2,37 millions d&rsquo;euros, <\/strong>mais en pleine pand\u00e9mie, son prix a chut\u00e9 de 21 % pour atteindre 1,87 million d&rsquo;euros. Et maintenant, deux ans plus tard, elle est disponible sur idealista avec une r\u00e9duction suppl\u00e9mentaire de 9 %, ce qui laisse le prix final \u00e0 1,7 million d&rsquo;euros.<\/p>\n<p class=\"wp-block-paragraph\">Entour\u00e9 par la nature et avec des vues sur les Picos de Europa, El Mortorio couvre une superficie de 130.000 m2 et dispose de 1.115 m2 de surface construite, dont 950 m2 sont utilisables. Le prix comprend 12 b\u00e2timents individuels, dont huit maisons rurales r\u00e9nov\u00e9es de 48 lits, et un horreo, ainsi que plus de vingt terrains \u00e0 b\u00e2tir, un entrep\u00f4t de 400 m2 pour le stockage et l&rsquo;entretien des machines, et des b\u00e2timents \u00e0 r\u00e9nover.<\/p>\n<p class=\"wp-block-paragraph\">Selon Iberia North, qui est charg\u00e9 de la commercialisation de la propri\u00e9t\u00e9, les cottages individuels ont entre deux et quatre chambres, et comprennent un salon, une cuisine et une salle \u00e0 manger. Ils ont \u00e9t\u00e9 r\u00e9nov\u00e9s entre 1995 et 2004, disposent d&rsquo;un acc\u00e8s priv\u00e9, d&rsquo;un chauffage individuel et plus de la moiti\u00e9 ont une chemin\u00e9e. Il y a un grand nombre de places de stationnement dans le village, pr\u00e8s des b\u00e2timents individuels.<\/p>\n<p class=\"wp-block-paragraph\">Cet h\u00f4tel-village se trouve \u00e0 une demi-heure de route des Picos de Europa et de Cangas de On\u00eds, et \u00e0 moins d&rsquo;une heure des villes historiques d&rsquo;Oviedo, Avil\u00e9s et Gij\u00f3n. La grande ville la plus proche est Infiesto, qui dispose de supermarch\u00e9s, de bars et de restaurants et se trouve \u00e0 environ 10 km, tandis que la c\u00f4te et les plages telles que La Griega sont \u00e0 environ 20 km.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias1.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias4.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias5.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias3.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias6.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias7.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias8.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias9.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias12.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/asturias13.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/pueblo.jpg\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/pueblo2.jpg\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/pueblo3.png\"><\/figure>\n<\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/ubicacion.jpg\"><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Source <a href=\"https:\/\/www.idealista.com\/news\/inmobiliario\/vivienda\/2022\/05\/12\/796552-nueva-rebaja-del-precio-de-venta-de-un-pueblo-en-asturias-con-vistas-a-los-picos-de\" target=\"_blank\" rel=\"noreferrer noopener\">Idealista\/News<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Mortorio a \u00e9t\u00e9 mis sur le march\u00e9 pour 2,37 millions, bien qu&rsquo;en 2020 le prix ait baiss\u00e9 de 21 % et maintenant de 9 % suppl\u00e9mentaires \u00e0 1,7 million. Idealista\/News, 12 mai 2022 Un petit village au c\u0153ur des Asturies n&rsquo;a pas encore trouv\u00e9 de nouveau propri\u00e9taire. C&rsquo;est El Mortorio, dont le prix demand\u00e9 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":70216,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,4504],"tags":[],"class_list":["post-70201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-resilience-agri"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=70201"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/70216"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=70201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=70201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=70201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}