{"id":70114,"date":"2026-03-09T07:08:22","date_gmt":"2026-03-09T07:08:22","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/aedas-affecte-303-millions-deuros-a-lachat-de-terrains-pour-developper-4-101-logements-2\/"},"modified":"2026-08-31T20:21:55","modified_gmt":"2026-08-31T20:21:55","slug":"aedas-affecte-303-millions-deuros-a-lachat-de-terrains-pour-developper-4-101-logements-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/aedas-affecte-303-millions-deuros-a-lachat-de-terrains-pour-developper-4-101-logements-2\/","title":{"rendered":"Aedas affecte 303 millions d&rsquo;euros \u00e0 l&rsquo;achat de terrains pour d\u00e9velopper 4.101 logements"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>Le promoteur du fonds am\u00e9ricain Castlelake dispose d&rsquo;une r\u00e9serve fonci\u00e8re pour le d\u00e9veloppement de 17.000 logements sur le march\u00e9 espagnol, ce qui garantit les livraisons pour les quatre prochaines ann\u00e9es.<\/em><\/p>\n<p class=\"wp-block-paragraph\">EjePrime, 1er juin 2022<\/p>\n<p class=\"wp-block-paragraph\">Aedas Home a \u00e9tabli un record d&rsquo;investissement dans les terrains au cours de son exercice 2021-22, qui s&rsquo;est termin\u00e9 le 31 mars. Le promoteur a acquis des parcelles d&rsquo;une valeur de <strong>303 millions d&rsquo;euros pour d\u00e9velopper 4.101 logements<\/strong> dans diff\u00e9rentes parties du march\u00e9 espagnol, a indiqu\u00e9 la soci\u00e9t\u00e9 dans un communiqu\u00e9. <\/p>\n<p class=\"wp-block-paragraph\">Les chiffres obtenus au cours de l&rsquo;exercice r\u00e9cemment achev\u00e9 d\u00e9passent de 24 % l&rsquo;objectif d&rsquo;investissement (en nombre d&rsquo;unit\u00e9s) pr\u00e9vu dans son plan d&rsquo;affaires 2021-25. 98 % des investissements r\u00e9alis\u00e9s concernent des terrains finalistes, c&rsquo;est-\u00e0-dire des terrains susceptibles d&rsquo;\u00eatre am\u00e9nag\u00e9s imm\u00e9diatement, les deux tiers \u00e9tant concentr\u00e9s sur les cinq principaux march\u00e9s r\u00e9sidentiels d&rsquo;Espagne : Madrid, Barcelone, Malaga, Alicante et Valence. <\/p>\n<p class=\"wp-block-paragraph\">Les nouveaux terrains d&rsquo;Aedas sont situ\u00e9s dans les enclaves r\u00e9sidentielles les plus dynamiques du pays et, en particulier, dans la r\u00e9gion de Madrid, o\u00f9 Aedas a repr\u00e9sent\u00e9 36 % du total des investissements r\u00e9alis\u00e9s par la soci\u00e9t\u00e9 au cours de son dernier exercice. <\/p>\n<h4 class=\"has-text-align-center wp-block-heading\"><strong>Aedas a r\u00e9alis\u00e9 98 % de ses achats de terrains au cours de son dernier exercice fiscal \u00e0 Madrid, Barcelone, Malaga, Alicante et Valence <\/strong><\/h4>\n<p class=\"wp-block-paragraph\">De cette mani\u00e8re, le promoteur a investi au cours de l&rsquo;exercice 2021\/22 plus de 109 millions d&rsquo;euros dans de nouveaux terrains dans la r\u00e9gion de Madrid, ce qui lui permettra de d\u00e9velopper plus de 1.000 nouveaux logements. <\/p>\n<p class=\"wp-block-paragraph\">Apr\u00e8s la r\u00e9gion de Madrid, l&rsquo;investissement r\u00e9alis\u00e9 par l&rsquo;entreprise au cours de la p\u00e9riode 2021\/22 dans les op\u00e9rations situ\u00e9es dans les directions territoriales de Levante-Bal\u00e9ares et de Catalogne-Aragon se distingue \u00e9galement, avec respectivement 20 % et 18 % de l&rsquo;investissement total. <\/p>\n<p class=\"wp-block-paragraph\">Les nouveaux investissements r\u00e9alis\u00e9s par Aedas permettent au promoteur de disposer d&rsquo;une r\u00e9serve fonci\u00e8re totale pour d\u00e9velopper 17.000 logements, ce qui repr\u00e9sente une augmentation de 10 % du portefeuille par rapport \u00e0 mars 2021 (15.484) et couvre ses objectifs de livraison de logements pour les quatre prochaines ann\u00e9es. <\/p>\n<p class=\"wp-block-paragraph\">Aedas a cl\u00f4tur\u00e9 son dernier exercice (avril \u00e0 mars) avec un r\u00e9sultat net de 93 millions d&rsquo;euros, soit 9 % de plus que l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. Les revenus de la soci\u00e9t\u00e9 ont atteint 766 millions d&rsquo;euros, soit une augmentation de 14 %, comme l&rsquo;a d\u00e9clar\u00e9 le groupe \u00e0 la Commission espagnole des valeurs mobili\u00e8res et des changes (CNMV).<\/p>\n<p class=\"wp-block-paragraph\">Source <a href=\"https:\/\/www.ejeprime.com\/residencial\/aedas-destina-303-millones-de-euros-a-suelo-para-desarrollar-4101-viviendas.html\" target=\"_blank\" rel=\"noreferrer noopener\">EjePrime<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le promoteur du fonds am\u00e9ricain Castlelake dispose d&rsquo;une r\u00e9serve fonci\u00e8re pour le d\u00e9veloppement de 17.000 logements sur le march\u00e9 espagnol, ce qui garantit les livraisons pour les quatre prochaines ann\u00e9es. EjePrime, 1er juin 2022 Aedas Home a \u00e9tabli un record d&rsquo;investissement dans les terrains au cours de son exercice 2021-22, qui s&rsquo;est termin\u00e9 le 31 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":27376,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-70114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=70114"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70114\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/27376"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=70114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=70114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=70114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}