{"id":70099,"date":"2026-03-09T07:00:33","date_gmt":"2026-03-09T07:00:33","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/le-secteur-senior-retrouve-le-chemin-de-la-croissance-et-deplace-46-milliards-en-2021-2\/"},"modified":"2026-08-31T19:50:40","modified_gmt":"2026-08-31T19:50:40","slug":"le-secteur-senior-retrouve-le-chemin-de-la-croissance-et-deplace-46-milliards-en-2021-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/le-secteur-senior-retrouve-le-chemin-de-la-croissance-et-deplace-46-milliards-en-2021-2\/","title":{"rendered":"Le secteur &lsquo;senior&rsquo; retrouve le chemin de la croissance et d\u00e9place 4,6 milliards en 2021"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;offre de places en r\u00e9sidences priv\u00e9es d\u00e9passe d\u00e9sormais les 290 000, dont 62 % de places priv\u00e9es pures et 38 % am\u00e9nag\u00e9es avec l&rsquo;Administration, une part qui montre une tendance \u00e0 la hausse.<\/p>\n<p class=\"wp-block-paragraph\">Volume r\u00e9sidentiel senior Le secteur senior se redresse. Le chiffre d&rsquo;affaires agr\u00e9g\u00e9 des soci\u00e9t\u00e9s de gestion de r\u00e9sidences pour personnes \u00e2g\u00e9es a enregistr\u00e9 une l\u00e9g\u00e8re croissance en 2021, apr\u00e8s la baisse de 3 % enregistr\u00e9e l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente en raison de l&rsquo;impact du Covid-19. Ainsi, les recettes ont atteint 4,6 milliards d&rsquo;euros l&rsquo;an dernier, soit 1,1 % de plus qu&rsquo;en 2020, favoris\u00e9es par la hausse de l&rsquo;offre et l&rsquo;occupation des lieux, selon l&rsquo;Observatoire sectoriel DBK de l&rsquo;Informa. <\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;activit\u00e9 de gestion de lieux privatifs purs a g\u00e9n\u00e9r\u00e9 2,66 milliards d&rsquo;euros, un chiffre qui repr\u00e9sentait 57,8 % du total. De son c\u00f4t\u00e9, l&rsquo;activit\u00e9 de gestion conventionn\u00e9e des places de stationnement a r\u00e9alis\u00e9 un chiffre d&rsquo;affaires de 1,4 milliards d&rsquo;euros (32 %), tandis que la gestion priv\u00e9e des places de stationnement public a recueilli les 10 % restants. Fin 2021, plus de 5 500 r\u00e9sidences pour personnes \u00e2g\u00e9es -publiques et priv\u00e9es- \u00e9taient op\u00e9rationnelles, qui disposaient d&rsquo;une offre totale de plus de 388 000 lits, cette derni\u00e8re ampleur augmentant de 1% par rapport \u00e0 2020. 75% des places sont situ\u00e9es en r\u00e9sidences priv\u00e9es, tandis que les 25 % restants correspondent \u00e0 des logements en r\u00e9sidences publiques pures priv\u00e9es (181 122 places). <\/p>\n<p class=\"wp-block-paragraph\">De leur c\u00f4t\u00e9, les places am\u00e9nag\u00e9es avec l&rsquo;Administration se sont \u00e9lev\u00e9es \u00e0 109 917, maintenant la tendance \u00e0 la hausse de leur part dans le nombre total de places priv\u00e9es, atteignant 37,8 %. Un grand nombre de petites entreprises d\u00e9di\u00e9es \u00e0 la gestion d&rsquo;un centre et appartenant \u00e0 l&rsquo;\u00c9tat op\u00e8rent dans le secteur. <\/p>\n<p class=\"wp-block-paragraph\">Cependant, dans les premi\u00e8res positions du march\u00e9 se distingue un groupe d&rsquo;op\u00e9rateurs de taille moyenne et grande qui g\u00e8rent un grand nombre de r\u00e9sidences, dont certaines d&rsquo;origine \u00e9trang\u00e8re. En 2021, les cinq principaux concurrents d\u00e9tenaient une part de march\u00e9 combin\u00e9e de 23,7 %, qui s&rsquo;\u00e9levait \u00e0 33,6 % si l&rsquo;on consid\u00e8re les dix premiers, selon les informations publi\u00e9es dans le rapport.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;offre de places en r\u00e9sidences priv\u00e9es d\u00e9passe d\u00e9sormais les 290 000, dont 62 % de places priv\u00e9es pures et 38 % am\u00e9nag\u00e9es avec l&rsquo;Administration, une part qui montre une tendance \u00e0 la hausse. Volume r\u00e9sidentiel senior Le secteur senior se redresse. Le chiffre d&rsquo;affaires agr\u00e9g\u00e9 des soci\u00e9t\u00e9s de gestion de r\u00e9sidences pour personnes \u00e2g\u00e9es a [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":27339,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-70099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=70099"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/27339"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=70099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=70099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=70099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}