{"id":70097,"date":"2026-03-09T07:00:18","date_gmt":"2026-03-09T07:00:18","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/palma-lance-sa-premiere-liaison-aerienne-reguliere-avec-new-york-2\/"},"modified":"2026-08-31T19:34:56","modified_gmt":"2026-08-31T19:34:56","slug":"palma-lance-sa-premiere-liaison-aerienne-reguliere-avec-new-york-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/palma-lance-sa-premiere-liaison-aerienne-reguliere-avec-new-york-2\/","title":{"rendered":"Palma lance sa premi\u00e8re liaison a\u00e9rienne r\u00e9guli\u00e8re avec New York"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>Le vol inaugural de la premi\u00e8re ligne r\u00e9guli\u00e8re de United Airlines entre Majorque et New York a atterri \u00e0 11h40 \u00e0 l&rsquo;a\u00e9roport de Palma de Majorque avec 204 passagers en provenance de l&rsquo;a\u00e9roport de Newark \u00e0 New York.<\/em><\/p>\n<p class=\"wp-block-paragraph\">Hosteltur, 3 juin 2022<\/p>\n<p class=\"wp-block-paragraph\">\u00ab\u00a0C&rsquo;est un jour passionnant, historique et important\u00a0\u00bb, a d\u00e9clar\u00e9 la pr\u00e9sidente du Conseil de Mallorca, Catalina Cladera, apr\u00e8s la r\u00e9ception des passagers, de l&rsquo;\u00e9quipage et de Patrick Quayle, vice-pr\u00e9sident de la compagnie a\u00e9rienne qui a opt\u00e9 pour cette route.<\/p>\n<p class=\"wp-block-paragraph\">Jusqu&rsquo;au 23 septembre, United Airlines assurera trois vols par semaine dans chaque sens avec un appareil Boeing 767-300 pouvant accueillir 214 personnes. M. Cladera a soulign\u00e9 que la nouvelle liaison pourrait amener quelque 10.000 touristes sur les \u00eeles cette ann\u00e9e et il est convaincu que l&rsquo;offre sera \u00e9largie en 2023.<\/p>\n<p class=\"wp-block-paragraph\">M. Quayle a d\u00e9clar\u00e9 qu&rsquo;il \u00e9tait \u00ab\u00a0ravi\u00a0\u00bb que United soit la premi\u00e8re compagnie a\u00e9rienne am\u00e9ricaine \u00e0 desservir r\u00e9guli\u00e8rement les Bal\u00e9ares.<\/p>\n<p class=\"wp-block-paragraph\">Du milieu des ann\u00e9es 1970 jusqu&rsquo;au milieu de la d\u00e9cennie suivante, la compagnie Spantax a assur\u00e9 des vols charters fr\u00e9quents entre Majorque et les \u00c9tats-Unis, mais depuis lors, les liaisons directes ont \u00e9t\u00e9 rares et jamais r\u00e9guli\u00e8res.<\/p>\n<p class=\"wp-block-paragraph\">Le dirigeant de United Airlines a d\u00e9clar\u00e9 que l&rsquo;extension de la p\u00e9riode d&rsquo;exploitation et du nombre de vols pour la saison 2023 d\u00e9pendrait de la demande cette ann\u00e9e, mais il s&rsquo;est montr\u00e9 optimiste quant \u00e0 l&rsquo;int\u00e9r\u00eat que la ligne a suscit\u00e9 \u00e0 New York et dans d&rsquo;autres villes tr\u00e8s peupl\u00e9es de l&rsquo;est des \u00c9tats-Unis, comme Chicago et Washington.<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/image-8-1024x683.png\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/image-9-1-1024x683.png\"><\/figure>\n<p class=\"wp-block-paragraph\">Source <a href=\"https:\/\/www.hosteltur.com\/151832_ihg-pone-su-foco-de-expansion-en-el-este-del-mediterraneo.html\" target=\"_blank\" rel=\"noreferrer noopener\">Hosteltur<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vol inaugural de la premi\u00e8re ligne r\u00e9guli\u00e8re de United Airlines entre Majorque et New York a atterri \u00e0 11h40 \u00e0 l&rsquo;a\u00e9roport de Palma de Majorque avec 204 passagers en provenance de l&rsquo;a\u00e9roport de Newark \u00e0 New York. Hosteltur, 3 juin 2022 \u00ab\u00a0C&rsquo;est un jour passionnant, historique et important\u00a0\u00bb, a d\u00e9clar\u00e9 la pr\u00e9sidente du Conseil [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":27336,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,234],"tags":[],"class_list":["post-70097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-logistique-retail"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=70097"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/27336"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=70097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=70097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=70097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}