{"id":70093,"date":"2026-03-09T06:53:21","date_gmt":"2026-03-09T06:53:21","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/creer-sa-micro-entreprise-en-france-et-resider-a-letranger-2\/"},"modified":"2026-08-31T19:34:49","modified_gmt":"2026-08-31T19:34:49","slug":"creer-sa-micro-entreprise-en-france-et-resider-a-letranger-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/creer-sa-micro-entreprise-en-france-et-resider-a-letranger-2\/","title":{"rendered":"Cr\u00e9er sa Micro-Entreprise en France et R\u00e9sider \u00e0 l\u2019\u00c9tranger"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<h2 class=\"wp-block-heading\"><strong>Expat : comment avoir le statut d\u2019auto-entrepreneur en France ?<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Cr\u00e9er sa propre entreprise en France et habiter \u00e0 l\u2019\u00e9tranger. Cette id\u00e9e peut para\u00eetre \u00e9trange au premier abord, mais en r\u00e9alit\u00e9, il s\u2019agit d\u2019une option qui a fait ses preuves et qui peut r\u00e9ellement vous aider \u00e0 mener une carri\u00e8re \u00e0 l\u2019\u00e9tranger. Une option surtout int\u00e9ressante pour la femme expat qui n\u2019a g\u00e9n\u00e9ralement pas d\u2019autre choix que de laisser son travail de salari\u00e9e en France pour accompagner son conjoint dans la mobilit\u00e9 g\u00e9ographique.<\/p>\n<p class=\"wp-block-paragraph\">Il faut dire que la probl\u00e9matique du travail est toujours la m\u00eame pour le conjoint d\u2019expatri\u00e9. Une fois la famille install\u00e9e dans son nouveau pays, la femme expatri\u00e9e aimerait, en g\u00e9n\u00e9ral, trouver un emploi \u00e0 l\u2019\u00e9tranger. Et ce n\u2019est pas toujours \u00e9vident. On remarque alors que l\u2019esprit d\u2019entrepreneuriat s\u2019est d\u00e9velopp\u00e9 ces derni\u00e8res ann\u00e9es.<\/p>\n<p class=\"wp-block-paragraph\">Mais quelles sont les possibilit\u00e9s offertes aux femmes expatri\u00e9es en mati\u00e8re de cr\u00e9ation d\u2019entreprise ? Peuvent-elles \u00eatre r\u00e9sidentes \u00e0 l\u2019\u00e9tranger et d\u00e9clarer leur activit\u00e9 en France ? Comment cela se passe-t-il, et sous quelles conditions ?<\/p>\n<p class=\"wp-block-paragraph\">Voici donc quelques explications pour <strong>cr\u00e9er sa micro-entreprise en France tout en vivant \u00e0 l\u2019\u00e9tranger.<\/strong><\/p>\n<h2 class=\"wp-block-heading\" id=\"conditions\"><strong>Quelles sont les conditions pour b\u00e9n\u00e9ficier du r\u00e9gime de la micro-entreprise en tant qu\u2019expat ?<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Le&nbsp;<a target=\"_blank\" href=\"https:\/\/www.economie.gouv.fr\/cedef\/resident-etranger-micro-entreprise-france#:~:text=Vous%20pouvez%20habiter%20%C3%A0%20l,de%20commerce%20et%20d&apos;industrie.\" rel=\"noreferrer noopener\">site officiel du Minist\u00e8re de l\u2019Economie, des Finances et de la Relance<\/a>&nbsp;nous le pr\u00e9cise clairement : en tant que r\u00e9sident \u00e0 l\u2019\u00e9tranger, vous pouvez tout \u00e0 fait \u00eatre micro-entrepreneur en France&nbsp;<strong>\u00e0 condition de disposer d\u2019une adresse en France<\/strong>&nbsp;\u00e0 laquelle vous fixez votre \u00e9tablissement principal. Il peut donc s\u2019agir de votre r\u00e9sidence secondaire (si vous en poss\u00e9dez une), d\u2019une bo\u00eete postale ou de l\u2019adresse d\u2019un ami ou d\u2019un membre de votre famille.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Disposer d\u2019une adresse de domiciliation en France<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Vous \u00eates d\u00e9j\u00e0 install\u00e9\u00b7e \u00e0 l\u2019\u00e9tranger alors vous vous dites peut-\u00eatre qu\u2019il n\u2019est pas possible de cr\u00e9er votre micro-entreprise en France car vous n\u2019avez plus d\u2019adresse en France. C\u2019est logique. Mais il existe n\u00e9anmoins une solution. En effet, il existe des&nbsp;<strong>soci\u00e9t\u00e9s de domiciliation&nbsp;<\/strong>qui vous permettent de b\u00e9n\u00e9ficier d\u2019une adresse fran\u00e7aise valable pour la cr\u00e9ation de votre micro-entreprise.<\/p>\n<p class=\"wp-block-paragraph\">La domiciliation est une solution simple \u00e0 mettre en place car vous n\u2019avez pas besoin d\u2019installer physiquement votre activit\u00e9 sur place. Vous pouvez ainsi la g\u00e9rer \u00e0 distance. La domiciliation de votre micro-entreprise n\u2019est donc pas li\u00e9e, de mani\u00e8re obligatoire, \u00e0 votre domicile en France.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Les d\u00e9marches pour obtenir une adresse administrative aupr\u00e8s d\u2019une soci\u00e9t\u00e9 de domiciliation<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Pour utiliser les services d\u2019une soci\u00e9t\u00e9 de domiciliation, il va falloir&nbsp;<strong>signer<\/strong>&nbsp;<strong>un contrat&nbsp;<\/strong>avec elle. Dans ce contrat, vous disposerez notamment de l\u2019adresse exacte de domiciliation de votre activit\u00e9 et de toutes les prestations propos\u00e9es.<\/p>\n<p class=\"wp-block-paragraph\">Vous n\u2019avez pas besoin d\u2019\u00eatre en France pour proc\u00e9der \u00e0 la recherche d\u2019une soci\u00e9t\u00e9 de domiciliation. En effet, tout peut se faire en ligne. Vous aurez juste \u00e0 comparer les tarifs et prestations de chaque domiciliataire et \u00e0 choisir celui qui vous convient le mieux.<\/p>\n<h3 class=\"wp-block-heading\"><strong>V\u00e9rifier les conditions de travail dans le pays de r\u00e9sidence<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Si vous partez vivez&nbsp;<strong>dans un pays de l\u2019espace Schengen<\/strong>, vous pouvez exercer votre activit\u00e9 en toute libert\u00e9 et b\u00e9n\u00e9ficier du r\u00e9gime de la micro-entreprise en France.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Pour ce qui est des autres pays<\/strong>, il arrive parfois que la r\u00e9glementation impose l\u2019obtention d\u2019un visa qui vous donne le droit de travailler sur le territoire \u00e9tranger.<\/p>\n<p class=\"wp-block-paragraph\">Mieux vaut donc vous renseigner pr\u00e9alablement aupr\u00e8s des autorit\u00e9s de votre pays d\u2019accueil pour conna\u00eetre leurs modalit\u00e9s en termes d\u2019emploi. Vous saurez ainsi si vous avez besoin d\u2019un visa sp\u00e9cial pour poursuivre votre activit\u00e9 sous le r\u00e9gime de la micro-entreprise fran\u00e7aise.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Payer ses imp\u00f4ts aupr\u00e8s de l\u2019\u00c9tat fran\u00e7ais<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">\u00c0 partir du moment o\u00f9 vous d\u00e9clarez votre activit\u00e9 d\u2019auto-entrepreneur en France, vous \u00eates&nbsp;<strong>consid\u00e9r\u00e9 comme r\u00e9sident fiscal fran\u00e7ais<\/strong>, m\u00eame si vous n\u2019habitez pas en France plus de 6 mois par an. La d\u00e9claration de vos revenus doit donc s\u2019effectuer aupr\u00e8s de l\u2019administration fiscale fran\u00e7aise.<\/p>\n<p class=\"wp-block-paragraph\">Cela est valable \u00e9galement pour les taxes et charges redevables en France pour tous les auto-entrepreneurs : cotisations sociales, versement lib\u00e9ratoire (si vous avez opt\u00e9 pour cette possibilit\u00e9) et la CFE (Cotisation Fonci\u00e8re des Entreprises).<\/p>\n<h3 class=\"wp-block-heading\"><strong>La situation fiscale aupr\u00e8s de votre pays d\u2019accueil<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Il faut savoir que la l\u00e9gislation en mati\u00e8re fiscale diff\u00e8re d\u2019un pays \u00e0 l\u2019autre. C\u2019est pour cela qu\u2019il est indispensable de se renseigner sur l\u2019existence ou non d\u2019une&nbsp;<strong>convention fiscale avec la Franc<\/strong>e. En cas d\u2019accord entre les deux pays, vous \u00e9viterez une double-imposition.<\/p>\n<p class=\"wp-block-paragraph\">N\u2019h\u00e9sitez pas \u00e0 consulter les fiches conseils aux voyageurs du&nbsp;<a href=\"https:\/\/www.diplomatie.gouv.fr\/fr\/conseils-aux-voyageurs\/\" target=\"_blank\" rel=\"noreferrer noopener\">site du Minist\u00e8re de l\u2019Europe et des Affaires \u00e9trang\u00e8res<\/a>&nbsp;pour trouver les coordonn\u00e9es des ambassades fran\u00e7aises et vous renseigner sur les conditions de r\u00e9sidence et de travail sur place.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/image-2.jpg\"><\/figure>\n<h2 class=\"wp-block-heading\" id=\"creer-micro\"><strong>Pourquoi est-il int\u00e9ressant pour le conjoint expatri\u00e9 de cr\u00e9er sa micro-entreprise ?<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Il existe plusieurs raisons pour lesquelles la cr\u00e9ation de sa micro-entreprise en France peut s\u2019av\u00e9rer int\u00e9ressante notamment pour les&nbsp;conjoints d\u2019expatri\u00e9s. Je pense notamment \u00e0 celles ci :<\/p>\n<h3 class=\"wp-block-heading\"><strong>L\u2019entrepreneuriat permet de trouver un \u00e9quilibre de vie en expatriation<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">L\u2019une des principales difficult\u00e9s, pour les femmes qui ont choisi d\u2019accompagner leur mari \u00e0 l\u2019\u00e9tranger, est d\u2019avoir une activit\u00e9 professionnelle. En effet, la majorit\u00e9 d\u2019entre elles n\u2019a pas d\u2019autre choix que de&nbsp;d\u00e9missionner pour suivre leur conjoint. Et parfois, ce sacrifice am\u00e8ne de la frustration et des reproches au fil du temps. Par ailleurs, retrouver un poste \u00e9quivalent \u00e0 celui qu\u2019elles avaient en France est g\u00e9n\u00e9ralement un v\u00e9ritable parcours du combattant. C\u2019est pourquoi se lancer \u00e0 son compte et cr\u00e9er sa micro-entreprise en France peut mettre fin \u00e0 la recherche syst\u00e9matique et compliqu\u00e9e d\u2019un emploi \u00e0 l\u2019\u00e9tranger et ainsi&nbsp;trouver un meilleur \u00e9quilibre vie priv\u00e9e vie professionnelle en expatriation.<\/p>\n<h3 class=\"wp-block-heading\"><strong>La simplicit\u00e9 du r\u00e9gime de la micro-entreprise<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Il est plut\u00f4t facile de cr\u00e9er son entreprise sous le r\u00e9gime de la micro-entreprise.&nbsp;<strong>Une simple d\u00e9claration en ligne suffit<\/strong>. Et puis cela vous permet de g\u00e9rer vous-m\u00eame votre quotidien. Par ailleurs vous ne prenez aucun risque. En effet, si finalement vous vous rendez compte qu\u2019entreprendre au f\u00e9minin&nbsp;n\u2019est pas pour vous, vous pouvez simplement fermer votre activit\u00e9 ou changer de statut si celui de la micro-entreprise n\u2019est pas adapt\u00e9e \u00e0 vos revenus.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Avoir un revenu \u00e0 l\u2019\u00e9tranger gr\u00e2ce \u00e0 un m\u00e9tier ind\u00e9pendant<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Vous quittez votre emploi car votre mari a d\u00e9croch\u00e9 une opportunit\u00e9 professionnelle. Bien souvent, son salaire devient plus attractif et le mari peut subvenir aux besoins de toute la famille. Oui mais voil\u00e0, la femme a aussi besoin de remplir ses journ\u00e9es pour ne pas se retrouver seule. Et puis si vous aviez un emploi en France, vous avez certainement envie d\u2019avoir aussi une reconnaissance professionnelle et des revenus ! En&nbsp;construisant votre projet professionnel \u00e0 l\u2019\u00e9tranger, vous retrouvez justement un niveau d\u2019ind\u00e9pendance financi\u00e8re. Enfin, cette option vous permet \u00e9galement de&nbsp;pr\u00e9parer sereinement un futur retour en France.<\/p>\n<h3 class=\"wp-block-heading\"><strong>La micro-entreprise est sans risque<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Le cadre juridique de la micro-entreprise vous permet de&nbsp;<strong>tester votre activit\u00e9 sans contraintes financi\u00e8res<\/strong>. Vous ne payez pas de cotisations ni de contributions sociales tant que vous ne faites pas de chiffre d\u2019affaires. Vous n\u2019avez aucun capital \u00e0 apporter \u00e0 la cr\u00e9ation et les formalit\u00e9s administratives sont simplifi\u00e9es. De plus, si votre business ne fonctionne pas, vous pouvez mettre fin \u00e0 votre entreprise rapidement et sans frais.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/image-1-2.jpg\"><\/figure>\n<h2 class=\"wp-block-heading\" id=\"micro-entrepreneur\"><strong>Comment faire pour s\u2019immatriculer comme micro-entrepreneur en France ?<\/strong><\/h2>\n<h3 class=\"wp-block-heading\"><strong>Avant de d\u00e9clarer votre activit\u00e9<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Avant de vous lancer, assurez-vous que le r\u00e9gime du micro-entrepreneur est adapt\u00e9 \u00e0 l\u2019activit\u00e9 que vous souhaitez exercer. En effet, ler\u00e9gime du micro-entrepreneur permet d\u2019exercer des&nbsp;<strong>activit\u00e9s de nature commerciale, artisanale ou lib\u00e9rale<\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">En r\u00e8gle g\u00e9n\u00e9rale, les conjoints expatri\u00e9s pratiquent une profession lib\u00e9rale dite \u00ab&nbsp;non r\u00e9glement\u00e9e&nbsp;\u00bb. Si vous souhaitez v\u00e9rifier que votre activit\u00e9 en fait bien partie, vous pouvez consulter la&nbsp;liste non exhaustive des professions lib\u00e9rales non r\u00e9glement\u00e9es qui s\u2019exercent en micro-entrepreneur.<\/p>\n<h3 class=\"wp-block-heading\"><strong>D\u00e9clarer son activit\u00e9 en ligne<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Pour cr\u00e9er votre micro-entreprise, vous allez faire une d\u00e9claration de d\u00e9but d\u2019activit\u00e9 aupr\u00e8s d\u2019un&nbsp;<strong>Centre de Formalit\u00e9 des Entreprises&nbsp;<\/strong>(CFE).<\/p>\n<p class=\"wp-block-paragraph\">Pour faire simple et \u00e9viter de vous rendre sur place, il est tout \u00e0 fait possible d\u2019effectuer cette d\u00e9marche en ligne. Vous aurez simplement besoin d\u2019une connexion internet, d\u2019une adresse mail valide et de vos justificatifs d\u2019identit\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">Il existe diff\u00e9rents CFE en ligne en fonction de la nature de votre activit\u00e9. Ici je vais parler uniquement des&nbsp;<strong>activit\u00e9s lib\u00e9rales non r\u00e9glement\u00e9es<\/strong>&nbsp;puisque ce sont celles qui vont vous permettre de&nbsp;travailler en freelance \u00e0 l\u2019\u00e9tranger.<\/p>\n<p class=\"wp-block-paragraph\">Rendez-vous ensuite sur le&nbsp;<a target=\"_blank\" href=\"https:\/\/www.cfe.urssaf.fr\/autoentrepreneur\/CFE_Bienvenue\" rel=\"noreferrer noopener\">site Auto-entrepreneur<\/a>, un service des Urssaf. Vous n\u2019aurez plus qu\u2019\u00e0 suivre les \u00e9tapes indiqu\u00e9es. On vous demandera, par exemple, votre domaine d\u2019activit\u00e9, sa d\u00e9nomination exacte\u2026 Une fois que vous avez tout renseign\u00e9, il suffit de valider votre d\u00e9claration en ligne.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Apr\u00e8s la validation de la d\u00e9claration en ligne de cr\u00e9ation d\u2019entreprise<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Vous recevez un mail vous informant que la demande est en cours de traitement. Une fois que le dossier est valid\u00e9 par le CFE, vous recevez&nbsp;<strong>un r\u00e9c\u00e9piss\u00e9 de d\u00e9p\u00f4t de dossier de cr\u00e9ation d\u2019entreprise<\/strong>. Celui-ci indique que le CFE a bien transmis le dossier aux organismes concern\u00e9s (Urssaf, Insee\u2026). Et enfin, l\u2019INSEE vous communique tous les identifiants de votre entreprise (num\u00e9ro SIREN, SIRET, code APE). Ce document est \u00e0 garder pr\u00e9cieusement dans vos archives.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/image-2-1.jpg\"><\/figure>\n<h2 class=\"wp-block-heading\" id=\"cout\"><strong>Quel co\u00fbt pour devenir auto-entrepreneur ?<\/strong><\/h2>\n<p class=\"wp-block-paragraph\"><strong>L\u2019inscription en micro-entrepreneur est gratuite<\/strong>, sauf pour l\u2019agent commercial. Vous n\u2019aurez donc aucun paiement \u00e0 effectuer, ni m\u00eame de frais d\u2019inscription. C\u2019est donc une d\u00e9marche que vous pouvez accomplir vous-m\u00eame sans avoir \u00e0 prendre l\u2019attache d\u2019une entreprise moyennant paiement. Apr\u00e8s vous \u00eates tout \u00e0 fait libre de d\u00e9l\u00e9guer cette t\u00e2che.<\/p>\n<h2 class=\"wp-block-heading\" id=\"obligations\"><strong>Quelles sont les obligations apr\u00e8s la cr\u00e9ation de sa micro-entreprise ?<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">La cr\u00e9ation de sa micro-entreprise ne demande aucune obligation particuli\u00e8re. Vous pouvez travailler en tant qu\u2019auto-entrepreneur, car c\u2019est un statut qui vous permet de d\u00e9marrer votre activit\u00e9 sans aucun investissement lourd.<\/p>\n<p class=\"wp-block-paragraph\">Le seul imp\u00e9ratif, c\u2019est d\u2019informer le CFE de tout changement ou modification de votre situation. Celle-ci peut avoir une incidence sur le fonctionnement de votre soci\u00e9t\u00e9 ou d\u2019autres obligations juridiques (d\u00e9claration de TVA par exemple).<\/p>\n<h3 class=\"wp-block-heading\"><strong>Les autres d\u00e9marches pour exercer son activit\u00e9 sous le r\u00e9gime de la micro-entreprise<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Apr\u00e8s votre immatriculation, vous pourrez cr\u00e9er tous vos comptes administratifs en ligne en rapport avec votre activit\u00e9 (Urssaf, Direction G\u00e9n\u00e9rale des Finances Publiques\u2026). Vous aurez \u00e9galement besoin de cr\u00e9er un compte bancaire d\u00e9di\u00e9 et de souscrire aux assurances professionnelles.<\/p>\n<p class=\"wp-block-paragraph\">Le statut d\u2019auto-entrepreneur vous permet de d\u00e9marrer votre activit\u00e9 tr\u00e8s simplement, sans aucun investissement. Vous pourrez ainsi vous lancer en toute s\u00e9r\u00e9nit\u00e9 sans vous soucier de devoir payer un avocat ou un banquier. Le seul imp\u00e9ratif, c\u2019est de s\u2019informer sur les obligations juridiques et administratives qui vont s\u2019appliquer \u00e0 votre entreprise.\u00a0<strong>En cr\u00e9ant votre micro-entreprise en France, vous avez la garantie d\u2019avoir un emploi tout en suivant votre conjoint \u00e0 l\u2019\u00e9tranger<\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/image-16.jpg\"><\/figure>\n<p class=\"wp-block-paragraph\"><strong>NADIA BULCOURT<\/strong><\/p>\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/conjointsexpatries.com\/creer-sa-micro-entreprise-en-france-et-resider-a-letranger\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les Conjoints d&rsquo;Expatri\u00e9s<\/a><br \/><em>Expatri\u00e9e depuis plus de 15 ans, j&rsquo;ai eu l&rsquo;id\u00e9e de cr\u00e9er ce blog dans le but d&rsquo;aider les conjoints expatri\u00e9s \u00e0 s&rsquo;\u00e9panouir pleinement pendant leur s\u00e9jour \u00e0 l&rsquo;\u00e9tranger. Ayant travaill\u00e9 plus de 11 ans dans l&rsquo;administration des Fran\u00e7ais de l&rsquo;\u00e9tranger, je me tourne d\u00e9sormais vers ces conjoints expatri\u00e9s, souvent oubli\u00e9s. Je mets \u00e0 profit mon exp\u00e9rience internationale pour leur partager mes astuces et conseils, notamment en mati\u00e8re de vie professionnelle pour qu&rsquo;ils puissent relever tous les d\u00e9fis de l&rsquo;expatriation.<\/em><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expat : comment avoir le statut d\u2019auto-entrepreneur en France ? Cr\u00e9er sa propre entreprise en France et habiter \u00e0 l\u2019\u00e9tranger. Cette id\u00e9e peut para\u00eetre \u00e9trange au premier abord, mais en r\u00e9alit\u00e9, il s\u2019agit d\u2019une option qui a fait ses preuves et qui peut r\u00e9ellement vous aider \u00e0 mener une carri\u00e8re \u00e0 l\u2019\u00e9tranger. Une option surtout [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":27323,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,4392],"tags":[],"class_list":["post-70093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-patrimoine"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=70093"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/27323"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=70093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=70093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=70093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}