{"id":70072,"date":"2026-03-09T06:37:22","date_gmt":"2026-03-09T06:37:22","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/exxacon-va-developper-76-logements-a-odon-et-galapagar-2\/"},"modified":"2026-05-07T16:42:21","modified_gmt":"2026-05-07T16:42:21","slug":"exxacon-va-developper-76-logements-a-odon-et-galapagar-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/exxacon-va-developper-76-logements-a-odon-et-galapagar-2\/","title":{"rendered":"Exxacon va d\u00e9velopper 76 logements \u00e0 Od\u00f3n et Galapagar"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p><em>Le promoteur de la Costa del Sol lance un projet de 48 logements \u00e0 Villaviciosa de Od\u00f3n et un autre de 28 r\u00e9sidences \u00e0 Galapagar. Il s&#8217;agit de maisons jumel\u00e9es dans une communaut\u00e9 avec des services.<\/em><\/p>\n<p>EjePrime, 16 juin 2022<\/p>\n<p>Exxacon s&#8217;engage une fois de plus \u00e0 Madrid. Le promoteur r\u00e9sidentiel a lanc\u00e9 deux nouveaux projets \u00e0 Villaviciosa de Od\u00f3n et Galapagar, qui totaliseront 76 unit\u00e9s. <\/p>\n<p>Exxacon commencera \u00e0 livrer dans les prochains mois les logements de son premier projet \u00e0 Madrid, dans la ville de Colmenar Viejo, o\u00f9 elle d\u00e9veloppe 156 logements. Situ\u00e9 dans la zone connue sous le nom de Monte de la Villa, tr\u00e8s proche du centre-ville de Villaviciosa de Od\u00f3n, le promoteur a acquis une zone constructible de 12.040 m\u00e8tres carr\u00e9s, o\u00f9 il construira 48 maisons unifamiliales jumel\u00e9es. <\/p>\n<p>Dans une communaut\u00e9 ferm\u00e9e, le projet disposera de services communs tels qu&#8217;un court de padel, un gymnase, un putting green et des piscines. <\/p>\n<p>\u00c0 Galapagar, Exxacon construira 28 logements (26 maisons jumel\u00e9es et deux maisons individuelles) sur un terrain de 20.750 m\u00e8tres carr\u00e9s. Dans un environnement entour\u00e9 par la nature, le d\u00e9veloppement disposera \u00e9galement de piscines, d&#8217;un putting green, d&#8217;une aire de jeux pour enfants et d&#8217;une zone de rencontre pour toute la communaut\u00e9. <\/p>\n<p>Viejo Exxacon, un promoteur r\u00e9sidentiel fond\u00e9 en 2000 \u00e0 Marbella, a d\u00e9velopp\u00e9 37 promotions immobili\u00e8res  au cours de son histoire, avec 2.035 unit\u00e9s, dont il a d\u00e9j\u00e0 livr\u00e9 688 logements. Actuellement, l&#8217;entreprise compte 17 projets en cours, avec un total de plus de 1.314 logements \u00e0 diff\u00e9rents stades de d\u00e9veloppement. <\/p>\n<p>Le promoteur a des projets dans la ville de Malaga ainsi que diff\u00e9rents projets sur la Costa del Sol, \u00e0 S\u00e9ville, Madrid et Valence. Elle a \u00e9galement une position forte au Chili.<\/p>\n<p>Source <a href=\"https:\/\/www.ejeprime.com\/residencial\/exxacon-promovera-76-viviendas-en-odon-y-galapagar.html\" target=\"_blank\" rel=\"noreferrer noopener\">EjePrime<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le promoteur de la Costa del Sol lance un projet de 48 logements \u00e0 Villaviciosa de Od\u00f3n et un autre de 28 r\u00e9sidences \u00e0 Galapagar. Il s&#8217;agit de maisons jumel\u00e9es dans une communaut\u00e9 avec des services. EjePrime, 16 juin 2022 Exxacon s&#8217;engage une fois de plus \u00e0 Madrid. Le promoteur r\u00e9sidentiel a lanc\u00e9 deux nouveaux [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":27243,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-70072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=70072"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/27243"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=70072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=70072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=70072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}