{"id":70024,"date":"2026-03-09T05:46:14","date_gmt":"2026-03-09T05:46:14","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/extendam-achete-deux-hotels-a-la-corogne-2\/"},"modified":"2026-05-07T15:47:07","modified_gmt":"2026-05-07T15:47:07","slug":"extendam-achete-deux-hotels-a-la-corogne-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/extendam-achete-deux-hotels-a-la-corogne-2\/","title":{"rendered":"Extendam ach\u00e8te deux h\u00f4tels \u00e0 La Corogne"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p><em>Le fonds d&#8217;investissement Extendam a achet\u00e9 deux actifs en Espagne, qui sont exploit\u00e9s sous les marques Hilton et Accor. Les h\u00f4tels n&#8217;auront pas besoin d&#8217;\u00eatre r\u00e9nov\u00e9s, mais feront l&#8217;objet d&#8217;une nouvelle strat\u00e9gie de gestion des revenus, sous l&#8217;impulsion du nouvel op\u00e9rateur et co-investisseur DG Invest.<\/em><\/p>\n<p>Hosteltur, 6 juillet 2022<\/p>\n<p>D&#8217;une part, elle a fait l&#8217;acquisition du DoubleTree by Hilton de La Corogne, un h\u00f4tel situ\u00e9 au c\u0153ur du centre-ville, qui compte 59 chambres, un espace bien-\u00eatre et une salle de sport. L&#8217;\u00e9tablissement a rouvert ses portes en septembre 2019, apr\u00e8s une importante remise \u00e0 neuf.<\/p>\n<p>D&#8217;autre part, le fonds fran\u00e7ais a repris l&#8217;Ibis Styles A Coru\u00f1a, situ\u00e9 au c\u0153ur du quartier des affaires et d&#8217;un important centre administratif. Cet h\u00f4tel de 84 chambres dispose d&#8217;un restaurant, de trois salles de r\u00e9ception et se trouve \u00e0 15 minutes \u00e0 pied de la gare et \u00e0 12 minutes en voiture de l&#8217;a\u00e9roport. L&#8217;h\u00f4tel a \u00e9t\u00e9 r\u00e9nov\u00e9 en 2018.<\/p>\n<p>Avec ces deux nouvelles acquisitions, Extendam compte d\u00e9sormais 18 h\u00f4tels en Espagne et 21 dans la p\u00e9ninsule ib\u00e9rique. Le fonds compte un total de 270 h\u00f4tels et un investissement de plus de 2,8 milliards d&#8217;euros en actifs.<\/p>\n<p>Source <a href=\"https:\/\/www.hosteltur.com\/152367_extendam-compra-dos-hoteles-en-la-coruna.html\" target=\"_blank\" rel=\"noreferrer noopener\">Hosteltur<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fonds d&#8217;investissement Extendam a achet\u00e9 deux actifs en Espagne, qui sont exploit\u00e9s sous les marques Hilton et Accor. Les h\u00f4tels n&#8217;auront pas besoin d&#8217;\u00eatre r\u00e9nov\u00e9s, mais feront l&#8217;objet d&#8217;une nouvelle strat\u00e9gie de gestion des revenus, sous l&#8217;impulsion du nouvel op\u00e9rateur et co-investisseur DG Invest. Hosteltur, 6 juillet 2022 D&#8217;une part, elle a fait l&#8217;acquisition [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":27012,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-70024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=70024"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/27012"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=70024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=70024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=70024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}