{"id":70004,"date":"2026-03-09T05:31:09","date_gmt":"2026-03-09T05:31:09","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/lun-des-derniers-hotels-particuliers-darturo-soria-madrid-sera-vendu-aux-encheres-pour-14-million-deuros-2\/"},"modified":"2026-05-07T15:38:14","modified_gmt":"2026-05-07T15:38:14","slug":"lun-des-derniers-hotels-particuliers-darturo-soria-madrid-sera-vendu-aux-encheres-pour-14-million-deuros-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/lun-des-derniers-hotels-particuliers-darturo-soria-madrid-sera-vendu-aux-encheres-pour-14-million-deuros-2\/","title":{"rendered":"L&#8217;un des derniers h\u00f4tels particuliers d&#8217;Arturo Soria (Madrid) sera vendu aux ench\u00e8res pour 1,4 million d&#8217;euros"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p><em>Le b\u00e2timent est en train d&#8217;\u00eatre catalogu\u00e9 comme b\u00e2timent prot\u00e9g\u00e9 par la mairie de Madrid &#8211; Un des derniers h\u00e9ritages de la Ciudad Lineal de l&#8217;urbaniste Arturo Soria.<\/em><\/p>\n<p>Idealista, 6 juillet 2022<\/p>\n<p>L&#8217;un des derniers vestiges de la Ciudad Lineal planifi\u00e9e par Arturo Soria a \u00e9t\u00e9 mis en vente pour 1,4 million. Ce manoir, connu sous le nom de Villa Menchu, est situ\u00e9 dans la rue Mar\u00eda Lombillo. Avant la pand\u00e9mie, il est pass\u00e9 entre les mains d&#8217;une banque apr\u00e8s une saisie. Les voisins ont demand\u00e9 \u00e0 la mairie de le classer comme \u00e9l\u00e9ment prot\u00e9g\u00e9, alors que le processus de vente se poursuit.<\/p>\n<p>Le b\u00e2timent d&#8217;origine date de 1920, mais il a \u00e9t\u00e9 r\u00e9form\u00e9 \u00e0 plusieurs reprises pour l&#8217;adapter aux diff\u00e9rentes utilisations qu&#8217;il a connues. En fait, elle a \u00e9t\u00e9 transform\u00e9e d&#8217;un logement en locaux, pour devenir le si\u00e8ge d&#8217;une clinique dentaire avant d&#8217;\u00eatre reprise. Aujourd&#8217;hui, il est annonc\u00e9 avec la possibilit\u00e9 de redevenir une maison priv\u00e9e.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/image-11-1.jpg\"><\/figure>\n<p>La maison est r\u00e9partie sur trois \u00e9tages ouverts auxquels on peut acc\u00e9der par un ascenseur int\u00e9rieur. Elle est situ\u00e9e sur un terrain de 480 m2, dont 336 m2 sont construits. Il s&#8217;agit d&#8217;une propri\u00e9t\u00e9 tr\u00e8s lumineuse car elle dispose de plusieurs terrasses \u00e0 ses \u00e9tages sup\u00e9rieurs et de grandes fen\u00eatres, caract\u00e9ristiques de son style moderniste. La vente est soumise \u00e0 des ench\u00e8res professionnelles avec un prix de d\u00e9part minimum de 1,45 million d&#8217;euros.<\/p>\n<p>La Villa Menchu sera incluse dans l&#8217;extension du catalogue des b\u00e2timents prot\u00e9g\u00e9s de la mairie de Madrid.<\/p>\n<p>Maintenant que le b\u00e2timent historique est sur le march\u00e9, le d\u00e9partement du d\u00e9veloppement urbain de la mairie de Madrid a propos\u00e9 d&#8217;inclure 738 nouveaux b\u00e2timents, de tous types, dans le catalogue des b\u00e2timents prot\u00e9g\u00e9s. Cette augmentation du patrimoine prot\u00e9g\u00e9 se concentre sur l&#8217;architecture industrielle et moderne, qui n&#8217;\u00e9tait pas prot\u00e9g\u00e9e dans les initiatives pr\u00e9c\u00e9dentes.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/image-12-1.jpg\"><\/figure>\n<p>Parmi eux, la Villa Menchu, parce qu&#8217;elle est &#8220;un \u00e9l\u00e9ment isol\u00e9, vestige de l&#8217;environnement urbain disparu ou d\u00e9figur\u00e9, \u00e0 condition qu&#8217;il r\u00e9ponde \u00e0 des processus urbanistiques significatifs pour l&#8217;histoire de l&#8217;urbanisme de la ville&#8221;, a d\u00e9clar\u00e9 le Consistoire de Madrid dans un communiqu\u00e9. L&#8217;un des environnements les plus touch\u00e9s est la conception environnementale historique de la Ciudad Lineal, planifi\u00e9e par Arturo Soria, et o\u00f9 33 b\u00e2timents doivent \u00eatre incorpor\u00e9s, dont ce manoir.<\/p>\n<p>L&#8217;Association culturelle Arturo Soria Legacy et les associations de quartier du secteur avaient d\u00e9nonc\u00e9 l&#8217;abandon du b\u00e2timent apr\u00e8s sa cession \u00e0 l&#8217;institution financi\u00e8re, et le fait qu&#8217;il subissait des actes de vandalisme, tels que des agressions et des graffitis sur sa fa\u00e7ade.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/image-13-1.jpg\"><\/figure>\n<p>Il fait actuellement l&#8217;objet d&#8217;une p\u00e9riode d&#8217;information publique de deux mois, qui concernera \u00e9galement d&#8217;autres b\u00e2timents de la zone, tels que l&#8217;h\u00f4tel Rub\u00edn, actuellement r\u00e9sidence pour mineurs et ancienne maison d&#8217;Arturo Soria, et le Colegio Hu\u00e9rfanos de la Armada (\u00e9cole des orphelins de la marine).<\/p>\n<p>D&#8217;autre part, le catalogue a \u00e9t\u00e9 \u00e9largi pour inclure des b\u00e2timents de la seconde moiti\u00e9 du XXe si\u00e8cle tels que l&#8217;immeuble Castelar (1983), au 50 Paseo de la Castellana ; la Fondation Juan March (1975) au 77 Calle Castell\u00f3 ou la Basilique hispano-am\u00e9ricaine Nuestra Se\u00f1ora de la Merced (1949-1965) au 23 Calle Edgar Neville, ou la coop\u00e9rative de logements militaires Santa Cruz de Marcenado.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/image-14-1.jpg\"><\/figure>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/image-15.jpg\"><\/figure>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/image-16.png\"><\/figure>\n<p>Source <a href=\"https:\/\/www.idealista.com\/news\/deco\/casas-de-ensueno\/2022\/07\/06\/797734-se-subasta-uno-de-los-ultimos-palacetes-en-arturo-soria-madrid-por-1-4-millones\" target=\"_blank\" rel=\"noreferrer noopener\">Idealista<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le b\u00e2timent est en train d&#8217;\u00eatre catalogu\u00e9 comme b\u00e2timent prot\u00e9g\u00e9 par la mairie de Madrid &#8211; Un des derniers h\u00e9ritages de la Ciudad Lineal de l&#8217;urbaniste Arturo Soria. Idealista, 6 juillet 2022 L&#8217;un des derniers vestiges de la Ciudad Lineal planifi\u00e9e par Arturo Soria a \u00e9t\u00e9 mis en vente pour 1,4 million. Ce manoir, connu [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":26944,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-70004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=70004"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/70004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/26944"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=70004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=70004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=70004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}