{"id":69809,"date":"2026-03-09T03:00:49","date_gmt":"2026-03-09T03:00:49","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/la-proptech-allemande-evernest-choisit-madrid-pour-son-expansion-internationale-2\/"},"modified":"2026-05-13T09:51:50","modified_gmt":"2026-05-13T09:51:50","slug":"la-proptech-allemande-evernest-choisit-madrid-pour-son-expansion-internationale-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/la-proptech-allemande-evernest-choisit-madrid-pour-son-expansion-internationale-2\/","title":{"rendered":"La PropTech allemande Evernest choisit Madrid pour son expansion internationale"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p>La PropTech allemande Evernest choisit Madrid pour son expansion internationale<br \/>De plus, l&#8217;entreprise \u00e9tudie l&#8217;expansion de sa pr\u00e9sence dans d&#8217;autres r\u00e9gions du pays, comme Barcelone ou Malaga.<\/p>\n<p>Marie Moreno, Madrid<\/p>\n<p>La PropTech allemande Evernest d\u00e9barque \u00e0 Madrid, commen\u00e7ant ainsi son expansion internationale. L&#8217;entreprise a d\u00e9velopp\u00e9 une plateforme num\u00e9rique pour ses agents immobiliers qui leur permet de simplifier le processus d&#8217;achat et de vente d&#8217;un bien gr\u00e2ce \u00e0 l&#8217;intelligence artificielle et \u00e0 l&#8217;analyse des donn\u00e9es.<\/p>\n<p>Avec l&#8217;utilisation de la plateforme, la startup a num\u00e9ris\u00e9 le march\u00e9 en Allemagne en doublant sa taille en un an. L&#8217;entreprise compte actuellement plus de 200 employ\u00e9s et agents immobiliers sur ses cinq sites en Allemagne : Hambourg, le si\u00e8ge social, Berlin et ses trois derni\u00e8res ouvertures en mars 2022 \u00e0 D\u00fcsseldorf, Francfort et Cologne.<\/p>\n<p>Evernest a r\u00e9ussi \u00e0 tripler son chiffre d&#8217;affaires et le volume de transactions sous contrat au premier semestre de cette ann\u00e9e par rapport \u00e0 la m\u00eame p\u00e9riode en 2021. Compte tenu des bons r\u00e9sultats, l&#8217;entreprise souhaite r\u00e9pliquer son mod\u00e8le dans les principales villes d&#8217;Europe et a choisi comme son premier emplacement pour commencer son expansion \u00e0 Madrid, car c&#8217;est une ville qui double Berlin en termes de volume de transactions immobili\u00e8res.<\/p>\n<p><strong>Madrid comme r\u00e9f\u00e9rence pour l&#8217;immobilier de luxe<\/strong><\/p>\n<p>La capitale espagnole a \u00e9t\u00e9 choisie par la proptech allemande pour ouvrir son premier bureau international, \u00e9tant donn\u00e9 que dans le monde de l&#8217;immobilier Madrid est une r\u00e9f\u00e9rence dans le secteur du luxe avec des quartiers comme Salamanca, Chamber\u00ed ou Chamart\u00edn.<\/p>\n<p>Par ailleurs, l&#8217;entreprise \u00e9tudie l&#8217;extension de sa pr\u00e9sence dans d&#8217;autres r\u00e9gions du pays, comme Barcelone ou Malaga, ainsi que dans des destinations de r\u00e9sidence secondaire comme les \u00eeles Bal\u00e9ares, les \u00eeles Canaries ou la Costa del Sol. comme une destination optimale pour le secteur immobilier depuis En fait, selon les donn\u00e9es de l&#8217;INE, au premier semestre 2022, la vente de maisons dans le pays a connu ses plus hauts historiques depuis 2007.<\/p>\n<p>La personne en charge du d\u00e9marrage du projet Evernest en Espagne sera Oscar Larrea, vice-pr\u00e9sident senior d&#8217;Evernest Espagne, qui a plus de 20 ans d&#8217;exp\u00e9rience dans le secteur immobilier et dont les objectifs pour le march\u00e9 espagnol ont \u00e9t\u00e9 fix\u00e9s pour atteindre un minimum de 150 agents en 2023 et jusqu&#8217;\u00e0 500 en 2024.<\/p>\n<p>Par ailleurs, en d\u00e9but d&#8217;ann\u00e9e, la startup a boucl\u00e9 un tour de table de 13 millions d&#8217;euros, co-men\u00e9 par le fonds new-yorkais, Prudence et par le fonds espagnol Kibo Ventures, et Bonsai Partners, ainsi que les pr\u00e9c\u00e9dents investisseurs Evernest. . , Project A Ventures et APIC, pour acc\u00e9l\u00e9rer le d\u00e9veloppement technologique de sa plateforme et amorcer son expansion internationale.<\/p>\n<p>\u00ab Dans notre vision de nous positionner comme la premi\u00e8re plateforme num\u00e9rique et soci\u00e9t\u00e9 immobili\u00e8re en Europe, l&#8217;Espagne, plus pr\u00e9cis\u00e9ment Madrid, joue un r\u00f4le fondamental, car c&#8217;est le premier bureau que nous ouvrirons. Les opportunit\u00e9s de num\u00e9risation du secteur sont \u00e9normes et nous sommes convaincus qu&#8217;Evernest contribue non seulement \u00e0 am\u00e9liorer le travail des agents et des conseillers, mais contribue \u00e9galement \u00e0 cr\u00e9er des exp\u00e9riences client vraiment positives et satisfaisantes \u00bb, d\u00e9clare Christian Evers, fondateur et PDG d&#8217;Evernest \u00e0 propos de son expansion en Espagne.<\/p>\n<p>Oscar Larrea, vice-pr\u00e9sident senior d&#8217;Evernest Espagne, commente \u00abEvernest est pour moi le projet le plus excitant et le plus ambitieux du secteur immobilier international de ces 20 derni\u00e8res ann\u00e9es et je suis tr\u00e8s heureux de d\u00e9velopper la croissance en Espagne. Je crois fermement que nous pouvons offrir une plateforme compl\u00e8te et le CRM le plus puissant et le plus avanc\u00e9 pour les consultants immobiliers. Avec la combinaison de la technologie, nos ann\u00e9es d&#8217;exp\u00e9rience dans le secteur immobilier et une marque contemporaine, nous serons en mesure d&#8217;offrir \u00e0 nos clients un service beaucoup plus professionnel et plus rapide.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La PropTech allemande Evernest choisit Madrid pour son expansion internationaleDe plus, l&#8217;entreprise \u00e9tudie l&#8217;expansion de sa pr\u00e9sence dans d&#8217;autres r\u00e9gions du pays, comme Barcelone ou Malaga. Marie Moreno, Madrid La PropTech allemande Evernest d\u00e9barque \u00e0 Madrid, commen\u00e7ant ainsi son expansion internationale. L&#8217;entreprise a d\u00e9velopp\u00e9 une plateforme num\u00e9rique pour ses agents immobiliers qui leur permet de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":22342,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-69809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/69809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=69809"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/69809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/22342"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=69809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=69809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=69809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}