{"id":69808,"date":"2026-03-09T03:00:43","date_gmt":"2026-03-09T03:00:43","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/urban-campus-entame-son-expansion-internationale-et-choisit-lille-pour-son-premier-immeuble-de-coliving-en-france-2\/"},"modified":"2026-07-11T03:52:03","modified_gmt":"2026-07-11T03:52:03","slug":"urban-campus-entame-son-expansion-internationale-et-choisit-lille-pour-son-premier-immeuble-de-coliving-en-france-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/urban-campus-entame-son-expansion-internationale-et-choisit-lille-pour-son-premier-immeuble-de-coliving-en-france-2\/","title":{"rendered":"Urban Campus entame son expansion internationale et choisit Lille pour son premier immeuble de coliving en France"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;entreprise pr\u00e9voit d&rsquo;ajouter 30 nouveaux b\u00e2timents dans les cinq prochaines ann\u00e9es, dont 20 \u00e0 l&rsquo;\u00e9tranger.<br \/>(Brainsre)<\/p>\n<p>Campus urbain Andr\u00e9s Mellado 80<br \/>Urban Campus, op\u00e9rateur de b\u00e2timents complets de coliving, franchit pour la premi\u00e8re fois la fronti\u00e8re espagnole et ouvrira \u00e0 Lille avant la fin de l&rsquo;ann\u00e9e.<\/p>\n<p class=\"wp-block-paragraph\">Une fois la pr\u00e9sence nationale \u00e9tablie, l&rsquo;expansion internationale \u00e9tait l&rsquo;un des objectifs de cette entreprise et l&rsquo;atterrissage en France se fera par le biais du Campus Urbain Saint So, qui sera situ\u00e9 dans la rue centrale de Douai dans la ville fran\u00e7aise.<\/p>\n<p class=\"wp-block-paragraph\">Urban Campus Saint So, un b\u00e2timent enti\u00e8rement r\u00e9nov\u00e9, dispose de quatre \u00e9tages avec 38 studios et appartements et 300 m\u00e8tres carr\u00e9s d&rsquo;espaces communs avec cuisine, salon, terrasses, coworking, salle de sport, biblioth\u00e8que et espaces pour \u00e9v\u00e9nements.<\/p>\n<p class=\"wp-block-paragraph\">De plus, il propose \u00e9galement son service tout compris habituel, de la connexion internet au m\u00e9nage et l&rsquo;acc\u00e8s \u00e0 Netflix dans les parties communes.<\/p>\n<p class=\"wp-block-paragraph\">Avec cela, il y a deux projets qu&rsquo;Urban Campus exploitera dans la ville fran\u00e7aise. Le Campus Urbain La Maillerie sera le prochain, m\u00eame s&rsquo;il n&rsquo;ouvrira qu&rsquo;en 2024. Dans ce cas, il sera compos\u00e9 de 121 appartements en colocation.<\/p>\n<p class=\"wp-block-paragraph\">Par ailleurs, l&rsquo;entreprise travaille d\u00e9j\u00e0 sur d&rsquo;autres projets de coliving dans le pays voisin en r\u00e9gion parisienne et en province. Comme l&rsquo;explique Ana Mart\u00ednez, directrice des op\u00e9rations d&rsquo;Urban Campus, l&rsquo;entreprise a l&rsquo;intention d&rsquo;ouvrir jusqu&rsquo;\u00e0 30 nouveaux centres d&rsquo;ici cinq ans et seulement dix d&rsquo;entre eux seraient en Espagne.<\/p>\n<p class=\"wp-block-paragraph\">Pour Maxime Armand, co-fondateur et COO d&rsquo;Urban Campus, \u00ab notre arriv\u00e9e dans une r\u00e9gion dynamique du march\u00e9 fran\u00e7ais est une source de fiert\u00e9. Cela a \u00e9t\u00e9 le fruit d&rsquo;une belle collaboration avec le LCPC (investisseur), Theop (AMO) et le studio d&rsquo;architecture LA.M Studio. Ensemble, nous avons cr\u00e9\u00e9 un immeuble de Coliving, avec une conception et des prestations de tr\u00e8s haute qualit\u00e9, pour r\u00e9pondre au mieux aux attentes des r\u00e9sidents, dans un march\u00e9 tendu. Notre \u00e9quipe a plus de 4 ans d&rsquo;exp\u00e9rience dans la gestion de colivings en Espagne. Le Coliving de Saint So va nous permettre de faire d\u00e9couvrir l&rsquo;exp\u00e9rience r\u00e9sidentielle Urban Campus aux locataires fran\u00e7ais.<\/p>\n<p class=\"wp-block-paragraph\">Ces derniers mois, Urban Campus a \u00e9largi son r\u00e9seau \u00e0 Madrid, avec l&rsquo;ouverture de deux nouveaux b\u00e2timents. Le premier d&rsquo;entre eux, dans le quartier de Tetu\u00e1n, avec une superficie de 1 200 m\u00e8tres carr\u00e9s et 21 studios.<\/p>\n<p class=\"wp-block-paragraph\">Et il y a quelques jours, il a fait de m\u00eame \u00e0 Atocha, l&rsquo;un de ses nouveaux joyaux en raison de son emplacement strat\u00e9gique par rapport au centre-ville et \u00e0 la gare du m\u00eame nom. Avec plus de 2 800 m\u00e8tres carr\u00e9s de surface, il propose 45 alternatives r\u00e9sidentielles entre studios, appartements et chambres.<\/p>\n<p class=\"wp-block-paragraph\">Le locataire type des immeubles de coliving Urban Campus est un jeune actif entre 25 et 45 ans, avec une moyenne d&rsquo;\u00e2ge sp\u00e9cifique de 33 ans. Ils sont principalement internationaux, bien qu&rsquo;\u00e0 la suite de la pand\u00e9mie, le pourcentage national ait augment\u00e9, se maintenant actuellement \u00e0 40 % de nationaux et 60 % d&rsquo;\u00e9trangers.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entreprise pr\u00e9voit d&rsquo;ajouter 30 nouveaux b\u00e2timents dans les cinq prochaines ann\u00e9es, dont 20 \u00e0 l&rsquo;\u00e9tranger.(Brainsre) Campus urbain Andr\u00e9s Mellado 80Urban Campus, op\u00e9rateur de b\u00e2timents complets de coliving, franchit pour la premi\u00e8re fois la fronti\u00e8re espagnole et ouvrira \u00e0 Lille avant la fin de l&rsquo;ann\u00e9e. Une fois la pr\u00e9sence nationale \u00e9tablie, l&rsquo;expansion internationale \u00e9tait l&rsquo;un des [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":26285,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-69808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/69808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=69808"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/69808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/26285"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=69808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=69808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=69808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}