{"id":69615,"date":"2026-03-09T01:33:13","date_gmt":"2026-03-09T01:33:13","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/loperateur-francais-de-glamping-huttopia-debarque-sur-le-marche-espagnol-2\/"},"modified":"2026-08-31T04:05:04","modified_gmt":"2026-08-31T04:05:04","slug":"loperateur-francais-de-glamping-huttopia-debarque-sur-le-marche-espagnol-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/09\/loperateur-francais-de-glamping-huttopia-debarque-sur-le-marche-espagnol-2\/","title":{"rendered":"L&rsquo;op\u00e9rateur fran\u00e7ais de \u00ab\u00a0glamping\u00a0\u00bb Huttopia d\u00e9barque sur le march\u00e9 espagnol"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">Le groupe dirig\u00e9 par C\u00e9line et Philippe Bossanne, avec Daniel Carrillo \u00e0 la t\u00eate de sa filiale en Espagne, a acquis le Village Do\u00f1arragan Park, situ\u00e9 \u00e0 Hinojos (Huelva), et le C\u00e1mping El Bergued\u00e0, \u00e0 Guardiola de Bergued\u00e0 (Barcelone).<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;op\u00e9rateur de \u00ab glamping \u00bb fran\u00e7ais Huttopia d\u00e9barque sur le march\u00e9 espagnol Le glamping \u00e0 la fran\u00e7aise d\u00e9barque en Espagne. Huttopia, fort d&rsquo;une histoire de plus de vingt ans dans le secteur du camping prime en France, a acquis deux complexes de cette classe d&rsquo;actifs situ\u00e9s \u00e0 Hinojos (Huelva) et Guardiola de Bergued\u00e0 (Barcelone). Des sources du march\u00e9 ont confirm\u00e9 l&rsquo;op\u00e9ration, bien que la soci\u00e9t\u00e9 ait refus\u00e9 de la commenter. <\/p>\n<p class=\"wp-block-paragraph\">Huttopia, op\u00e9rateur qui se distingue pour \u00eatre un pionnier sur le segment du glamping, un produit vertical qui s&rsquo;engage pour la qualit\u00e9 et l&rsquo;int\u00e9gration durable dans l&rsquo;environnement, a formalis\u00e9 ces derni\u00e8res semaines diverses soci\u00e9t\u00e9s pour g\u00e9rer ses premiers actifs en Espagne. <\/p>\n<p class=\"wp-block-paragraph\">Le si\u00e8ge de la filiale ib\u00e9rique d&rsquo;Huttopia est situ\u00e9 \u00e0 Madrid, au num\u00e9ro 9 Glorieta Quevedo. Le groupe dirig\u00e9 par C\u00e9line et Philippe Bossanne a mandat\u00e9 Daniel Carrillo pour \u00e9tendre son mod\u00e8le de glamping sur les march\u00e9s espagnol et portugais. Carrillo a plus de quinze ans d&rsquo;exp\u00e9rience dans le secteur du tourisme, o\u00f9 il a occup\u00e9 des postes de responsabilit\u00e9 dans des entreprises telles que Turkish Airlines ou Grupo Sagardi. <\/p>\n<p class=\"wp-block-paragraph\">Huttopia a mandat\u00e9 Daniel Carrillo pour \u00e9tendre son mod\u00e8le \u00ab glamping \u00bb sur les march\u00e9s espagnol et portugais. En Andalousie, Huttopia exploitera le camping quatre \u00e9toiles Village Do\u00f1arragan Park, situ\u00e9 \u00e0 Hinojos (Huelva), au c\u0153ur du Parc National de Do\u00f1ana. Le complexe d&rsquo;une surface totale de 7 000 m\u00e8tres carr\u00e9s abrite 23 logements en bungalow et 48 parcelles.<\/p>\n<p class=\"wp-block-paragraph\">Une fois la saison termin\u00e9e, d\u00e9but novembre, Huttopia proc\u00e9dera \u00e0 des travaux de r\u00e9novation de l&rsquo;actif pour l&rsquo;adapter \u00e0 ses normes, avec qui la r\u00e9ouverture du complexe est pr\u00e9vue en avril prochain. L&rsquo;op\u00e9rateur fran\u00e7ais ajoutera \u00e9galement un autre camping en Catalogne, plus pr\u00e9cis\u00e9ment \u00e0 Guardiola de Bergued\u00e0 (Barcelone). Huttopia exploitera le C\u00e0mping Bergued\u00e0, situ\u00e9 \u00e0 c\u00f4t\u00e9 du Parc Naturel Cad\u00ed-Moixer\u00f3. <\/p>\n<p class=\"wp-block-paragraph\">Le complexe dispose de 71 parcelles de 80 \u00e0 120 m\u00e8tres carr\u00e9s et de six bungalows. La soci\u00e9t\u00e9 a \u00e9galement cr\u00e9\u00e9 une soci\u00e9t\u00e9 bas\u00e9e \u00e0 Saint-Jacques-de-Compostelle, mais elle n&rsquo;a pas pr\u00e9cis\u00e9 sur quel actif dans la zone elle op\u00e9rera. <\/p>\n<p class=\"wp-block-paragraph\">En 2021, Huttopia disposait d&rsquo;un portefeuille de 90 campings et villages situ\u00e9s en France, aux Pays-Bas, en Chine, au Canada et aux Etats-Unis, selon des donn\u00e9es rendues publiques par l&rsquo;entreprise. Au total, l&rsquo;entreprise disposait d&rsquo;une offre de 16 000 logements. L&rsquo;op\u00e9rateur, n\u00e9 en 1999 \u00e0 Lyon, la ville o\u00f9 il maintient son si\u00e8ge social, a atteint un chiffre d&rsquo;affaires de 69 millions d&rsquo;euros en 2021, soit 21 % de plus que l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe dirig\u00e9 par C\u00e9line et Philippe Bossanne, avec Daniel Carrillo \u00e0 la t\u00eate de sa filiale en Espagne, a acquis le Village Do\u00f1arragan Park, situ\u00e9 \u00e0 Hinojos (Huelva), et le C\u00e1mping El Bergued\u00e0, \u00e0 Guardiola de Bergued\u00e0 (Barcelone). L&rsquo;op\u00e9rateur de \u00ab glamping \u00bb fran\u00e7ais Huttopia d\u00e9barque sur le march\u00e9 espagnol Le glamping \u00e0 la [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":69616,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-69615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/69615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=69615"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/69615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/69616"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=69615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=69615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=69615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}