{"id":69464,"date":"2026-03-08T23:57:59","date_gmt":"2026-03-08T23:57:59","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/lecole-francaise-essca-installera-son-premier-campus-en-espagne-a-malaga-2\/"},"modified":"2026-08-30T22:47:51","modified_gmt":"2026-08-30T22:47:51","slug":"lecole-francaise-essca-installera-son-premier-campus-en-espagne-a-malaga-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/lecole-francaise-essca-installera-son-premier-campus-en-espagne-a-malaga-2\/","title":{"rendered":"L&rsquo;\u00e9cole fran\u00e7aise Essca installera son premier campus en Espagne \u00e0 Malaga"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9cole fran\u00e7aise Essca installera son premier campus en Espagne \u00e0 MalagaLe centre de gestion r\u00e9forme compl\u00e8tement un ancien couvent dans le centre historique de la ville andalouse pour ouvrir un campus de 4200 m\u00e8tres carr\u00e9s. Le centre sera op\u00e9rationnel \u00e0 partir de 2024.<\/p>\n<p class=\"wp-block-paragraph\">Essca arrive \u00e0 Malaga Malaga est \u00e0 la mode. L&rsquo;\u00e9cole de commerce fran\u00e7aise Essca a choisi la capitale de la Costa del Sol pour implanter son premier campus en Espagne. Essca va s&rsquo;installer dans un ancien couvent du centre historique de Malaga. La propri\u00e9t\u00e9 sera enti\u00e8rement r\u00e9nov\u00e9e pour abriter les installations de l&rsquo;\u00e9cole de commerce. <\/p>\n<p class=\"wp-block-paragraph\">Il s&rsquo;agit d&rsquo;un b\u00e2timent de 4 200 m\u00e8tres carr\u00e9s, qui sera d\u00e9sormais mis \u00e0 jour pour qu&rsquo;Essca puisse l&rsquo;occuper avec un contrat de location \u00e0 partir de 2024. \u00ab\u00a0Nous avions pour mandat de pr\u00e9senter des propri\u00e9t\u00e9s potentielles dans des villes du sud de l&rsquo;Espagne, comme Valence, S\u00e9ville ou M\u00e1laga \u00bb, explique Mauricio Pedraza, consultant TTS\/Parella, qui a conseill\u00e9 l&rsquo;\u00e9cole fran\u00e7aise sur cette op\u00e9ration. <\/p>\n<p class=\"wp-block-paragraph\">La qualit\u00e9 de vie de Malaga et son attractivit\u00e9 en tant que centre de d\u00e9veloppement des affaires qu&rsquo;elle a atteint ces derni\u00e8res ann\u00e9es ont conduit Essca \u00e0 miser enfin sur ce lieu pour d\u00e9barquer son offre d&rsquo;information sur le march\u00e9 espagnol. <\/p>\n<p class=\"wp-block-paragraph\">Ainsi, l&rsquo;\u00e9cole de management cherche \u00e0 attirer sur son nouveau campus \u00e0 la fois des \u00e9tudiants locaux et des \u00e9tudiants fran\u00e7ais en immersion en Espagne. L&rsquo;Essca compte huit campus dans le monde, offrant ses programmes et dipl\u00f4mes en gestion d&rsquo;entreprise \u00e0 plus de 7 000 \u00e9tudiants Fond\u00e9e en 1909 \u00e0 Angers, elle compte huit campus offrant des programmes et dipl\u00f4mes en gestion d&rsquo;entreprise \u00e0 une communaut\u00e9 de plus de 7 000 \u00e9tudiants et 460 enseignants et administratifs. <\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;arriv\u00e9e d&rsquo;Essca \u00e0 Malaga confirme le pouvoir d&rsquo;attraction que la ville a g\u00e9n\u00e9r\u00e9 ces derni\u00e8res ann\u00e9es. La place M\u00e9diterran\u00e9e affiche un taux d&rsquo;occupation \u00e9lev\u00e9 de ses immeubles de bureaux et son taux de vacance est inf\u00e9rieur \u00e0 5 %. Dans le cas du centre historique, la disponibilit\u00e9 des bureaux est inf\u00e9rieure \u00e0 2 %. Le quartier repr\u00e9sente \u00e9galement le principal quartier d&rsquo;affaires de la ville, la Calle Larios \u00e9tant l&rsquo;axe principal avec des loyers de 18 euros par m\u00e8tre carr\u00e9 par mois. <\/p>\n<p class=\"wp-block-paragraph\">Le dynamisme se traduit clairement dans un march\u00e9 r\u00e9sidentiel en plein essor. Sur les 70 000 logements neufs qui seront vendus cette ann\u00e9e sur l&rsquo;ensemble du march\u00e9 espagnol, 10,6% se trouveront \u00e0 Malaga, se classant deuxi\u00e8me apr\u00e8s Madrid (15,8%) et devant Barcelone (9,2%), selon les donn\u00e9es de Colliers . En effet, des quatre grands march\u00e9s r\u00e9sidentiels (Madrid, Barcelone, Valence et Malaga), la ville andalouse est celle qui s&rsquo;en sort le mieux avec un taux d&rsquo;absorption de 113,5 %. En d&rsquo;autres termes, cette ann\u00e9e \u00e0 Malaga, beaucoup plus de maisons ont \u00e9t\u00e9 vendues qu&rsquo;elles n&rsquo;ont \u00e9t\u00e9 produites<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9cole fran\u00e7aise Essca installera son premier campus en Espagne \u00e0 MalagaLe centre de gestion r\u00e9forme compl\u00e8tement un ancien couvent dans le centre historique de la ville andalouse pour ouvrir un campus de 4200 m\u00e8tres carr\u00e9s. Le centre sera op\u00e9rationnel \u00e0 partir de 2024. Essca arrive \u00e0 Malaga Malaga est \u00e0 la mode. L&rsquo;\u00e9cole de commerce [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":25399,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,5089,4440],"tags":[],"class_list":["post-69464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-mag-communaute","category-networking"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/69464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=69464"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/69464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/25399"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=69464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=69464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=69464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}