{"id":68972,"date":"2026-03-08T18:08:47","date_gmt":"2026-03-08T18:08:47","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/le-fonds-eqt-etudie-une-introduction-en-bourse-du-portail-idealista-2\/"},"modified":"2026-08-30T05:07:01","modified_gmt":"2026-08-30T05:07:01","slug":"le-fonds-eqt-etudie-une-introduction-en-bourse-du-portail-idealista-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/le-fonds-eqt-etudie-une-introduction-en-bourse-du-portail-idealista-2\/","title":{"rendered":"Le fonds EQT \u00e9tudie une introduction en bourse du portail Idealista"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>Le gestionnaire de fonds su\u00e9dois propose \u00e0 la direction de l&rsquo;entreprise de la c\u00e9der en faisant entrer de nouveaux actionnaires ou en la pla\u00e7ant \u00e9ventuellement sur le march\u00e9 des capitaux.<\/em><\/p>\n<p class=\"wp-block-paragraph\">Des changements se profilent \u00e0 l&rsquo;horizon chez Idealista. EQT Partners, Apax Partners et Oakley Capital, les trois fonds propri\u00e9taires du portail de vente et d&rsquo;achat de biens immobiliers, \u00e9tudient diff\u00e9rentes strat\u00e9gies pour la vente de l&rsquo;entreprise, y compris une introduction en bourse, selon El Economista. <\/p>\n<p class=\"wp-block-paragraph\">Bien qu&rsquo;aucune d\u00e9cision n&rsquo;ait encore \u00e9t\u00e9 prise \u00e0 ce sujet, selon le journal, le gestionnaire de fonds su\u00e9dois EQT, qui d\u00e9tient une participation majoritaire dans le groupe, a d\u00e9j\u00e0 pris <strong>contact avec Jes\u00fas Encinar, fondateur et PDG d&rsquo;Idealista, afin d&rsquo;explorer les diff\u00e9rentes possibilit\u00e9s<\/strong>. <\/p>\n<p class=\"wp-block-paragraph\">Parmi les possibilit\u00e9s envisag\u00e9es, il y a l&rsquo;entr\u00e9e de nouveaux actionnaires qui prendraient le relais des actionnaires actuels ou, si la situation du march\u00e9 le permet, l&rsquo;\u00e9tude d&rsquo;une \u00e9ventuelle introduction en bourse. D&rsquo;autres portails similaires, tels que Rightmove, le leader britannique, ont suivi la strat\u00e9gie de l&rsquo;introduction en bourse. <\/p>\n<p class=\"wp-block-paragraph\">Bien qu&rsquo;en principe l&rsquo;<strong>op\u00e9ration prenne la forme d&rsquo;un d\u00e9sinvestissement de la part d&rsquo;EQT, il est \u00e9galement possible qu&rsquo;elle reste actionnaire<\/strong> avec une participation moindre que celle qu&rsquo;elle d\u00e9tient actuellement.<\/p>\n<p><strong>Idealista est contr\u00f4l\u00e9e par les fonds EQT, Apax et Oakley, ainsi que par l&rsquo;\u00e9quipe de direction dirig\u00e9e par les fr\u00e8res Encinar<\/strong> <\/p>\n<p>La derni\u00e8re transaction d&rsquo;Idealista remonte \u00e0 2001, lorsque Apax Partners a rachet\u00e9 17% d&rsquo;EQT pour 250 millions d&rsquo;euros. \u00c0 l&rsquo;\u00e9poque, <strong>la transaction valorisait 100% d&rsquo;Idealista \u00e0 1,4 milliard d&rsquo;euros<\/strong>. <\/p>\n<p class=\"wp-block-paragraph\">Presque parall\u00e8lement au r\u00e9investissement d&rsquo;Apax, une autre soci\u00e9t\u00e9 britannique de capital-investissement, Oakley Capital, a pris une participation de 1% dans Idealista pour 175 millions d&rsquo;euros. Depuis lors, les deux fonds partagent le capital avec les actionnaires majoritaires d&rsquo;Idealista: l&rsquo;\u00e9quipe de direction, dirig\u00e9e par les fr\u00e8res Encinar, et la soci\u00e9t\u00e9 de gestion EQT, par l&rsquo;interm\u00e9diaire de son v\u00e9hicule EQT Fund IX. <\/p>\n<p class=\"wp-block-paragraph\">Fond\u00e9e en 2000, au plus fort du boom des dotcoms, Idealista est n\u00e9e comme une start-up dans le secteur de la publicit\u00e9 immobili\u00e8re pour concurrencer les portails de presse et des entreprises telles que P\u00e1ginas Amarillas. Elle est actuellement la premi\u00e8re plateforme en Espagne et au Portugal. De plus, suite \u00e0 l&rsquo;acquisition de la soci\u00e9t\u00e9 italienne Casa.it, elle est \u00e9galement en t\u00eate de l&rsquo;activit\u00e9 en Italie.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gestionnaire de fonds su\u00e9dois propose \u00e0 la direction de l&rsquo;entreprise de la c\u00e9der en faisant entrer de nouveaux actionnaires ou en la pla\u00e7ant \u00e9ventuellement sur le march\u00e9 des capitaux. Des changements se profilent \u00e0 l&rsquo;horizon chez Idealista. EQT Partners, Apax Partners et Oakley Capital, les trois fonds propri\u00e9taires du portail de vente et d&rsquo;achat [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":23895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[],"class_list":["post-68972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=68972"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/23895"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=68972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=68972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=68972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}