{"id":68945,"date":"2026-03-08T17:50:41","date_gmt":"2026-03-08T17:50:41","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/les-premiers-taxis-aeriens-espagnols-voleront-aux-baleares-2\/"},"modified":"2026-08-30T04:04:08","modified_gmt":"2026-08-30T04:04:08","slug":"les-premiers-taxis-aeriens-espagnols-voleront-aux-baleares-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/les-premiers-taxis-aeriens-espagnols-voleront-aux-baleares-2\/","title":{"rendered":"Les premiers taxis a\u00e9riens espagnols voleront aux Bal\u00e9ares"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>Les premiers taxis a\u00e9riens espagnols commenceront \u00e0 voler en juin prochain dans les \u00eeles Bal\u00e9ares gr\u00e2ce \u00e0 la <strong>plateforme de r\u00e9servation num\u00e9rique <\/strong>NextNorth, qui a d\u00e9j\u00e0 pr\u00e9sent\u00e9 des v\u00e9hicules \u00e9lectriques lors de la Coupe du monde 2022 au Qatar. Elle se pr\u00e9pare maintenant \u00e0 introduire ses solutions de mobilit\u00e9 a\u00e9rienne pour les passagers des \u00eeles au d\u00e9but de la haute saison touristique.<\/em><\/p>\n<p class=\"wp-block-paragraph\">La soci\u00e9t\u00e9 a expliqu\u00e9 qu&rsquo;elle cherchait \u00e0 devenir \u00ab\u00a0l&rsquo;une des entreprises leaders dans la nouvelle aviation du dernier kilom\u00e8tre\u00a0\u00bb. \u00c0 cette fin, elle offrira au public des moyens de transport permettant \u00ab\u00a0des gains de temps<strong> allant jusqu&rsquo;\u00e0 80% <\/strong>sur les vols intra-\u00eeles et inter-\u00eeles\u00a0\u00bb, a d\u00e9clar\u00e9 la soci\u00e9t\u00e9 dans un communiqu\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">Selon la soci\u00e9t\u00e9, l&rsquo;objectif de NextNorth est d&rsquo;offrir une \u00ab\u00a0meilleure accessibilit\u00e9\u00a0\u00bb \u00e0 l&rsquo;aviation et de pr\u00e9parer l&rsquo;adoption d&rsquo;avions innovants eVTOL (Electric Vertical Take Off and Landing), qui d\u00e9collent et atterrissent \u00e0 la verticale et utilisent des \u00e9nergies propres. \u00c0 cet \u00e9gard, la marque pr\u00e9cise qu&rsquo;il s&rsquo;agit d&rsquo;une alternative de transport plus durable que les formes traditionnelles.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Dans un premier temps avec des h\u00e9licopt\u00e8res<\/strong><\/p>\n<p class=\"wp-block-paragraph\">Ainsi, cet \u00e9t\u00e9, l&rsquo;entreprise <strong>commencera \u00e0 op\u00e9rer temporairement<\/strong> avec des h\u00e9licopt\u00e8res pour d\u00e9tecter les meilleurs itin\u00e9raires et emplacements et, plus tard, pourra op\u00e9rer avec des avions \u00e9lectriques et silencieux qui \u00ab\u00a0r\u00e9duiront la friction du voyage\u00a0\u00bb en offrant une alternative de mobilit\u00e9 \u00e0 certains itin\u00e9raires terrestres et maritimes, atteignant des endroits o\u00f9 d&rsquo;autres moyens de transport ne peuvent pas aller.<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;engagement de NextNorth dans cette nouvelle fa\u00e7on de voyager est bas\u00e9 sur la technologie, l&rsquo;exp\u00e9rience client et l&rsquo;engagement pour l&rsquo;environnement \u00e0 travers l&rsquo;aviation du dernier kilom\u00e8tre, comme l&rsquo;a soulign\u00e9 l&rsquo;entreprise. Elle consid\u00e8re \u00e9galement que <strong>les vols seront d\u00e9mocratis\u00e9s<\/strong> gr\u00e2ce au fait que l&rsquo;utilisateur pourra choisir un ou plusieurs si\u00e8ges sur un trajet donn\u00e9.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les premiers taxis a\u00e9riens espagnols commenceront \u00e0 voler en juin prochain dans les \u00eeles Bal\u00e9ares gr\u00e2ce \u00e0 la plateforme de r\u00e9servation num\u00e9rique NextNorth, qui a d\u00e9j\u00e0 pr\u00e9sent\u00e9 des v\u00e9hicules \u00e9lectriques lors de la Coupe du monde 2022 au Qatar. Elle se pr\u00e9pare maintenant \u00e0 introduire ses solutions de mobilit\u00e9 a\u00e9rienne pour les passagers des \u00eeles [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":23800,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,5089],"tags":[],"class_list":["post-68945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-mag-communaute"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=68945"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/23800"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=68945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=68945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=68945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}