{"id":68942,"date":"2026-03-08T17:50:24","date_gmt":"2026-03-08T17:50:24","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/stage-chef-de-projet-wordpress-et-ai-madrid-2\/"},"modified":"2026-08-30T04:04:02","modified_gmt":"2026-08-30T04:04:02","slug":"stage-chef-de-projet-wordpress-et-ai-madrid-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/stage-chef-de-projet-wordpress-et-ai-madrid-2\/","title":{"rendered":"Stage Chef de projet WordPress et AI Madrid"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">Depuis 18 ans, Le Courrier d&rsquo;Espagne est la 1\u00e8re source d&rsquo;information sur l&rsquo;immobilier en Espagne. Dans le cadre de son d\u00e9veloppement et de la mise en place de nouveaux sites annexes, le m\u00e9dia recherche un stagiaire sp\u00e9cialiste en r\u00e9seaux et wordpress et qui d\u00e9montre un grand int\u00e9r\u00eat pour les AI.<\/p>\n<p class=\"wp-block-paragraph\">Mission:<\/p>\n<ul class=\"wp-block-list\">\n<li>Veille technologique &amp; suggestion de nouveaux outils<\/li>\n<li>Gestion des nouveaux plugin du site wordpress<\/li>\n<li>Recherche et utilisation d&rsquo;AI pour le site <\/li>\n<li>Optimization de la presence digitale<\/li>\n<li>Gestion des serveurs.<\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">Dur\u00e9e du stage: 6 mois minimum \u00e0 partir de juillet ou septembre<\/p>\n<p class=\"wp-block-paragraph\">R\u00e9mun\u00e9ration: fixe selon experience<\/p>\n<p class=\"wp-block-paragraph\">Exp\u00e9rience claire et wordpress et codage de site. Il n&rsquo;est pas n\u00e9cessaire de parler espagnol. Mais ce stage peut-\u00eatre une bonne occasion de l&rsquo;apprendre.<\/p>\n<p class=\"wp-block-paragraph\">Bureaux en plein centre de Madrid. Site: lecourrier.es<\/p>\n<p class=\"wp-block-paragraph\">Bac + 2,3 ou 4- Ecole d&rsquo;ing\u00e9nieurs ou \u00e9quivalent. Ouverts aux autodidactes de n&rsquo;importe quelle universit\u00e9 ou \u00e9cole. <\/p>\n<p class=\"wp-block-paragraph\">Candidature: cv + lettre \u00e0: <a href=\"mailto:com.lecourrier@gmail.com\">com.lecourrier@gmail.com<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis 18 ans, Le Courrier d&rsquo;Espagne est la 1\u00e8re source d&rsquo;information sur l&rsquo;immobilier en Espagne. Dans le cadre de son d\u00e9veloppement et de la mise en place de nouveaux sites annexes, le m\u00e9dia recherche un stagiaire sp\u00e9cialiste en r\u00e9seaux et wordpress et qui d\u00e9montre un grand int\u00e9r\u00eat pour les AI. Mission: Veille technologique &amp; suggestion [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":68943,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[273],"tags":[],"class_list":["post-68942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jobs-stages"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=68942"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/68943"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=68942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=68942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=68942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}