{"id":68941,"date":"2026-03-08T17:50:18","date_gmt":"2026-03-08T17:50:18","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/le-plus-grand-elevage-de-crevettes-en-interieur-du-monde-est-medina-del-campo-valladolid-2\/"},"modified":"2026-08-30T04:03:59","modified_gmt":"2026-08-30T04:03:59","slug":"le-plus-grand-elevage-de-crevettes-en-interieur-du-monde-est-medina-del-campo-valladolid-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/le-plus-grand-elevage-de-crevettes-en-interieur-du-monde-est-medina-del-campo-valladolid-2\/","title":{"rendered":"Le plus grand \u00e9levage de crevettes en int\u00e9rieur du monde est\u2026 Medina del Campo (Valladolid)"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">On imagine qu&rsquo;un village de Valladolid pourrait abriter un ossuaire, et beaucoup de c\u00e9r\u00e9ales dans les vastes champs. On pense aussi \u00e0 l&rsquo;architecture romane, mais on n&rsquo;imagine pas qu&rsquo;\u00e0 c\u00f4t\u00e9 de Medina del Campo se trouve le plus grand \u00e9levage de crevettes en int\u00e9rieur du monde. Surprenant, n&rsquo;est-ce pas ?<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;entreprise Noray Seafood y poss\u00e8de ses installations et, de l&rsquo;ext\u00e9rieur, rien ne laisse supposer que les crevettes sont \u00e9lev\u00e9es dans des bassins dans ce terrain vague\u2026 Il s&rsquo;agit d&rsquo;un b\u00e2timent (un autre est en cours de construction juste \u00e0 c\u00f4t\u00e9, signe que l&rsquo;entreprise se porte bien) qui pourrait bien abriter n&rsquo;importe quoi d&rsquo;autre, car vous en conviendrez : des crevettes dans la mer et non dans la campagne castillane. Pourquoi ici ? \u00ab\u00a0Nous sommes \u00e0 Medina del Campo parce que c&rsquo;est un point strat\u00e9gique d&rsquo;un point de vue logistique. Madrid n&rsquo;est pas loin, ni le nord\u00a0\u00bb, explique <strong>Paula Esteban, directrice de la qualit\u00e9 et de la durabilit\u00e9 de la marque<\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">Ainsi, au milieu des champs de Castille et \u00e0 c\u00f4t\u00e9 d&rsquo;une ville qui fut autrefois un moteur \u00e9conomique (au XVIe si\u00e8cle, la ville de Valladolid \u00e9tait l&rsquo;un des principaux centres \u00e9conomiques du pays, avec une projection internationale gr\u00e2ce \u00e0 sa laine, ses textiles, ses \u0153uvres d&rsquo;art, ses livres\u2026), on \u00e9l\u00e8ve des crevettes locales dont la saveur et la texture n&rsquo;ont rien \u00e0 envier \u00e0 celles des crevettes de mer. Dans 24 bassins d&rsquo;eau sal\u00e9e (le nouveau b\u00e2timent en abritera autant \u00e0 la fin des travaux), qu&rsquo;ils salent et conditionnent eux-m\u00eames pour l&rsquo;\u00e9levage des petites b\u00eates. Les bassins, dans un environnement sombre et tropical, sont souterrains : \u00ab\u00a0Le fait qu&rsquo;ils soient souterrains est un avantage car la g\u00e9othermie est l&rsquo;isolant et maintient la temp\u00e9rature, qui doit \u00eatre d&rsquo;environ 29 degr\u00e9s\u00a0\u00bb, explique-t-il. Les \u00e9chassiers et les filets ont pris possession de cette partie de la campagne castillane dans ce qui est la premi\u00e8re ferme d&rsquo;\u00e9levage de crevettes en int\u00e9rieur au monde.<\/p>\n<p class=\"wp-block-paragraph\">Noray, nom donn\u00e9 au bollard auquel sont accroch\u00e9s les bateaux \u00e0 leur arriv\u00e9e au port, est l\u00e0 depuis 2013. \u00ab\u00a0Plus de 60% du personnel est originaire de Medina del Campo\u00a0\u00bb, pr\u00e9cise Esteban. Et nous ne doutons pas que beaucoup d&rsquo;autres sont d\u00e9sireux de venir travailler : en une demi-heure que nous partageons avec la r\u00e9ceptionniste, nous voyons plusieurs personnes venir d\u00e9poser leur CV, ce qui explique pourquoi l&rsquo;entreprise est un moteur de la r\u00e9gion en termes d&#8217;emploi. Mais ils ne viennent pas que des environs : ils ont m\u00eame un employ\u00e9 qui est venu travailler de Madagascar\u2026<\/p>\n<p><strong>Projet innovant<\/strong><\/p>\n<p>Quels ont \u00e9t\u00e9 les avantages et les inconv\u00e9nients de cette implantation ? \u00ab\u00a0Lorsque le projet a \u00e9t\u00e9 port\u00e9 en Espagne au niveau national, l&rsquo;aquaculture n&rsquo;\u00e9tait pas \u00e9tablie. L&rsquo;installation d&rsquo;une ferme d&rsquo;\u00e9levage de crevettes ici impliquait de pr\u00e9senter un projet totalement innovant \u00e0 toutes les autorit\u00e9s, sanitaires, locales\u2026 et au march\u00e9 en g\u00e9n\u00e9ral. La prise en compte de ce mod\u00e8le \u00e9conomique a \u00e9t\u00e9 compliqu\u00e9e. Mais il est vrai qu&rsquo;au niveau strat\u00e9gique et au niveau de la production, il n&rsquo;y a pas eu de probl\u00e8me d\u00e8s le d\u00e9part. Aujourd&rsquo;hui, nous sommes une trentaine de travailleurs\u00a0\u00bb, explique le responsable de la qualit\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">Ainsi, l&rsquo;une des strat\u00e9gies de l&rsquo;entreprise est d&#8217;embaucher des profils locaux : \u00ab\u00a0C&rsquo;est l&rsquo;une des strat\u00e9gies de Noray, pour promouvoir le d\u00e9veloppement de l&rsquo;\u00e9conomie locale et la fixation de la population, en particulier en Castille, o\u00f9 plus de 40% des villages sont d\u00e9peupl\u00e9s. En plus de cette politique, le r\u00f4le des femmes est crucial, essentiellement parce que le d\u00e9partement charg\u00e9 de l&rsquo;\u00e9levage des premiers stades de la vie des crevettes est occup\u00e9 \u00e0 100% par des femmes. Nous repr\u00e9sentons 39% du personnel et nous avons derri\u00e8re nous des d\u00e9partements importants et vitaux\u00a0\u00bb, dit-elle.<\/p>\n<p><strong>Fournisseurs locaux<br \/><\/strong><br \/>Non seulement le personnel est originaire de la r\u00e9gion, mais aussi les fournisseurs : ceux qui fabriquent les emballages, les v\u00eatements du personnel, les services de nettoyage\u2026 Ils ont \u00e9galement trouv\u00e9 des clients dans cet environnement, comme le restaurant M\u00f3naco, situ\u00e9 sur la belle place de Medina del Campo, qui sert ses crevettes sous diff\u00e9rentes pr\u00e9sentations et qui devrait \u00eatre un must pour tous les gourmands\u2026<\/p>\n<p class=\"wp-block-paragraph\">Noray se vend en Castille et L\u00e9on, \u00e0 Madrid, dans les Asturies, au Pays basque\u2026 En dehors de nos fronti\u00e8res, les crevettes de Valladolid se retrouvent en Norv\u00e8ge (le fondateur de l&rsquo;entreprise est originaire de ce pays pour une bonne raison), en Autriche, en France, \u00e0 Singapour\u2026<\/p>\n<p class=\"wp-block-paragraph\"><strong>Ils produisent environ 50 millions de tonnes par an<\/strong>, mais ils ont l&rsquo;intention de doubler la production de cette ann\u00e9e et de la multiplier par 5 dans les prochaines ann\u00e9es. Elle consacre plus de 10 millions d&rsquo;euros \u00e0 la R&amp;D&amp;I.<\/p>\n<p class=\"wp-block-paragraph\">Un autre \u00e9l\u00e9ment qui rend ces installations uniques est leur mod\u00e8le de production durable : elles disposent de m\u00e9canismes de recyclage de l&rsquo;eau, consomment peu d&rsquo;\u00e9nergie et ne produisent aucun d\u00e9chet. \u00ab\u00a0Le projet est bas\u00e9 sur la durabilit\u00e9 pour plusieurs raisons. La premi\u00e8re est la politique d&rsquo;utilisation des mati\u00e8res premi\u00e8res telles que l&rsquo;eau que nous conditionnons, que nous utilisons et dont la strat\u00e9gie de production est bas\u00e9e sur la r\u00e9utilisation de cette eau. Le deuxi\u00e8me pilier fondamental de la durabilit\u00e9 est notre approvisionnement en \u00e9nergie. 100 % de l&rsquo;\u00e9nergie \u00e9lectrique que nous consommons est d&rsquo;origine renouvelable. Enfin, le troisi\u00e8me pilier de la durabilit\u00e9 est l&rsquo;utilisation des d\u00e9chets que nous produisons\u00a0\u00bb, conclut Esteban.<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;ann\u00e9e derni\u00e8re, l&rsquo;entreprise a remport\u00e9 <strong>le prix de la p\u00eache et de la production aquacole d\u00e9cern\u00e9 par le minist\u00e8re de l&rsquo;agriculture, de la p\u00eache et de l&rsquo;alimentation<\/strong>.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/langostinos_01-1024x535.jpeg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/langostinos_02-1024x535.jpeg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/langostinos_03-1-1024x535.jpeg\"><\/figure><figcaption class=\"blocks-gallery-caption wp-element-caption\"><em>Idealista<\/em><\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On imagine qu&rsquo;un village de Valladolid pourrait abriter un ossuaire, et beaucoup de c\u00e9r\u00e9ales dans les vastes champs. On pense aussi \u00e0 l&rsquo;architecture romane, mais on n&rsquo;imagine pas qu&rsquo;\u00e0 c\u00f4t\u00e9 de Medina del Campo se trouve le plus grand \u00e9levage de crevettes en int\u00e9rieur du monde. Surprenant, n&rsquo;est-ce pas ? L&rsquo;entreprise Noray Seafood y poss\u00e8de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":23791,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,5089],"tags":[],"class_list":["post-68941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-mag-communaute"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=68941"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/23791"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=68941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=68941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=68941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}