{"id":68931,"date":"2026-03-08T17:40:27","date_gmt":"2026-03-08T17:40:27","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/lhotel-kempinski-de-marbella-est-mis-en-vente-pour-un-minimum-de-60-millions-deuros-2\/"},"modified":"2026-08-30T03:17:16","modified_gmt":"2026-08-30T03:17:16","slug":"lhotel-kempinski-de-marbella-est-mis-en-vente-pour-un-minimum-de-60-millions-deuros-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/lhotel-kempinski-de-marbella-est-mis-en-vente-pour-un-minimum-de-60-millions-deuros-2\/","title":{"rendered":"L&rsquo;h\u00f4tel Kempinski de Marbella est mis en vente pour un minimum de 60 millions d&rsquo;euros"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>Azora et l&rsquo;homme d&rsquo;affaires David Shammon proposent un \u00e9tablissement de 148 chambres et un terrain de golf priv\u00e9, ainsi qu&rsquo;une promenade.<\/em><\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;h\u00f4tel Kempinski de Marbella fait l&rsquo;objet de vives ench\u00e8res. Selon El Confidencial, M. Azora et l&rsquo;homme d&rsquo;affaires David Shammon, propri\u00e9taire du complexe Puente Romano, sont en concurrence pour l&rsquo;acquisition de cet \u00e9tablissement cinq \u00e9toiles de 148 chambres.<\/p>\n<p class=\"wp-block-paragraph\">Le Kempinski Hotel Marbella, propri\u00e9t\u00e9 d&rsquo;une famille suisse, est sur le march\u00e9 pour au moins 60 millions d&rsquo;euros. L&rsquo;\u00e9tablissement dispose notamment d&rsquo;un terrain de golf et d&rsquo;une promenade int\u00e9rieure.<\/p>\n<p class=\"wp-block-paragraph\">Azora, le groupe d&rsquo;investissement de Fernando Gumuzio et Concha Os\u00e1car, s&rsquo;est d\u00e9j\u00e0 int\u00e9ress\u00e9 \u00e0 l&rsquo;h\u00f4tel par le pass\u00e9 et aurait pr\u00e9sent\u00e9 une offre pour l&rsquo;h\u00f4tel. Il en va de m\u00eame pour <strong>David Shamoon, un homme d&rsquo;affaires ayant d&rsquo;importants int\u00e9r\u00eats \u00e0 Marbella<\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">Propri\u00e9taire du Puente Romano, un complexe de plus de 250 chambres et de trois villas sur le mile d&rsquo;or de Marbella, il g\u00e8re \u00e9galement le Marbella Club, un autre des grands h\u00f4tels de la ville de Malaga. <\/p>\n<p><strong>Azora poss\u00e8de d&rsquo;importants investissements h\u00f4teliers, tandis que Shammon poss\u00e8de le complexe Puente Romano et g\u00e8re le Marbella Club<br \/><\/strong><br \/>Azora, pour sa part, a investi 1,2 milliard d&rsquo;euros entre 2014 et 2018 dans l&rsquo;acquisition de 13 mille chambres. De plus, <strong>en 2019, elle a lanc\u00e9 le fonds Azora European Hotel&amp;Lodging, un v\u00e9hicule dot\u00e9 de plus de 800 millions d&rsquo;euros pour investir dans des h\u00f4tels en Europe<\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;int\u00e9r\u00eat de ces deux groupes pour le Kempinski de Marbella intervient \u00e0 un moment o\u00f9 l&rsquo;activit\u00e9 touristique en Espagne conna\u00eet une p\u00e9riode faste. <strong>Des destinations telles que les \u00eeles Bal\u00e9ares, les \u00eeles Canaries et la Costa del Sol sont devenues des zones privil\u00e9gi\u00e9es pour l&rsquo;acquisition d&rsquo;h\u00f4tels par de grands groupes d&rsquo;investissement ou des fonds internationaux<\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">Le secteur de l&rsquo;h\u00f4tellerie a attir\u00e9 des investissements de 3,279 milliards d&rsquo;euros l&rsquo;ann\u00e9e derni\u00e8re, qu&rsquo;il s&rsquo;agisse d&rsquo;h\u00f4tels en exploitation, de propri\u00e9t\u00e9s \u00e0 convertir en h\u00f4tels ou de terrains destin\u00e9s \u00e0 l&rsquo;h\u00f4tellerie. <\/p>\n<p class=\"wp-block-paragraph\"><strong>Au total, 133 h\u00f4tels et 17.754 chambres ont fait l&rsquo;objet de transactions l&rsquo;ann\u00e9e derni\u00e8re, contre 127 h\u00f4tels et 19.043 chambres en 2021<\/strong>. En outre, trente autres actifs ont \u00e9t\u00e9 achet\u00e9s et vendus, y compris des terrains pour le d\u00e9veloppement d&rsquo;h\u00f4tels et des propri\u00e9t\u00e9s pour la conversion d&rsquo;h\u00f4tels. <\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Azora et l&rsquo;homme d&rsquo;affaires David Shammon proposent un \u00e9tablissement de 148 chambres et un terrain de golf priv\u00e9, ainsi qu&rsquo;une promenade. L&rsquo;h\u00f4tel Kempinski de Marbella fait l&rsquo;objet de vives ench\u00e8res. Selon El Confidencial, M. Azora et l&rsquo;homme d&rsquo;affaires David Shammon, propri\u00e9taire du complexe Puente Romano, sont en concurrence pour l&rsquo;acquisition de cet \u00e9tablissement cinq \u00e9toiles [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":23756,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,258],"tags":[],"class_list":["post-68931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-hotels-living"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=68931"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/23756"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=68931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=68931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=68931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}