{"id":68912,"date":"2026-03-08T17:31:01","date_gmt":"2026-03-08T17:31:01","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/la-demande-de-bureaux-a-madrid-chute-de-13-au-premier-trimestre-2\/"},"modified":"2026-07-10T18:17:49","modified_gmt":"2026-07-10T18:17:49","slug":"la-demande-de-bureaux-a-madrid-chute-de-13-au-premier-trimestre-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/la-demande-de-bureaux-a-madrid-chute-de-13-au-premier-trimestre-2\/","title":{"rendered":"La demande de bureaux \u00e0 Madrid chute de 13% au premier trimestre"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>Le centre et le quartier des affaires de la capitale ont repr\u00e9sent\u00e9 62% de la surface contract\u00e9e, selon les donn\u00e9es de la soci\u00e9t\u00e9 de conseil BNP Paribas Real Estate.<\/em><\/p>\n<p class=\"wp-block-paragraph\">Le march\u00e9 des bureaux \u00e0 Madrid conna\u00eet un l\u00e9ger ralentissement. Au cours du premier trimestre, la demande plac\u00e9e s&rsquo;est \u00e9lev\u00e9e \u00e0 115.136 m\u00e8tres carr\u00e9s, soit 13 % de moins qu&rsquo;au cours de la m\u00eame p\u00e9riode l&rsquo;ann\u00e9e derni\u00e8re et 10% de moins qu&rsquo;au quatri\u00e8me trimestre 2022, selon les donn\u00e9es de BNP Paribas Real Estate.<\/p>\n<p class=\"wp-block-paragraph\">La surface moyenne sous contrat au premier trimestre s&rsquo;\u00e9tablit \u00e0 1.189 m\u00b2, soit 11% de plus que la moyenne de 2022. Les transactions les plus remarquables sont la location de neuf mille m\u00e8tres carr\u00e9s dans l&rsquo;immeuble KOI par l&rsquo;Universit\u00e9 Camilo Jos\u00e9 Cela et la location de sept mille m\u00e8tres carr\u00e9s par une soci\u00e9t\u00e9 de production cin\u00e9matographique am\u00e9ricaine dans l&rsquo;immeuble Lacy.<\/p>\n<p class=\"wp-block-paragraph\">En ce qui concerne le comportement de la demande par zone au cours du premier trimestre de l&rsquo;ann\u00e9e, il convient de souligner que les zones centrales et le quartier des affaires (CBD) ont repr\u00e9sent\u00e9 la majeure partie de la surface lou\u00e9e, soit 62% de la demande. La zone centrale a repr\u00e9sent\u00e9 34% des prises en location ce trimestre, avec deux op\u00e9rations de plus de 6.000 m\u00b2. Le CBD, la deuxi\u00e8me zone qui a absorb\u00e9 le plus de demande, a enregistr\u00e9 28% des m\u00e8tres carr\u00e9s sous contrat ce trimestre.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Le loyer moyen sur le march\u00e9 des bureaux de Madrid a augment\u00e9 de 7,8% au cours des douze derniers mois<\/strong><\/p>\n<p class=\"wp-block-paragraph\">La troisi\u00e8me zone, la zone d\u00e9centralis\u00e9e, a absorb\u00e9 21% de la demande du march\u00e9 et 25% des transactions enregistr\u00e9es ce trimestre. Enfin, la p\u00e9riph\u00e9rie a repr\u00e9sent\u00e9 24% des transactions et 17% de la surface sous contrat.<\/p>\n<p class=\"wp-block-paragraph\">Le loyer moyen \u00e0 Madrid est d&rsquo;environ 20,1 euros par m\u00e8tre carr\u00e9 par mois, refl\u00e9tant une augmentation annuelle de 7,8% par rapport au m\u00eame trimestre en 2022. Le loyer <em>prime<\/em> reste \u00e0 36,75 euros par m\u00e8tre carr\u00e9 par mois, tandis que le loyer moyen dans le CBD s&rsquo;\u00e9l\u00e8ve \u00e0 32 euros par m\u00e8tre carr\u00e9 par mois, enregistrant une augmentation annuelle de 12,2%. \u00c0 ce stade, le loyer sign\u00e9 le plus \u00e9lev\u00e9 du trimestre atteint 40 euros par m\u00e8tre carr\u00e9 par mois dans la Torre Serrano, situ\u00e9e au num\u00e9ro 47 de la rue Serrano.<\/p>\n<p class=\"wp-block-paragraph\">Dans la zone centrale, le loyer moyen a diminu\u00e9 par rapport au trimestre pr\u00e9c\u00e9dent pour atteindre 24,3 euros par m\u00e8tre carr\u00e9 par mois et dans la zone d\u00e9centralis\u00e9e, le loyer moyen \u00e9tait de 14,20 euros par m\u00e8tre carr\u00e9 par mois au premier trimestre.<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le centre et le quartier des affaires de la capitale ont repr\u00e9sent\u00e9 62% de la surface contract\u00e9e, selon les donn\u00e9es de la soci\u00e9t\u00e9 de conseil BNP Paribas Real Estate. Le march\u00e9 des bureaux \u00e0 Madrid conna\u00eet un l\u00e9ger ralentissement. Au cours du premier trimestre, la demande plac\u00e9e s&rsquo;est \u00e9lev\u00e9e \u00e0 115.136 m\u00e8tres carr\u00e9s, soit 13 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":23674,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[605,375],"class_list":["post-68912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-bureaux","tag-madrid"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=68912"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/23674"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=68912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=68912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=68912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}