{"id":68889,"date":"2026-03-08T17:21:00","date_gmt":"2026-03-08T17:21:00","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/ikea-renforce-sa-logistique-avec-un-investissement-de-90-millions-deuros-en-deux-ans-2\/"},"modified":"2026-08-30T01:42:07","modified_gmt":"2026-08-30T01:42:07","slug":"ikea-renforce-sa-logistique-avec-un-investissement-de-90-millions-deuros-en-deux-ans-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/ikea-renforce-sa-logistique-avec-un-investissement-de-90-millions-deuros-en-deux-ans-2\/","title":{"rendered":"IKEA renforce sa logistique avec un investissement de 90 millions d&rsquo;euros en deux ans"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>La croissance de l&rsquo;activit\u00e9 et une \u00ab\u00a0pr\u00e9vision d&rsquo;expansion ambitieuse\u00a0\u00bb ont conduit IKEA \u00e0 adapter son r\u00e9seau logistique avec des plans \u00e0 \u00ab\u00a0fort impact\u00a0\u00bb en Espagne.<\/em><\/p>\n<p class=\"wp-block-paragraph\">IKEA pr\u00e9voit d&rsquo;investir 90 millions d&rsquo;euros d&rsquo;ici 2025 pour la transformation de sa logistique, selon <strong>Kristien Nuyts<\/strong>, directeur de Fulfillment et membre du comit\u00e9 de gestion en <strong>Espagne<\/strong>. \u00ab\u00a0Notre activit\u00e9 continue de cro\u00eetre fortement, y compris sur le canal en ligne, et nous allons ouvrir de nouveaux points de contact, de sorte que notre force logistique doit \u00e9voluer avec elle, ce qui se traduit par des plans importants pour notre pr\u00e9sence et nos op\u00e9rations en <strong>Espagne<\/strong>\u00ab\u00a0, a d\u00e9clar\u00e9 Kristien Nuyts.<\/p>\n<p class=\"wp-block-paragraph\">Concr\u00e8tement, <strong>IKEA<\/strong> d\u00e9crit quatre domaines d&rsquo;action allant de l&rsquo;ouverture de nouveaux centres logistiques, comme ceux d\u00e9j\u00e0 annonc\u00e9s \u00e0 <strong>Illescas (Tol\u00e8de)<\/strong> et <strong>Antequera (Malaga)<\/strong> &#8211; avec un investissement de 60 millions d&rsquo;euros -, et un autre \u00e0 <strong>San Sebasti\u00e1n de los Reyes (Madrid)<\/strong> &#8211; 20 millions -, au renforcement de la capacit\u00e9 logistique des magasins eux-m\u00eames, comme cela s&rsquo;est d\u00e9j\u00e0 produit dans 13 de ses grands magasins \u00e0 la suite de projets d&rsquo;ex\u00e9cution. De m\u00eame, certains magasins font office de centres logistiques r\u00e9gionaux, comme c&rsquo;est le cas \u00e0 <strong>Jerez de la Frontera (Cadix)<\/strong>, qui approvisionne toute la r\u00e9gion andalouse, \u00e0 <strong>Saragosse<\/strong>, qui traite \u00e9galement avec <strong>la Navarre <\/strong>et <strong>La Rioja<\/strong>, \u00e0 <strong>Valence<\/strong>, Murcie, et Valladolid, avec l&rsquo;ensemble du march\u00e9 du nord. Dans ce dernier cas, l&rsquo;investissement est de 10 millions d&rsquo;euros. Enfin, parmi ses projets figure \u00e9galement la red\u00e9finition des accords avec les fournisseurs, comme la nouvelle alliance avec <strong>DHL<\/strong> pour la gestion du centre d&rsquo;<strong>Illescas<\/strong>, op\u00e9rationnel depuis mars dernier, qui prend en charge une partie de ses op\u00e9rations en ligne pour l&rsquo;ensemble du territoire national.<\/p>\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Nous devons continuer \u00e0 trouver de meilleures fa\u00e7ons d&rsquo;op\u00e9rer; de cette fa\u00e7on, nous pouvons r\u00e9duire les co\u00fbts et les d\u00e9lais de livraison. D&rsquo;apr\u00e8s nos calculs, cette transformation nous permettra de livrer 80% de la population<strong> espagnole<\/strong> dans un d\u00e9lai maximum de 48 heures. Nos nouveaux points de contact, plus proches et plus accessibles, sont \u00e9galement essentiels, et c&rsquo;est pourquoi nous y investissons. Nous sommes pass\u00e9s \u00e0 environ 80 points de livraison pour les commandes volumineuses et \u00e0 plus de 2.000 points de livraison pour les commandes de colis, et nous continuerons \u00e0 le faire. Nous avons de grands projets pour l&rsquo;<strong>Espagne<\/strong>\u00ab\u00a0, a d\u00e9clar\u00e9 <strong>Kristien Nuyts<\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">Ces plans conduiront \u00e0 la cr\u00e9ation de plus de 450 nouveaux emplois directs au cours de ces deux ann\u00e9es, en plus de la g\u00e9n\u00e9ration d&rsquo;opportunit\u00e9s parmi son pool d&rsquo;entreprises externes, qui est compos\u00e9 de pr\u00e8s de trente grandes entreprises, d&rsquo;autres plus petites et de plates-formes de messagerie.<\/p>\n<p class=\"wp-block-paragraph\">C&rsquo;est cette m\u00eame philosophie qui guide son plan d&rsquo;expansion \u00ab\u00a0ambitieux\u00a0\u00bb, qui pr\u00e9voit l&rsquo;ouverture de plus de 40 nouveaux points de contact cette ann\u00e9e: 12 points de vente de diff\u00e9rents formats et 32 points de livraison des commandes. Un plan qu&rsquo;<strong>IKEA<\/strong> continuera \u00e0 d\u00e9velopper au cours du prochain exercice fiscal, en pr\u00e9voyant de doubler ces points avec l&rsquo;ouverture de 11 points de vente et de 26 points de livraison. Actuellement, l&rsquo;entreprise dispose de cinq formats de points diff\u00e9rents et de plus d&rsquo;une centaine d&#8217;emplacements, auxquels s&rsquo;ajoutent plus de 2.300 points de collecte propres et g\u00e9r\u00e9s par des tiers.<\/p>\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.opea.io\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/Capture-decran-2023-03-30-a-10.04.29-1-1-1024x105.jpg\"><\/a><\/figure>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La croissance de l&rsquo;activit\u00e9 et une \u00ab\u00a0pr\u00e9vision d&rsquo;expansion ambitieuse\u00a0\u00bb ont conduit IKEA \u00e0 adapter son r\u00e9seau logistique avec des plans \u00e0 \u00ab\u00a0fort impact\u00a0\u00bb en Espagne. IKEA pr\u00e9voit d&rsquo;investir 90 millions d&rsquo;euros d&rsquo;ici 2025 pour la transformation de sa logistique, selon Kristien Nuyts, directeur de Fulfillment et membre du comit\u00e9 de gestion en Espagne. \u00ab\u00a0Notre activit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":23605,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,234],"tags":[],"class_list":["post-68889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-logistique-retail"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=68889"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/23605"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=68889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=68889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=68889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}