{"id":68866,"date":"2026-03-08T17:06:16","date_gmt":"2026-03-08T17:06:16","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/le-marche-du-retail-se-prepare-a-une-vague-de-desinvestissement-2\/"},"modified":"2026-08-30T01:09:42","modified_gmt":"2026-08-30T01:09:42","slug":"le-marche-du-retail-se-prepare-a-une-vague-de-desinvestissement-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/le-marche-du-retail-se-prepare-a-une-vague-de-desinvestissement-2\/","title":{"rendered":"Le march\u00e9 du retail se pr\u00e9pare \u00e0 une vague de d\u00e9sinvestissement"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>Les d\u00e9sinvestissements sur le march\u00e9 espagnol de la distribution devraient avoir lieu apr\u00e8s avoir ajust\u00e9 leurs valorisations de 30% depuis 2018, selon EY.<\/em><\/p>\n<p class=\"wp-block-paragraph\">Au cours des derniers mois, le march\u00e9 des centres commerciaux en <strong>Espagne<\/strong> a \u00e9volu\u00e9 positivement, selon les donn\u00e9es du rapport annuel \u00ab\u00a0<strong>The Retail Property Telescope<\/strong>\u00ab\u00a0, pr\u00e9par\u00e9 par l&rsquo;\u00e9quipe Strat\u00e9gie et Transactions d&rsquo;EY.<\/p>\n<p class=\"wp-block-paragraph\">Le rapport indique que, malgr\u00e9 la baisse de confiance des consommateurs due \u00e0 un sc\u00e9nario \u00e9conomique d\u00e9favorable, caract\u00e9ris\u00e9 par une inflation \u00e9lev\u00e9e et des taux d&rsquo;int\u00e9r\u00eat en hausse, les ventes et les entr\u00e9es de projets de <strong>premier ordre<\/strong> se rapprochent des niveaux de 2019 et les d\u00e9passent m\u00eame.<\/p>\n<p class=\"wp-block-paragraph\">En effet, les <strong>centres commerciaux<\/strong> de premier ordre, ceux dont la fr\u00e9quentation annuelle est sup\u00e9rieure \u00e0 6 millions de visiteurs et dont le chiffre d&rsquo;affaires par m2 est sup\u00e9rieur \u00e0 3.500 \u20ac\/an, ont connu une augmentation de 7,7% de leurs loyers bruts au cours du dernier exercice. En outre, ils ont r\u00e9duit leurs remises de 61%, ce qui a entra\u00een\u00e9 une augmentation de 15% des loyers nets au cours des 12 derniers mois.<\/p>\n<p class=\"wp-block-paragraph\">Cette performance positive s&rsquo;est \u00e9galement \u00e9tendue aux centres commerciaux de second rang, dont le chiffre d&rsquo;affaires annuel par m2 se situe entre 2.500 et 3.500 \u20ac. Dans ces centres, les loyers bruts ont augment\u00e9 de 6,6%, tandis que les remises temporaires ont \u00e9t\u00e9 r\u00e9duites de 31%.<\/p>\n<p class=\"wp-block-paragraph\">Cependant, le rapport met en garde contre la n\u00e9cessit\u00e9 de repositionner une grande surface locative actuellement occup\u00e9e par des op\u00e9rateurs du secteur de la mode et des accessoires qui ont de gros probl\u00e8mes de continuit\u00e9 en raison de leur taux d&rsquo;effort \u00e9lev\u00e9. Selon l&rsquo;analyse d&rsquo;<strong>EY<\/strong>, 42% de la surface locative brute des centres commerciaux, occup\u00e9e par des entreprises de mode et d&rsquo;accessoires, d\u00e9passe la demande existante.<\/p>\n<p class=\"wp-block-paragraph\">D&rsquo;o\u00f9 la n\u00e9cessit\u00e9 de repositionner 40% de cet espace pour le transformer en nouvelles cat\u00e9gories commerciales. Parmi les options mises en avant dans le rapport figurent les services d&rsquo;accueil, les bureaux, les centres d&rsquo;\u00e9tude et de recherche et les cr\u00e8ches.<\/p>\n<p class=\"wp-block-paragraph\">\u00c0 cet \u00e9gard, <strong>Javier Garc\u00eda-Mateo<\/strong>, associ\u00e9 responsable de l&rsquo;immobilier dans le secteur Strat\u00e9gie et Transactions d&rsquo;<strong>EY<\/strong>, a soulign\u00e9 \u00ab\u00a0la n\u00e9cessit\u00e9 de reconvertir jusqu&rsquo;\u00e0 un tiers du parc commercial espagnol, en optant pour de nouvelles utilisations qui int\u00e8grent de mani\u00e8re optimale les besoins de la population actuelle. Des r\u00e9gions comme l&rsquo;<strong>Aragon<\/strong>, la <strong>Galice<\/strong>, <strong>Murcie<\/strong> et <strong>Madrid<\/strong> ont une offre exc\u00e9dentaire qui ne sera pas viable \u00e0 moyen terme si les propri\u00e9taires ne s&rsquo;engagent pas \u00e0 se reconvertir et ne conviennent pas de programmes de coop\u00e9ration avec l&rsquo;initiative publique\u00a0\u00bb.<\/p>\n<p class=\"wp-block-paragraph\">En outre, le rapport souligne que le march\u00e9 de l&rsquo;investissement international a connu une forte croissance au cours des 12 derniers mois, atteignant 160 milliards d&rsquo;euros et d\u00e9passant le volume transactionnel enregistr\u00e9 en 2018.<\/p>\n<p class=\"wp-block-paragraph\">\u00ab\u00a0En <strong>Espagne<\/strong>, nous sommes encore loin des 5,8 milliards d&rsquo;euros transig\u00e9s en 2018, des 2,4 milliards d&rsquo;euros \u00e0 peine investis en 2022 et des presque 300 millions d&rsquo;euros transig\u00e9s jusqu&rsquo;\u00e0 pr\u00e9sent en 2023. Cependant, une fois la performance de l&rsquo;immobilier revenue \u00e0 ses niveaux pr\u00e9-pand\u00e9miques, les principaux propri\u00e9taires qui avaient pr\u00e9vu de faire tourner leurs portefeuilles entre 2020 et 2022 consid\u00e8rent qu&rsquo;il n&rsquo;est plus possible d&rsquo;attendre plus longtemps pour d\u00e9sinvestir et pr\u00e9voient de le faire de mani\u00e8re ordonn\u00e9e pour placer environ 7,4 milliards d&rsquo;actifs entre 2023 et 2025\u2033, souligne-t-on chez <strong>EY<\/strong>.<\/p>\n<p class=\"wp-block-paragraph\">Enfin, le rapport indique que les banques espagnoles et \u00e9trang\u00e8res sont dispos\u00e9es \u00e0 refinancer les projets de d\u00e9tail existants dans un sc\u00e9nario de changement de contr\u00f4le, gr\u00e2ce auquel elles peuvent r\u00e9\u00e9quilibrer la rentabilit\u00e9 et le risque qu&rsquo;elles assument actuellement.<\/p>\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.opea.io\/\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/image-8-1-1-1024x105.jpg\"><\/a><\/figure>\n<p class=\"wp-block-paragraph\">\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les d\u00e9sinvestissements sur le march\u00e9 espagnol de la distribution devraient avoir lieu apr\u00e8s avoir ajust\u00e9 leurs valorisations de 30% depuis 2018, selon EY. Au cours des derniers mois, le march\u00e9 des centres commerciaux en Espagne a \u00e9volu\u00e9 positivement, selon les donn\u00e9es du rapport annuel \u00ab\u00a0The Retail Property Telescope\u00ab\u00a0, pr\u00e9par\u00e9 par l&rsquo;\u00e9quipe Strat\u00e9gie et Transactions d&rsquo;EY. [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":23508,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,234],"tags":[],"class_list":["post-68866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-logistique-retail"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=68866"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/68866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/23508"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=68866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=68866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=68866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}