{"id":67851,"date":"2026-03-08T05:51:45","date_gmt":"2026-03-08T05:51:45","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/stage-communication-seo-contenu-madrid-2\/"},"modified":"2026-07-10T06:47:23","modified_gmt":"2026-07-10T06:47:23","slug":"stage-communication-seo-contenu-madrid-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/stage-communication-seo-contenu-madrid-2\/","title":{"rendered":"Stage communication, SEO &#038; contenu Madrid"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">Le Courrier d&rsquo;Espagne propose un stage de communication, copywritting et contenu de 6 mois minimum \u00e0 partir de mai bas\u00e9 dans nos bureaux \u00e0 Madrid, ou stage de c\u00e9sure 6-12 mois.<\/p>\n<p class=\"wp-block-paragraph\">Depuis 20 ans, Le Courrier d&rsquo;Espagne est la premi\u00e8re source d&rsquo;info en fran\u00e7ais sur l&rsquo;Espagne. Mais aussi une plate-forme hispano-fran\u00e7aise de networking et d&rsquo;\u00e9v\u00e9nementiel dans le secteur de l&rsquo;immobilier. De mani\u00e8re r\u00e9guli\u00e8re, le m\u00e9dia lance des projets start-up dans le domaine de l&rsquo;immobilier afin de compl\u00e9ter son offre de communication.<\/p>\n<p class=\"wp-block-paragraph\">Le Courrier se tourne r\u00e9solument vers le secteur de l&rsquo;immobilier avec une nouvelle plate-forme digitale, nous recherchons donc un talent afin de nous aider \u00e0 d\u00e9velopper le contenu de nos plate-formes, faire le suivi du SEO et publier des articles. <\/p>\n<p class=\"wp-block-paragraph\">Profil :<\/p>\n<ul class=\"wp-block-list\">\n<li>Bon niveau espagnol.<\/li>\n<li>Exp\u00e9rience de 4 \u00e0 6 mois minimum dans un service seo ou de communication.\u00a0<\/li>\n<li>Rigoureux, sens des responsabilit\u00e9s, dynamique, enthousiaste et sens de la communication.<\/li>\n<li>Curieux<\/li>\n<li>Autonome et avec la culture du r\u00e9sultat.<\/li>\n<li>Connaissance avanc\u00e9e en wordpress<\/li>\n<li>stage de 4 \u00e0 6 mois \u00e0 partir du 1 mai<\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">R\u00e9mun\u00e9ration : oui et selon exp\u00e9rience<\/p>\n<p class=\"wp-block-paragraph\">Bureaux en plein centre de Madrid, metro Arguelles.<\/p>\n<p class=\"wp-block-paragraph\">Infos :&nbsp;<a href=\"http:\/\/www.lecourrier.es\">lecourrier.es<\/a><\/p>\n<p class=\"wp-block-paragraph\">Candidature : envoyer lettre et cv en espagnol \u00e0:<a href=\"mailto:com.lecourrier@gmail.com\"> <\/a>marketing@lecourrier.es <\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/20230202JR_5636-scaled.jpg\"><\/figure>\n<\/figure>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/smush-webp\/2024\/04\/20230202JR_6074-scaled.jpg.webp\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/20230202JR_5817-scaled.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/20230202JR_5858-scaled.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/20230202JR_5730-scaled.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/20230202JR_5662-scaled.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/womms-valencia-fotos-1.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2024\/04\/WOMMS_019-1024x683.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/gabanasept03.jpg\"><figcaption class=\"wp-element-caption\">Loes d&rsquo;une de ses premi\u00e8res soir\u00e9e WOMms, Le Courrier d&rsquo;Espagne avait offert \u00e0 ses convives plus de 3.000 hu\u00eetres fran\u00e7aise Sorlut au Gabana, en 2007..<\/figcaption><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/womms-valencia-photo-1.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/womms.jpg\"><\/figure>\n<\/figure>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Courrier d&rsquo;Espagne propose un stage de communication, copywritting et contenu de 6 mois minimum \u00e0 partir de mai bas\u00e9 dans nos bureaux \u00e0 Madrid, ou stage de c\u00e9sure 6-12 mois. Depuis 20 ans, Le Courrier d&rsquo;Espagne est la premi\u00e8re source d&rsquo;info en fran\u00e7ais sur l&rsquo;Espagne. Mais aussi une plate-forme hispano-fran\u00e7aise de networking et d&rsquo;\u00e9v\u00e9nementiel [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":20062,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[273],"tags":[],"class_list":["post-67851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jobs-stages"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/67851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=67851"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/67851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/20062"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=67851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=67851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=67851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}