{"id":67799,"date":"2026-03-08T05:26:51","date_gmt":"2026-03-08T05:26:51","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/une-usine-de-dessalement-pour-leconomie-circulaire-a-lloret-de-mar-2\/"},"modified":"2026-08-28T13:21:08","modified_gmt":"2026-08-28T13:21:08","slug":"une-usine-de-dessalement-pour-leconomie-circulaire-a-lloret-de-mar-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/une-usine-de-dessalement-pour-leconomie-circulaire-a-lloret-de-mar-2\/","title":{"rendered":"Une usine de dessalement pour l&rsquo;\u00e9conomie circulaire \u00e0 Lloret de Mar"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">La recherche d&rsquo;initiatives pour parvenir \u00e0 un tourisme durable implique parfois de s&rsquo;adapter \u00e0 des situations difficiles. Et c&rsquo;est le cas de Lloret de Mar, la c\u00e9l\u00e8bre commune de la Costa Brava qui, comme le reste de la Catalogne, s&rsquo;inqui\u00e8te de la <strong>s\u00e9cheresse<\/strong>. Comment relever ce d\u00e9fi lorsque vous devez proposer aux visiteurs des h\u00f4tels avec piscine ? La solution est une usine de dessalement.<\/p>\n<p class=\"wp-block-paragraph\">Le conseiller des services publics de Lloret de Mar, Nino Gonz\u00e1lez, parle de l&rsquo;implication des h\u00f4teliers dans la cristallisation de ce projet, qui est un exemple d&rsquo;\u00e9conomie circulaire et qui, comme il l&rsquo;explique lui-m\u00eame dans cette interview vid\u00e9o, est <strong>d\u00e9j\u00e0 imit\u00e9 par d&rsquo;autres municipalit\u00e9s de la r\u00e9gion.<\/strong><\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;usine de dessalement de Lloret de Mar sera bient\u00f4t une r\u00e9alit\u00e9 et, comme le rappelle \u00e0 juste titre M. Gonz\u00e1lez, elle permettra d&rsquo;<strong>offrir les services attendus par les touristes<\/strong>, de pr\u00e9server la saison touristique et tous les emplois d\u00e9riv\u00e9s de cette industrie. Si la durabilit\u00e9 est associ\u00e9e \u00e0 la survie, elle n&rsquo;est jamais aussi claire que dans le cas pr\u00e9sent.<\/p>\n<p class=\"wp-block-paragraph\">Le conseiller esp\u00e8re que nous apprendrons en tant que soci\u00e9t\u00e9 et que, pour une fois, nous cesserons d&rsquo;affronter les probl\u00e8mes de mani\u00e8re d\u00e9cisive\u00a0<strong>uniquement lorsqu&rsquo;ils se pr\u00e9sentent \u00e0 nous<\/strong>. L&rsquo;eau est une denr\u00e9e rare, comme on le dit toujours, mais en r\u00e9alit\u00e9 c&rsquo;est de l&rsquo;eau douce, car il y en a autant que l&rsquo;on veut dans la mer. Il suffit de la traiter par des m\u00e9thodes telles que l&rsquo;osmose.<\/p>\n<p class=\"wp-block-paragraph\"><i>Source<\/i> : <em><a href=\"https:\/\/www.hosteltur.com\/162584_una-desaladora-para-la-economia-circular-de-lloret-de-mar.html\">Hosteltur<\/a><\/em><\/p>\n<div style=\"height:209px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<p>[mailerlite_form form_id=3]<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La recherche d&rsquo;initiatives pour parvenir \u00e0 un tourisme durable implique parfois de s&rsquo;adapter \u00e0 des situations difficiles. Et c&rsquo;est le cas de Lloret de Mar, la c\u00e9l\u00e8bre commune de la Costa Brava qui, comme le reste de la Catalogne, s&rsquo;inqui\u00e8te de la s\u00e9cheresse. Comment relever ce d\u00e9fi lorsque vous devez proposer aux visiteurs des h\u00f4tels [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":22345,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[5089],"tags":[322,828,829,830],"class_list":["post-67799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mag-communaute","tag-costa-brava","tag-economie-circulaire","tag-lloret-del-mar","tag-tourisme-durable"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/67799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=67799"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/67799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/22345"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=67799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=67799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=67799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}