{"id":67304,"date":"2026-03-08T00:30:21","date_gmt":"2026-03-08T00:30:21","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/iryo-renforce-son-engagement-dans-le-sud-avec-une-nouvelle-ligne-au-depart-de-barcelone\/"},"modified":"2026-08-27T22:04:58","modified_gmt":"2026-08-27T22:04:58","slug":"iryo-renforce-son-engagement-dans-le-sud-avec-une-nouvelle-ligne-au-depart-de-barcelone","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/08\/iryo-renforce-son-engagement-dans-le-sud-avec-une-nouvelle-ligne-au-depart-de-barcelone\/","title":{"rendered":"Iryo renforce son engagement dans le sud avec une nouvelle ligne au d\u00e9part de Barcelone"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>L&rsquo;op\u00e9rateur reprend le mod\u00e8le de la connexion avec S\u00e9ville, qui est op\u00e9rationnelle depuis 2023. Iryo s&rsquo;est engag\u00e9e dans les liaisons transversales entre Barcelone et le corridor sud avec une nouvelle liaison vers Malaga au d\u00e9part de Barcelone, qui sera op\u00e9rationnelle \u00e0 partir de d\u00e9cembre. Il s&rsquo;agira de la 2\u00e8me liaison de ce type que la compagnie exploitera apr\u00e8s celle reliant Barcelone \u00e0 S\u00e9ville, et elle offrira plus de 336.000 si\u00e8ges par an.<\/em><\/p>\n<p class=\"wp-block-paragraph\">\u00c0 partir du 15 d\u00e9cembre, iryo exploitera une nouvelle ligne transversale reliant les villes de Barcelone et Malaga. Il s&rsquo;agit de la 2\u00e8me liaison de la compagnie reliant le nord-ouest au sud de l&rsquo;Espagne, apr\u00e8s celle entre Barcelone et S\u00e9ville, qui sera disponible \u00e0 partir de 2023.<\/p>\n<p class=\"wp-block-paragraph\">Avec 2 fr\u00e9quences par jour -une aller et une retour- 7j\/7, la ligne aura des arr\u00eats \u00e0 Saragosse, Madrid (20 minutes) et Cordoue. Le nombre de si\u00e8ges qu&rsquo;iryo offrira par an pour cette ligne sera de 336.530, reliant les 2 villes en environ <strong>5 heures et 50 minutes<\/strong>. Concr\u00e8tement, le d\u00e9part de Barcelone se fera \u00e0 11 h 50 et l&rsquo;arriv\u00e9e \u00e0 17 h 42, tandis que le d\u00e9part de Malaga se fera \u00e0 11 h 35 et l&rsquo;arriv\u00e9e \u00e0 17 h 37.<\/p>\n<p class=\"wp-block-paragraph\">Christian Ley, directeur commercial d&rsquo;iryo, a d\u00e9clar\u00e9 que la compagnie esp\u00e8re que cette nouvelle liaison sera aussi bien accueillie qu&rsquo;une autre liaison vers S\u00e9ville.<\/p>\n<h2 class=\"wp-block-heading\">Objectif : renforcer la pr\u00e9sence dans le corridor sud<\/h2>\n<p class=\"wp-block-paragraph\">Alors que Ouigo va d\u00e9barquer \u00e0 S\u00e9ville cet automne &#8211; c&rsquo;est le seul corridor o\u00f9 il n&rsquo;est pas encore pr\u00e9sent &#8211; iryo renforce son engagement dans le sud avec cette nouvelle ligne transversale, dans le but de continuer \u00e0 gagner des parts de march\u00e9 avec des liaisons qui lui rapportent de bons chiffres.<\/p>\n<p class=\"wp-block-paragraph\">En effet, apr\u00e8s la lib\u00e9ralisation du transport ferroviaire, iryo a \u00e9t\u00e9 la premi\u00e8re entreprise \u00e0 retirer \u00e0 Renfe son monopole sur la ligne \u00e0 grande vitesse Madrid-S\u00e9ville. Un an apr\u00e8s avoir commenc\u00e9 \u00e0 op\u00e9rer dans le corridor andalou, iryo avait d\u00e9j\u00e0 transport\u00e9 2,4 millions de passagers, avec un taux d&rsquo;occupation de 70% et une part de march\u00e9 de 32%.<\/p>\n<p class=\"wp-block-paragraph\">Au total, jusqu&rsquo;\u00e0 la fin de 2023, l&rsquo;op\u00e9rateur a assur\u00e9 5.000 services avec l&rsquo;Andalousie (2.900 vers S\u00e9ville et 2.100 vers Malaga).<\/p>\n<p class=\"wp-block-paragraph\">Source : <a href=\"https:\/\/www.hosteltur.com\/165475_iryo-refuerza-su-apuesta-por-el-sur-con-una-nueva-ruta-desde-barcelona.html\">Hosteltur<\/a><\/p>\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;op\u00e9rateur reprend le mod\u00e8le de la connexion avec S\u00e9ville, qui est op\u00e9rationnelle depuis 2023. Iryo s&rsquo;est engag\u00e9e dans les liaisons transversales entre Barcelone et le corridor sud avec une nouvelle liaison vers Malaga au d\u00e9part de Barcelone, qui sera op\u00e9rationnelle \u00e0 partir de d\u00e9cembre. Il s&rsquo;agira de la 2\u00e8me liaison de ce type que la [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":63854,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,5089],"tags":[447,4128],"class_list":["post-67304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-mag-communaute","tag-barcelone","tag-iryo"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/67304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=67304"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/67304\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=67304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=67304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=67304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}