{"id":67081,"date":"2026-03-07T21:45:04","date_gmt":"2026-03-07T21:45:04","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/construmat-lance-un-concours-a-lintention-des-jeunes-talents-pour-la-conception-de-son-espace-vip\/"},"modified":"2026-08-27T13:53:11","modified_gmt":"2026-08-27T13:53:11","slug":"construmat-lance-un-concours-a-lintention-des-jeunes-talents-pour-la-conception-de-son-espace-vip","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/construmat-lance-un-concours-a-lintention-des-jeunes-talents-pour-la-conception-de-son-espace-vip\/","title":{"rendered":"Construmat lance un concours \u00e0 l&rsquo;intention des jeunes talents pour la conception de son espace VIP"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">La Plaza VIP Lounge \u00bb, l&rsquo;espace le plus exclusif de Construmat, portera la signature d&rsquo;un jeune talent lors de sa prochaine \u00e9dition, pr\u00e9vue du 20 au 22 mai 2025. Le salon de la construction de la Fira de Barcelona a lanc\u00e9 un concours destin\u00e9 aux \u00e9tudiants et aux professionnels r\u00e9cemment inscrits dans le domaine de l&rsquo;architecture, de l&rsquo;architecture d&rsquo;int\u00e9rieur et du design, dans le but de cr\u00e9er un espace innovant, durable et fonctionnel qui refl\u00e8te les valeurs du secteur.<\/p>\n<p class=\"wp-block-paragraph\">Organis\u00e9 par Construmat en collaboration avec World Wood Future, une entit\u00e9 qui promeut des solutions durables pour la construction, le concours d&rsquo;id\u00e9es pour la conception de \u00ab La Plaza VIP Lounge \u00bb vise \u00e0 stimuler l&rsquo;innovation dans le secteur et \u00e0 promouvoir ses talents \u00e9mergents. \u00c0 cette fin, l&rsquo;initiative cherche \u00e0 impliquer \u00e0 la fois les centres \u00e9ducatifs et les jeunes professionnels, en promouvant de nouvelles id\u00e9es et approches en mati\u00e8re d&rsquo;architecture et de design.<\/p>\n<p class=\"wp-block-paragraph\">La proposition est ouverte aux \u00e9tudiants inscrits pour l&rsquo;ann\u00e9e acad\u00e9mique 2024-25 dans des dipl\u00f4mes d&rsquo;architecture, d&rsquo;architecture technique ou d&rsquo;architecture d&rsquo;int\u00e9rieur, dans des masters et des formations professionnelles sup\u00e9rieures connexes, ainsi qu&rsquo;aux professionnels dipl\u00f4m\u00e9s ou membres d&rsquo;une association professionnelle depuis moins de 2 ans.<\/p>\n<p class=\"wp-block-paragraph\">Les candidats doivent pr\u00e9senter un projet complet comprenant \u00e0 la fois la structure et l&rsquo;am\u00e9nagement int\u00e9rieur, garantissant sa fonctionnalit\u00e9 en tant que lieu de repos et de travail pour les visiteurs VIP de la foire.<\/p>\n<h3 class=\"wp-block-heading\">Un espace polyvalent<\/h3>\n<p class=\"wp-block-paragraph\">Le \u00ab Plaza VIP Lounge \u00bb occupera une surface de pr\u00e8s de 200 m\u00b2, int\u00e9grant un salon pour les orateurs, un espace VIP, un bar et une zone de mise en r\u00e9seau. Il devrait s&rsquo;agir d&rsquo;un espace modulable, adaptable \u00e0 diff\u00e9rents lieux et conditions, tant \u00e0 l&rsquo;int\u00e9rieur qu&rsquo;\u00e0 l&rsquo;ext\u00e9rieur. Il sera \u00e9galement appr\u00e9ci\u00e9 qu&rsquo;il puisse \u00eatre mont\u00e9 et d\u00e9mont\u00e9 rapidement, qu&rsquo;il puisse \u00eatre facilement transport\u00e9 et stock\u00e9, qu&rsquo;il utilise des mat\u00e9riaux durables et sains, et qu&rsquo;il int\u00e8gre des solutions technologiques avanc\u00e9es.<\/p>\n<p class=\"wp-block-paragraph\">Le budget maximum pour l&rsquo;ex\u00e9cution du projet sera de 90.000 euros, comprenant la conception, la certification, le transport et l&rsquo;assemblage et le d\u00e9sassemblage complets. Les projets finalistes seront expos\u00e9s pendant l&rsquo;\u00e9v\u00e9nement et la proposition gagnante recevra un prix de 2.000 euros, en plus d&rsquo;une reconnaissance publique pendant Construmat 2025.<\/p>\n<p class=\"wp-block-paragraph\">La date limite de pr\u00e9sentation des candidatures est fix\u00e9e au 1er d\u00e9cembre 2024, et la d\u00e9cision finale du jury sera annonc\u00e9e le 21 f\u00e9vrier de l&rsquo;ann\u00e9e prochaine.<\/p>\n<h3 class=\"wp-block-heading\">Construmat 2025<\/h3>\n<p class=\"wp-block-paragraph\">Le salon de la construction de Fira de Barcelona pr\u00e9pare d\u00e9j\u00e0 la prochaine \u00e9dition, qui aura lieu du 20 au 22 mai 2025, avec la participation des entreprises les plus innovantes en mati\u00e8re de mat\u00e9riaux, d&rsquo;industrialisation et de durabilit\u00e9, ainsi que de leurs professionnels, dans le but de dynamiser l&rsquo;industrie et de relever ses principaux d\u00e9fis.<\/p>\n<p class=\"wp-block-paragraph\">Parmi les diff\u00e9rentes propositions pr\u00e9vues, le Congr\u00e8s du b\u00e2timent durable sera renforc\u00e9 et son caract\u00e8re international sera renforc\u00e9 en r\u00e9unissant des conf\u00e9renciers de premier plan. Une autre nouveaut\u00e9 sera l&rsquo;Exp\u00e9rience Construmat, un espace o\u00f9 des conf\u00e9rences innovantes seront donn\u00e9es par des entreprises et des organisations sectorielles. Il y aura \u00e9galement une zone de d\u00e9marrage, un forum d&rsquo;investissement et une nouvelle \u00e9dition des Construmat Awards, organis\u00e9e par la Fondation Mies van der Rohe, entre autres activit\u00e9s.<\/p>\n<p class=\"wp-block-paragraph\">Pour en savoir plus et s&rsquo;inscrire, cliquez sur <a href=\"https:\/\/www.construmat.com\/jovenes-talentos\/\">ce lien<\/a>.<\/p>\n<p class=\"wp-block-paragraph\">Barcelone, 18 novembre 2024<br \/>Albert Sas Gimeno<br \/>93 233 23 78<br \/>asas@firabarcelona.com<br \/><a href=\"https:\/\/www.construmat.com\/\">Construmat<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Plaza VIP Lounge \u00bb, l&rsquo;espace le plus exclusif de Construmat, portera la signature d&rsquo;un jeune talent lors de sa prochaine \u00e9dition, pr\u00e9vue du 20 au 22 mai 2025. Le salon de la construction de la Fira de Barcelona a lanc\u00e9 un concours destin\u00e9 aux \u00e9tudiants et aux professionnels r\u00e9cemment inscrits dans le domaine de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":64727,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[4440],"tags":[3258,3691,4235],"class_list":["post-67081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-networking","tag-concours","tag-construmat","tag-jeunes-talents"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/67081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=67081"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/67081\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=67081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=67081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=67081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}