{"id":66999,"date":"2026-03-07T20:35:35","date_gmt":"2026-03-07T20:35:35","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/twin-peaks-capital-investit-80-millions-deuros-dans-un-projet-de-flex-living-a-las-rozas\/"},"modified":"2026-08-27T10:09:43","modified_gmt":"2026-08-27T10:09:43","slug":"twin-peaks-capital-investit-80-millions-deuros-dans-un-projet-de-flex-living-a-las-rozas","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/twin-peaks-capital-investit-80-millions-deuros-dans-un-projet-de-flex-living-a-las-rozas\/","title":{"rendered":"Twin Peaks Capital investit 80 millions d&rsquo;euros dans un projet de \u00ab flex living \u00bb \u00e0 Las Rozas"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">Twin Peaks Capital poursuit sa strat\u00e9gie d&rsquo;expansion dans le secteur r\u00e9sidentiel avec l&rsquo;acquisition de son troisi\u00e8me projet de \u00ab flex living \u00bb en 2024. La soci\u00e9t\u00e9 a affect\u00e9 plus de 80 millions d&rsquo;euros au d\u00e9veloppement de 400 unit\u00e9s de location \u00e0 long terme \u00e0 Las Rozas, consolidant ainsi sa position d&rsquo;acteur cl\u00e9 de ce mod\u00e8le innovant dans la r\u00e9gion de Madrid.<\/p>\n<p class=\"wp-block-paragraph\">Le nouveau projet sera situ\u00e9 sur un terrain constructible de 23 000 m2 \u00e0 seulement 15 minutes du centre de Madrid, gr\u00e2ce \u00e0 sa proximit\u00e9 strat\u00e9gique avec la gare de train de banlieue de Majadahonda. La transaction a \u00e9t\u00e9 conseill\u00e9e par CBRE, Atlas Real Estate et le cabinet d&rsquo;avocats Garrigues.<\/p>\n<h3 class=\"wp-block-heading\">Une vision pour l&rsquo;avenir de Las Rozas<\/h3>\n<p class=\"wp-block-paragraph\">\u00ab Nous sommes ravis de cette acquisition, qui nous permettra d&rsquo;\u00e9largir notre offre de logements flexibles dans l&rsquo;un des quartiers les plus dynamiques de Madrid. Las Rozas combine un cadre tranquille avec des connexions imbattables avec la capitale, ce qui en fait une destination id\u00e9ale pour ceux qui recherchent la qualit\u00e9 de vie et la commodit\u00e9 \u00bb, d\u00e9clare Fernando Rivero de Aguilar, directeur des investissements chez Twin Peaks Capital.<\/p>\n<p class=\"wp-block-paragraph\">Avec ce projet, la soci\u00e9t\u00e9 dispose d\u00e9sormais d&rsquo;un total de plus de 1.200 unit\u00e9s locatives r\u00e9parties entre des projets dans des zones telles que Torrej\u00f3n (450 unit\u00e9s), Valdemar\u00edn (125 unit\u00e9s), Getafe (210 unit\u00e9s) et Las Rozas (430 unit\u00e9s), consolidant ainsi sa position comme l&rsquo;un des principaux acteurs du march\u00e9 de la location r\u00e9sidentielle dans la capitale.<\/p>\n<h3 class=\"wp-block-heading\">\u00ab\u00a0Flex living \u00ab\u00a0, un mod\u00e8le en plein essor<\/h3>\n<p class=\"wp-block-paragraph\">Le concept de \u00ab flex living \u00bb, adopt\u00e9 par Twin Peaks Capital, offre aux r\u00e9sidents une exp\u00e9rience de location avec des options flexibles de court ou long s\u00e9jour. Ces d\u00e9veloppements privil\u00e9gient la commodit\u00e9, les emplacements strat\u00e9giques et les \u00e9quipements qui am\u00e9liorent l&rsquo;exp\u00e9rience des locataires. En outre, le mod\u00e8le est con\u00e7u en mettant l&rsquo;accent sur la durabilit\u00e9 et la vie en communaut\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">Ce nouveau projet \u00e0 Las Rozas marque \u00e9galement le d\u00e9but d&rsquo;une alliance strat\u00e9gique avec GravityCo, une marque internationale de logements flexibles avec une pr\u00e9sence \u00e9tablie \u00e0 Londres. Cette collaboration ouvre de nouvelles opportunit\u00e9s pour GravityCo sur le march\u00e9 espagnol, o\u00f9 elle vise \u00e0 exploiter 2.000 lits d&rsquo;ici 2026.<\/p>\n<h3 class=\"wp-block-heading\">Un partenariat strat\u00e9gique<\/h3>\n<p class=\"wp-block-paragraph\">\u00ab Il s&rsquo;agit du 1er d&rsquo;une s\u00e9rie de d\u00e9veloppements sur lesquels nous avons travaill\u00e9 avec Twin Peaks Capital, et nous sommes ravis d&rsquo;apporter notre expertise en mati\u00e8re de logements flexibles \u00e0 Madrid. La forte demande d&rsquo;options locatives de haute qualit\u00e9 et la communaut\u00e9 internationale dynamique de la ville font de Madrid un march\u00e9 id\u00e9al pour ce mod\u00e8le \u00bb, d\u00e9clare Marta Sauri, associ\u00e9e et responsable de l&rsquo;expansion et des march\u00e9s de capitaux chez GravityCo.<\/p>\n<p class=\"wp-block-paragraph\">Cette collaboration avec Twin Peaks refl\u00e8te notre vision de cr\u00e9er des solutions de logement innovantes et durables dans les principales villes d&rsquo;Europe \u00bb, d\u00e9clare Riccardo Tessaro, PDG de GravityCo. Nous sommes ravis d&rsquo;entrer sur le march\u00e9 madril\u00e8ne et nous sommes impatients d&rsquo;\u00e9tablir GravityCo comme la 1\u00e8re marque de flex living en Europe.<\/p>\n<p class=\"wp-block-paragraph\">Avec l&rsquo;ensemble des avantages qu&rsquo;elle offre, notamment des connexions exceptionnelles, une proximit\u00e9 privil\u00e9gi\u00e9e avec le centre de Madrid et son d\u00e9veloppement croissant en tant que municipalit\u00e9 r\u00e9sidentielle, Las Rozas \u00e9merge comme un point de r\u00e9f\u00e9rence pour le mod\u00e8le de flex living dans la r\u00e9gion. L&rsquo;engagement de Twin Peaks Capital et de GravityCo renforce encore l&rsquo;attractivit\u00e9 de cette zone.<\/p>\n<p class=\"wp-block-paragraph\">Source : <a href=\"https:\/\/www.idealista.com\/news\/inmobiliario\/vivienda\/2024\/12\/23\/825578-twin-peaks-capital-invierte-80-millones-en-un-proyecto-flex-living-en-las-rozas\">Idealista<\/a><\/p>\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Twin Peaks Capital poursuit sa strat\u00e9gie d&rsquo;expansion dans le secteur r\u00e9sidentiel avec l&rsquo;acquisition de son troisi\u00e8me projet de \u00ab flex living \u00bb en 2024. La soci\u00e9t\u00e9 a affect\u00e9 plus de 80 millions d&rsquo;euros au d\u00e9veloppement de 400 unit\u00e9s de location \u00e0 long terme \u00e0 Las Rozas, consolidant ainsi sa position d&rsquo;acteur cl\u00e9 de ce mod\u00e8le [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":65196,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,258],"tags":[],"class_list":["post-66999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-hotels-living"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=66999"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66999\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=66999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=66999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=66999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}