{"id":66976,"date":"2026-03-07T20:20:26","date_gmt":"2026-03-07T20:20:26","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/mujeres-avenir-lance-un-appel-au-leadership-des-femmes-pour-lavenir-des-stim\/"},"modified":"2026-08-27T09:21:56","modified_gmt":"2026-08-27T09:21:56","slug":"mujeres-avenir-lance-un-appel-au-leadership-des-femmes-pour-lavenir-des-stim","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/mujeres-avenir-lance-un-appel-au-leadership-des-femmes-pour-lavenir-des-stim\/","title":{"rendered":"Mujeres Avenir lance un appel au leadership des femmes pour l&rsquo;avenir des STIM"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>4 femmes du monde des STIM ont partag\u00e9 leurs parcours professionnels inspirants, les d\u00e9fis auxquels elles ont \u00e9t\u00e9 confront\u00e9es et les ressources et strat\u00e9gies de leadership qu&rsquo;elles ont utilis\u00e9es pour les surmonter.<\/em><\/p>\n<p class=\"wp-block-paragraph\"><strong>Madrid, 29 janvier 2025.<\/strong> L&rsquo;association d&rsquo;amiti\u00e9 franco-espagnole Mujeres Avenir (<a href=\"http:\/\/www.mujeresavenir.com\">www.mujeresavenir.com<\/a>), qui \u0153uvre \u00e0 la consolidation de la visibilit\u00e9 des femmes dans tous les secteurs de la soci\u00e9t\u00e9 et \u00e0 <strong>l&rsquo;\u00e9galit\u00e9 r\u00e9elle et effective entre les femmes et les hommes<\/strong>, a organis\u00e9 une table ronde intitul\u00e9e \u00ab Female leadership for the future of STEM \u00bb dans les bureaux du cabinet de conseil Forvis Mazars, en collaboration avec son comit\u00e9 de jeunes, avec des femmes cadres des secteurs STEM et automobile, dans le but de <strong>mettre en avant les talents f\u00e9minins dans les postes de direction.<\/strong><\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/20250128JR_0743-scaled.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/20250128JR_0710-scaled.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/20250128JR_0654-scaled.jpg\"><\/figure>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/03\/20250128JR_0549-scaled.jpg\"><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 pr\u00e9sent\u00e9 par <strong>Rebeca \u00c1vila, pr\u00e9sidente ex\u00e9cutive de Mujeres Avenir<\/strong>, qui a expliqu\u00e9 que \u00ab l&rsquo;objectif de la r\u00e9union est de donner de la visibilit\u00e9 au leadership f\u00e9minin en mettant en avant les carri\u00e8res exceptionnelles de femmes dans le monde professionnel, qui sont des r\u00e9f\u00e9rences pour les nouvelles g\u00e9n\u00e9rations \u00bb. Elle a \u00e9galement affirm\u00e9 que \u00ab l<em>e leadership f\u00e9minin, avec ses valeurs et ses traits diff\u00e9rentiels, apporte une vision unique et pr\u00e9cieuse dans le domaine des STIM, en favorisant des environnements de travail plus \u00e9quilibr\u00e9s, collaboratifs, orient\u00e9s vers l&rsquo;action et les r\u00e9sultats <\/em>\u00bb.<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9v\u00e9nement, anim\u00e9 par <em>Luc\u00eda Palop<\/em>, responsable des op\u00e9rations de recrutement chez GT Global Talent, a permis de r\u00e9fl\u00e9chir \u00e0 la mani\u00e8re dont les femmes qui ont r\u00e9ussi dans des domaines fortement masculinis\u00e9s font tomber les barri\u00e8res et apportent de la valeur et des r\u00e9sultats, en \u00e9tant un \u00e9l\u00e9ment essentiel de la r\u00e9ussite des entreprises et du progr\u00e8s de la soci\u00e9t\u00e9.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Marta Bl\u00e1zquez, pr\u00e9sidente de FACONAUTO,<\/strong> a soulign\u00e9 l&rsquo;enrichissement du leadership f\u00e9minin, encourageant les jeunes femmes \u00e0 ne pas se d\u00e9valoriser, \u00e0 croire en leur travail et \u00e0 le d\u00e9fendre, ainsi qu&rsquo;\u00e0 avoir une vision globale et strat\u00e9gique.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Beatriz Arias, directrice de la transformation num\u00e9rique chez DigitalES<\/strong> et auteure du livre El S\u00edndrome de la impostora, a expliqu\u00e9 que \u00ab les femmes n&rsquo;ont pas \u00e0 justifier leur position de leader, car elles viennent d&rsquo;elles-m\u00eames \u00bb. Elle a encourag\u00e9 les jeunes femmes \u00e0 concentrer leur attention et leur \u00e9nergie sur leurs int\u00e9r\u00eats plut\u00f4t que de lutter contre les pr\u00e9jug\u00e9s et les attentes externes. Elle a \u00e9galement d\u00e9crit les sympt\u00f4mes et les strat\u00e9gies pour se d\u00e9fendre contre le syndrome de l&rsquo;imposteur qui, malheureusement et \u00e0 cause des structures, est un probl\u00e8me courant chez les jeunes femmes.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Francisca Rubio, PDG de Gaia-X<\/strong>, a insist\u00e9 sur le fait qu&rsquo;\u00ab il ne faut pas exercer un style de leadership qui n&rsquo;est pas le sien, nous devons tous d\u00e9fendre notre propre caract\u00e8re \u00bb, ainsi que sur le fait que l&rsquo;\u00e9ducation est un outil puissant, \u00ab il faut apprendre et se former en permanence \u00bb, et elle a encourag\u00e9 \u00e0 \u00e9tudier les carri\u00e8res STEM parce qu&rsquo;elles doivent \u00eatre d\u00e9mocratis\u00e9es. Comme strat\u00e9gies suppl\u00e9mentaires pour atteindre le leadership, elle a d\u00e9fendu l&rsquo;importance de s&rsquo;appuyer sur les r\u00e9seaux et les r\u00e9f\u00e9rences des femmes.<\/p>\n<p class=\"wp-block-paragraph\">De m\u00eame, <strong>Celiana Carre\u00f1o, vice-pr\u00e9sidente de la technologie et chef de produit pour l&rsquo;Europe chez Globant<\/strong>, a soulign\u00e9 l&rsquo;importance de \u00ab savoir clairement ce que l&rsquo;on veut, pourquoi et dans quel but on le veut comme guide de travail, parce que faire plus de t\u00e2ches n&rsquo;est pas n\u00e9cessairement mieux \u00bb. Elle a \u00e9galement plaid\u00e9 en faveur de la formation et de l&rsquo;\u00e9panouissement personnel et professionnel, mais aussi du travail sur la visibilit\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">A propos de LA <strong>ASOCIACI\u00d3N DE AMISTAD HISPANO &#8211; FRANCESA MUJERES AVENIR:<\/strong><\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;association est pr\u00e9sid\u00e9e par un bureau dont Rebeca \u00c1vila est pr\u00e9sidente ex\u00e9cutive, ainsi que la pr\u00e9sidente fondatrice, Mar\u00eda Luisa de Contes d&rsquo;Esgranges, trois vice-pr\u00e9sidentes, Beatriz Medina, directrice des relations sociales du groupe LVMH, Anne Viard, associ\u00e9e chez Mazars et Teresa Castillo, qui pr\u00e9side la commission des jeunes au sein de Mujeres Avenir. Pauline Leroyer en est \u00e9galement la secr\u00e9taire g\u00e9n\u00e9rale. Toutes composent le bureau de Mujeres Avenir, qui est l&rsquo;\u00e9quipe de travail qui pilote l&rsquo;association.<\/p>\n<p class=\"wp-block-paragraph\">Communiqu\u00e9 de presse de Mujeres Avenir<br \/><a href=\"https:\/\/mujeresavenir.com\/\"><strong>https:\/\/mujeresavenir.com\/<\/strong><\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>4 femmes du monde des STIM ont partag\u00e9 leurs parcours professionnels inspirants, les d\u00e9fis auxquels elles ont \u00e9t\u00e9 confront\u00e9es et les ressources et strat\u00e9gies de leadership qu&rsquo;elles ont utilis\u00e9es pour les surmonter. Madrid, 29 janvier 2025. L&rsquo;association d&rsquo;amiti\u00e9 franco-espagnole Mujeres Avenir (www.mujeresavenir.com), qui \u0153uvre \u00e0 la consolidation de la visibilit\u00e9 des femmes dans tous les [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":66981,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[5089],"tags":[452],"class_list":["post-66976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mag-communaute","tag-mujeres-avenir"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=66976"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/66981"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=66976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=66976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=66976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}