{"id":66499,"date":"2026-03-07T15:22:38","date_gmt":"2026-03-07T15:22:38","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/le-fonds-autonomy-lance-en-2026-son-projet-residentiel-phare-a-madrid\/"},"modified":"2026-08-26T17:47:35","modified_gmt":"2026-08-26T17:47:35","slug":"le-fonds-autonomy-lance-en-2026-son-projet-residentiel-phare-a-madrid","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/le-fonds-autonomy-lance-en-2026-son-projet-residentiel-phare-a-madrid\/","title":{"rendered":"Le fonds Autonomy lance en 2026 son projet r\u00e9sidentiel phare \u00e0 Madrid"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>La soci\u00e9t\u00e9 de gestion cr\u00e9\u00e9e par l&rsquo;ancien dirigeant de Lehman Brothers, Robert Gibbins, promeut ce projet de transformation urbaine sur l&rsquo;un des rares terrains disponibles \u00e0 proximit\u00e9 du quartier d&rsquo;Arturo Soria, avec lequel elle esp\u00e8re obtenir un rendement de 21,4 %.<\/em><\/p>\n<p class=\"wp-block-paragraph\">Apr\u00e8s des ann\u00e9es de d\u00e9marches administratives, le fonds d&rsquo;investissement Autonomy, cr\u00e9\u00e9 par l&rsquo;ancien dirigeant de Lehman Brothers Robert Gibbins et dirig\u00e9 en Espagne par David Ventoso, a enfin fix\u00e9 la date de lancement de son grand projet phare dans le pays, plus pr\u00e9cis\u00e9ment \u00e0 Madrid : Nuevo San Luis.<\/p>\n<p class=\"wp-block-paragraph\">Il s&rsquo;agit d&rsquo;un projet de r\u00e9g\u00e9n\u00e9ration urbaine situ\u00e9 dans l&rsquo;un des quartiers r\u00e9sidentiels les plus pris\u00e9s de la ville : Hortaleza, \u00e0 quelques m\u00e8tres du quartier hupp\u00e9 d&rsquo;Arturo Soria, \u00e0 c\u00f4t\u00e9 du si\u00e8ge du groupe de m\u00e9dias Unidad Editorial et d&rsquo;importants projets immobiliers d&rsquo;entreprises telles que Metrovacesa (Mesena) et Acciona (son campus d&rsquo;entreprises).<\/p>\n<p class=\"wp-block-paragraph\">Autonomy y a acquis pour 38,75 millions d&rsquo;euros un terrain de 63 518 m\u00e8tres carr\u00e9s qui \u00e9tait rest\u00e9 inexploit\u00e9 pendant des ann\u00e9es et servait en partie de parking. Baptis\u00e9 APE 16-12 Avenida de San Luis-Torrecillas, le site comprend plusieurs propri\u00e9t\u00e9s, dont cinq seront c\u00e9d\u00e9es \u00e0 la mairie de Madrid dans le cadre des cessions obligatoires correspondant \u00e0 tout projet d&rsquo;urbanisme dans la ville. Elles seront destin\u00e9es \u00e0 des r\u00e9seaux locaux, tels qu&rsquo;un centre d&rsquo;\u00e9quipement social, et deux d&rsquo;entre elles seront destin\u00e9es \u00e0 des logements.<\/p>\n<p class=\"wp-block-paragraph\">Autonomy, l&rsquo;un des rares investisseurs institutionnels \u00e0 avoir mis\u00e9 sur le d\u00e9veloppement urbain dans le pays, a acquis ce terrain pour environ 39 millions d&rsquo;euros.<\/p>\n<p class=\"wp-block-paragraph\">Le projet pr\u00e9voit une surface constructible maximale de 25 975 m\u00e8tres carr\u00e9s, dont 23 377 m\u00e8tres carr\u00e9s seront destin\u00e9s \u00e0 des logements libres, et 1 121 m\u00e8tres carr\u00e9s seront r\u00e9serv\u00e9s \u00e0 des logements sociaux \u00e0 prix mod\u00e9r\u00e9 (Vppl), avec une surface constructible de 2 597 m\u00e8tres carr\u00e9s.<\/p>\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/01\/estado-actual-del-solar-donde-promovera-autonomy-en-avenida-san-luis-hortaleza-1024x435.jpg\"><\/figure>\n<p class=\"wp-block-paragraph\"><em>\u00c9tat actuel du terrain o\u00f9 sera construit le projet Autonomy, avenue San Luis Hortaleza<\/em><\/p>\n<p class=\"wp-block-paragraph\">Sur ce terrain de 9 514 m\u00e8tres carr\u00e9s et d&rsquo;une surface constructible de 22 039 m\u00e8tres carr\u00e9s, le fonds, par l&rsquo;interm\u00e9diaire de la soci\u00e9t\u00e9 Terciario San Luis, r\u00e9alisera un complexe r\u00e9sidentiel priv\u00e9 de sept \u00e9tages (plus un penthouse) destin\u00e9 au logement libre. Au total, le projet comprendra 250 logements, dont 50 seront sociaux, et 300 places de parking souterrain.<\/p>\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir obtenu il y a quelques jours l&rsquo;approbation de l&rsquo;\u00e9tude d\u00e9taill\u00e9e, Autonomy pr\u00e9voit de finaliser la proc\u00e9dure d&rsquo;urbanisme d\u00e9but 2026 et, dans un d\u00e9lai de dix mois, d&rsquo;obtenir le permis pour mener de front l&rsquo;urbanisation (qui d\u00e9buterait en f\u00e9vrier) et la construction. Ainsi, les travaux de construction de ces appartements commenceraient au troisi\u00e8me trimestre 2026, avec un d\u00e9lai de promotion de deux ans.<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;objectif du fonds promoteur est de vendre ces logements \u00e0 4 900 euros le m\u00e8tre carr\u00e9, plus 24 000 euros pour chaque place de parking, ce qui repr\u00e9sentera un chiffre d&rsquo;affaires de 108 millions d&rsquo;euros pour les appartements et 7,2 millions d&rsquo;euros pour les garages.<\/p>\n<p class=\"wp-block-paragraph\">Suite sur<a href=\"https:\/\/www.ejeprime.com\/residencial\/el-fondo-autonomy-logra-el-ok-definitivo-para-250-viviendas-junto-a-arturo-soria-madrid\"> Ejeprime<\/a><\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 de gestion cr\u00e9\u00e9e par l&rsquo;ancien dirigeant de Lehman Brothers, Robert Gibbins, promeut ce projet de transformation urbaine sur l&rsquo;un des rares terrains disponibles \u00e0 proximit\u00e9 du quartier d&rsquo;Arturo Soria, avec lequel elle esp\u00e8re obtenir un rendement de 21,4 %. Apr\u00e8s des ann\u00e9es de d\u00e9marches administratives, le fonds d&rsquo;investissement Autonomy, cr\u00e9\u00e9 par l&rsquo;ancien dirigeant [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":66132,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,258,4506],"tags":[4287,4288,4289,4290],"class_list":["post-66499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-hotels-living","category-projets-immo","tag-arturo-soria-madrid","tag-fonds-autonomy","tag-projet-residentiel-madrid","tag-real-estate-madrid"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=66499"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66499\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=66499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=66499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=66499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}