{"id":66462,"date":"2026-03-07T14:47:18","date_gmt":"2026-03-07T14:47:18","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/fitur-2026-en-direct-agenda-nouveautes-et-cles-du-tourisme\/"},"modified":"2026-08-26T15:56:35","modified_gmt":"2026-08-26T15:56:35","slug":"fitur-2026-en-direct-agenda-nouveautes-et-cles-du-tourisme","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/fitur-2026-en-direct-agenda-nouveautes-et-cles-du-tourisme\/","title":{"rendered":"Fitur 2026, en direct : agenda, nouveaut\u00e9s et cl\u00e9s du tourisme."},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\">La 46e \u00e9dition du<strong> <\/strong>salon Fitur ouvre ses portes \u00e0 Ifema Madrid du 21 au 25 janvier dans un contexte marqu\u00e9 par le tragique accident ferroviaire survenu \u00e0 Adamuz (Cordoue), qui a entra\u00een\u00e9 des annulations et des ajustements dans le programme du salon pendant ses premiers jours.<\/p>\n<p class=\"wp-block-paragraph\">Cet \u00e9v\u00e9nement, qui rassemble des milliers de professionnels du secteur, accueille le Mexique en tant que pays partenaire invit\u00e9 et participe pour la premi\u00e8re fois avec une repr\u00e9sentation conjointe de ses 32 \u00c9tats, tandis que l&rsquo;organisation introduit une nouveaut\u00e9 dans le calendrier, avec l&rsquo;inauguration officielle par les rois pr\u00e9vue le jeudi 22 janvier, un jour plus tard que d&rsquo;habitude. Le salon conserve sa dimension internationale, avec la pr\u00e9sence d&rsquo;entreprises, de destinations et d&rsquo;institutions de plus de 160 pays, et ajoute de nouveaux domaines ax\u00e9s sur l&rsquo;innovation et la connaissance.<\/p>\n<p class=\"wp-block-paragraph\">09:59 | 22\/01\/2026<\/p>\n<h2 class=\"wp-block-heading\"><strong>Les d\u00e9penses touristiques dans les Bal\u00e9ares atteindront 24,67 milliards d&rsquo;euros en 2026<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">\u00ab Nous avons atteint un niveau record en mati\u00e8re de d\u00e9penses touristiques et la moyenne continuera d&rsquo;augmenter en 2026 \u00bb, a d\u00e9clar\u00e9 Antoni Costa, vice-pr\u00e9sident premier et conseiller \u00e0 l&rsquo;\u00c9conomie du gouvernement des Bal\u00e9ares lors du salon Fitur 2026, indiquant qu&rsquo;en 2025, les d\u00e9penses touristiques ont augment\u00e9 de 4,9 % pour atteindre 23,446 milliards d&rsquo;euros.<\/p>\n<p class=\"wp-block-paragraph\">Selon Catalina Barcel\u00f3, directrice g\u00e9n\u00e9rale de l&rsquo;\u00c9conomie et des Statistiques, la croissance de 2025 se concentre sur la basse saison, de janvier \u00e0 avril et de novembre \u00e0 d\u00e9cembre, avec une am\u00e9lioration de 10,2 %, tandis que pendant la haute saison, elle augmente de 3,9 %.<\/p>\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.hosteltur.com\/173765_baleares-preve-que-el-gasto-turistico-en-2026-aumente-un-52-hasta-los-24670-millones.html\"><mark class=\"has-inline-color has-black-color\">Les Bal\u00e9ares pr\u00e9voient que les d\u00e9penses touristiques en 2026 augmenteront de 5,2 %, pour atteindre 24,670 milliards d&rsquo;euros.<\/mark><\/a><\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">07:39 | 22\/01\/2026<\/p>\n<h2 class=\"wp-block-heading\"><strong>Preciados (Ilunion Hotels) re\u00e7oit aujourd&rsquo;hui le prix Hosteltur de la personnalit\u00e9 touristique \u00e0 Fitur<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Le Prix Hosteltur de la personnalit\u00e9 touristique 2025 est d\u00e9cern\u00e9 aujourd&rsquo;hui \u00e0 Jos\u00e9 \u00c1ngel Preciados, directeur g\u00e9n\u00e9ral d&rsquo;Ilunion Hotels. La c\u00e9r\u00e9monie aura lieu ce jeudi 22 janvier, \u00e0 12 h, sur le stand d&rsquo;Hosteltur (10F22), pavillon 10.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/01\/M_073901_blobid1769063938108.jpg\"><\/figure>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/01\/M_073920_blobid1769063957796.jpg\"><\/figure>\n<p class=\"wp-block-paragraph\">Cette distinction r\u00e9compense une carri\u00e8re professionnelle de plus de 40 ans, et en particulier son travail \u00e0 la t\u00eate de la cha\u00eene h\u00f4teli\u00e8re du groupe social ONCE, o\u00f9 il a mis en place un mod\u00e8le de gestion engag\u00e9 envers les personnes, le secteur et la soci\u00e9t\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">07:19 | 22\/01\/2026<\/p>\n<p class=\"wp-block-paragraph\"><strong>Grimaldi va investir 1,3 milliard dans de nouveaux navires et pr\u00e9voit des b\u00e9n\u00e9fices chez Trasmed<\/strong><\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/01\/L_235847_el-grupo-grimaldi-invierte-1300-m-en-nueve-ferris-sostenibles-1024x683.jpg\"><\/figure>\n<p class=\"wp-block-paragraph\">Le<mark class=\"has-inline-color has-black-color\"> groupe Grimaldi investira 1,3 milliard d&rsquo;euros dans la construction de neuf navires de derni\u00e8re g\u00e9n\u00e9ration<\/mark> afin de progresser dans la d\u00e9carbonisation du transport maritime, une op\u00e9ration qui sera financ\u00e9e par ses propres ressources. De plus, sa filiale espagnole Trasmed a cl\u00f4tur\u00e9 l&rsquo;ann\u00e9e 2025 avec une augmentation de 10 % de ses revenus provenant des passagers et de 14 % de ceux provenant du fret, et pr\u00e9voit de r\u00e9aliser des b\u00e9n\u00e9fices nets en 2026.<\/p>\n<p class=\"wp-block-paragraph\">07:18 | 22\/01\/2026<\/p>\n<h2 class=\"wp-block-heading\"><strong>Le secteur h\u00f4telier r\u00e9clame un leadership public et une plus grande coh\u00e9rence face \u00e0 la tourismephobie<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Lors d&rsquo;une table ronde organis\u00e9e par Beonx, des dirigeants h\u00f4teliers ont d\u00e9nonc\u00e9 le manque de leadership du secteur public pour anticiper et g\u00e9rer des probl\u00e8mes structurels tels que la tourismephobie, une responsabilit\u00e9 qui, selon eux, continue de reposer de mani\u00e8re excessive sur l&rsquo;initiative priv\u00e9e.<\/p>\n<p class=\"wp-block-paragraph\">Ils r\u00e9clament une collaboration public-priv\u00e9 plus coh\u00e9rente et exemplaire, avec des engagements clairs et align\u00e9s entre le discours et l&rsquo;action, afin de maintenir la comp\u00e9titivit\u00e9 touristique de l&rsquo;Espagne.<\/p>\n<p class=\"wp-block-paragraph\">\u00c0 cet \u00e9gard, Beatriz Miguel (Ilunion Hotels) a soulign\u00e9 \u00ab l&rsquo;importance de la collaboration public-priv\u00e9, chacun assumant ses responsabilit\u00e9s avec un leadership exemplaire et une coh\u00e9rence entre ce que l&rsquo;on dit et ce que l&rsquo;on fait. Car le secteur public a pour mission et responsabilit\u00e9 de garantir que l&rsquo;Espagne reste une r\u00e9f\u00e9rence en mati\u00e8re de tourisme \u00bb<\/p>\n<p class=\"wp-block-paragraph\">En outre, ils soulignent la n\u00e9cessit\u00e9 de simplifier les proc\u00e9dures administratives et de raccourcir les d\u00e9lais, en avertissant que les retards dans l&rsquo;octroi des licences et la vision \u00e0 court terme des administrations entravent les investissements et mettent en p\u00e9ril la durabilit\u00e9 du mod\u00e8le touristique \u00e0 long terme.<\/p>\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.hosteltur.com\/173757_como-es-el-liderazgo-con-mas-generaciones-que-nunca-en-las-cadenas-hoteleras.html\"><mark class=\"has-inline-color has-black-color\">\u00c0 quoi ressemble le leadership avec plus de g\u00e9n\u00e9rations que jamais dans les cha\u00eenes h\u00f4teli\u00e8res ?<\/mark><\/a><\/li>\n<\/ul>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/01\/M_071711_blobid1769062628014.jpg\"><\/figure>\n<p class=\"wp-block-paragraph\">06:56 | 22\/01\/2026<\/p>\n<h2 class=\"wp-block-heading\"><strong>Les rois inaugurent officiellement Fitur ce jeudi<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Aujourd&rsquo;hui, jeudi 22 janvier, a lieu l&rsquo;inauguration officielle de Fitur, un \u00e9v\u00e9nement pr\u00e9sid\u00e9 par les rois d&rsquo;Espagne, Don Felipe et Do\u00f1a Letizia, dont le d\u00e9but est pr\u00e9vu \u00e0 10h30.<\/p>\n<p class=\"wp-block-paragraph\">Les m\u00e9dias graphiques et t\u00e9l\u00e9vis\u00e9s qui souhaitent couvrir l&rsquo;inauguration doivent \u00eatre accr\u00e9dit\u00e9s en tant que presse et se pr\u00e9senter \u00e0 9h30 \u00e0 la Puerta Norte, point de rencontre \u00e9tabli pour le contr\u00f4le des \u00e9quipements et l&rsquo;accr\u00e9ditation sp\u00e9cifique \u00e0 l&rsquo;\u00e9v\u00e9nement. L&rsquo;organisation demande \u00e0 tous d&rsquo;\u00eatre ponctuels, d&rsquo;apporter leur accr\u00e9ditation imprim\u00e9e et de faciliter la v\u00e9rification des \u00e9quipements techniques par la s\u00e9curit\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">Une fois la visite inaugurale commenc\u00e9e, les journalistes ne seront plus autoris\u00e9s \u00e0 rejoindre le cort\u00e8ge.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/01\/M_065722_blobid1769061437733.jpg\"><\/figure>\n<p class=\"wp-block-paragraph\">17:04 | 21\/01\/2026<\/p>\n<h2 class=\"wp-block-heading\"><strong>Le changement des habitudes de voyage favorise une nouvelle mobilit\u00e9<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">La moiti\u00e9 des conducteurs espagnols modifient leur fa\u00e7on de voyager pendant les vacances en raison de la hausse des prix et de la congestion, selon l&rsquo;\u00ab \u00c9tude sur la mobilit\u00e9 du futur 2025 \u00bb, r\u00e9alis\u00e9e par Europcar Mobility Group et le Mobility Institute, qui a \u00e9t\u00e9 pr\u00e9sent\u00e9e mercredi \u00e0 Fitur.<\/p>\n<p class=\"wp-block-paragraph\">Parmi les nouvelles habitudes touristiques, le rapport, promu par le RACC et Deloitte, souligne la pr\u00e9f\u00e9rence pour les d\u00e9placements hors saison, selon 20,6 % des personnes interrog\u00e9es, les escapades plus courtes (15,7 %) et les voyages vers des zones moins fr\u00e9quent\u00e9es (13,2 %).<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/01\/M_170836_blobid1769011712510.jpg\"><\/figure>\n<p class=\"wp-block-paragraph\">14:42 | 21\/01\/2026<\/p>\n<h2 class=\"wp-block-heading\"><strong>Pi\u00f1ero et Hyatt : bilan de la premi\u00e8re ann\u00e9e du partenariat strat\u00e9gique<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Dans le cadre du salon Fitur, Encarna Pi\u00f1ero<strong>,<\/strong> PDG mondiale de Pi\u00f1ero et pr\u00e9sidente de Bahia Principe Hotels &amp; Resorts ; Javier \u00c1guila<strong>,<\/strong> pr\u00e9sident mondial de l&rsquo;Inclusive Collection de Hyatt, et Julio P\u00e9rez, PDG de Bah\u00eda Pr\u00edncipe Hotels &amp; Resorts, ont analys\u00e9 la premi\u00e8re ann\u00e9e de la joint-venture et leur plan pour 2026, ax\u00e9 sur l&rsquo;am\u00e9lioration du positionnement de la marque et de l&rsquo;exp\u00e9rience client sur les march\u00e9s cl\u00e9s.<\/p>\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.hosteltur.com\/173754_los-ejes-de-expansion-de-bahia-principe-norte-de-africa-caribe-y-mediterraneo.html\"><mark class=\"has-inline-color has-black-color\">Les axes d&rsquo;expansion de Bah\u00eda Pr\u00edncipe : Afrique du Nord, Cara\u00efbes et M\u00e9diterran\u00e9e<\/mark><\/a><\/li>\n<\/ul>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/01\/M_144153_blobid1769002890620.jpg\"><\/figure>\n<p class=\"wp-block-paragraph\">14h15 | 21\/01\/2026<\/p>\n<h2 class=\"wp-block-heading\"><strong>La CEAV fait le bilan de l&rsquo;ann\u00e9e 2025 avec de nouveaux partenaires et des destinations premium alli\u00e9es<\/strong><\/h2>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/immo.lecourrier.es\/wp-content\/uploads\/2026\/01\/M_140927_blobid1769000964820.jpg\"><\/figure>\n<p class=\"wp-block-paragraph\">La <mark class=\"has-inline-color has-black-color\">Conf\u00e9d\u00e9ration espagnole des agences de voyages (CEAV) <\/mark>pr\u00e9voit une ann\u00e9e 2025 positive pour le r\u00e9seau d&rsquo;associations d&rsquo;agences de voyages, qui compte 37 membres, un total de 36 partenaires, avec de nouvelles incorporations telles que Revolut, et trois destinations premium alli\u00e9es : l&rsquo;Andalousie, l&rsquo;Allemagne et le Maroc.<\/p>\n<p class=\"wp-block-paragraph\">Pour cette ann\u00e9e, la CEAV a annonc\u00e9, dans le cadre du<mark class=\"has-inline-color has-black-color\"> salon Fitur<\/mark>, qu&rsquo;elle comptera une nouvelle destination internationale partenaire : Abu Dhabi. Au niveau national, elle unira ses efforts avec l&rsquo;Aragon et Le\u00f3n, entre autres<strong>.<\/strong><\/p>\n<p class=\"wp-block-paragraph\">Suite sur <a href=\"https:\/\/www.hosteltur.com\/173735_fitur-2026-en-directo-agenda-novedades-y-claves-del-turismo.html\"><mark class=\"has-inline-color has-black-color\">HOSTELTUR<\/mark><\/a><\/p>\n<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 46e \u00e9dition du salon Fitur ouvre ses portes \u00e0 Ifema Madrid du 21 au 25 janvier dans un contexte marqu\u00e9 par le tragique accident ferroviaire survenu \u00e0 Adamuz (Cordoue), qui a entra\u00een\u00e9 des annulations et des ajustements dans le programme du salon pendant ses premiers jours. Cet \u00e9v\u00e9nement, qui rassemble des milliers de professionnels [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":66232,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,258,4440],"tags":[4366,704,1639],"class_list":["post-66462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-hotels-living","category-networking","tag-evenement-madrid","tag-fitur","tag-ifema"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=66462"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66462\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=66462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=66462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=66462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}