{"id":66459,"date":"2026-03-07T14:42:31","date_gmt":"2026-03-07T14:42:31","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/le-sol-urbanise-en-espagne-offre-un-potentiel-de-construction-denviron-500-000-immeubles\/"},"modified":"2026-08-26T15:41:03","modified_gmt":"2026-08-26T15:41:03","slug":"le-sol-urbanise-en-espagne-offre-un-potentiel-de-construction-denviron-500-000-immeubles","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/le-sol-urbanise-en-espagne-offre-un-potentiel-de-construction-denviron-500-000-immeubles\/","title":{"rendered":"Le sol urbanis\u00e9 en Espagne offre un potentiel de construction d&rsquo;environ 500 000 immeubles."},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>Le minist\u00e8re du Logement r\u00e9clame un syst\u00e8me statistique public sur le logement afin de ne plus d\u00e9pendre des donn\u00e9es priv\u00e9es, tandis que l&rsquo;INE affirme que des am\u00e9liorations des statistiques immobili\u00e8res sont d\u00e9j\u00e0 \u00e0 l&rsquo;\u00e9tude.<\/em><\/p>\n<p class=\"wp-block-paragraph\">Les terrains urbanis\u00e9s en Espagne dans les secteurs r\u00e9sidentiels de plus de 1 000 logements ont le potentiel de construire environ 500 000 immeubles, selon les informations communiqu\u00e9es mercredi par le sous-directeur g\u00e9n\u00e9ral du sol et de l&rsquo;information du minist\u00e8re du Logement et de l&rsquo;Agenda urbain, Miguel Baiget, lors de la conf\u00e9rence \u00ab Rencontre des producteurs et des utilisateurs de statistiques immobili\u00e8res \u00bb.<\/p>\n<p class=\"wp-block-paragraph\">Lors de sa participation \u00e0 la table ronde \u00ab Mesure de l&rsquo;offre de logements neufs et de terrains \u00bb de la conf\u00e9rence, l&rsquo;expert a indiqu\u00e9 que ces donn\u00e9es sont tir\u00e9es d&rsquo;une nouvelle \u00e9tude en cours d&rsquo;\u00e9laboration par le minist\u00e8re du Logement et qui sera publi\u00e9e dans les prochains jours. La c\u00e9r\u00e9monie a \u00e9t\u00e9 inaugur\u00e9e par la pr\u00e9sidente de l&rsquo;Institut national de statistique (INE), Elena Manzanera, le directeur g\u00e9n\u00e9ral de l&rsquo;\u00e9conomie de la Banque d&rsquo;Espagne, David L\u00f3pez, et le secr\u00e9taire d&rsquo;\u00c9tat au Logement, David Lucas, rapporte <em>Europa Press<\/em>.<\/p>\n<p class=\"wp-block-paragraph\">R\u00e9cemment, le dernier rapport \u00ab Suelos 2026 \u00bb (Terrains 2026) r\u00e9alis\u00e9 par le cabinet de conseil Atlas Real Estate indiquait qu&rsquo;avec les terrains disponibles en termes agr\u00e9g\u00e9s, il serait th\u00e9oriquement possible de construire pr\u00e8s de 7 millions de logements, mais la r\u00e9alit\u00e9 est bien diff\u00e9rente, puisque ce rapport r\u00e9v\u00e8le que moins de 0,5 % est actuellement en cours de construction, tandis que plus de 74 % reste non urbanis\u00e9, ce qui constitue une limite structurelle insurmontable pour que le secteur de la promotion immobili\u00e8re puisse r\u00e9pondre aux besoins en logements du pays.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Le Conseil consultatif du logement disposera d&rsquo;un groupe de travail charg\u00e9 de faire progresser la transparence des donn\u00e9es afin de mettre en place un syst\u00e8me rigoureux.<\/strong><\/p>\n<p class=\"wp-block-paragraph\">Au cours de ces journ\u00e9es, David Lucas a revendiqu\u00e9 la n\u00e9cessit\u00e9 de mettre en place un syst\u00e8me statistique public sur le logement, avec des donn\u00e9es fiables, homog\u00e8nes et accessibles depuis tout le territoire national, afin de ne pas d\u00e9pendre des statistiques priv\u00e9es. Pour y parvenir, il a soulign\u00e9 que le gouvernement entretenait des alliances avec la Banque d&rsquo;Espagne et l&rsquo;Institut national de statistique (INE), entre autres.<\/p>\n<p class=\"wp-block-paragraph\">M. Lucas a rappel\u00e9 que le Conseil consultatif du logement, cr\u00e9\u00e9 la semaine derni\u00e8re, disposera d&rsquo;un groupe de travail charg\u00e9 de faire progresser la transparence des donn\u00e9es afin de mettre en place un syst\u00e8me rigoureux. En outre, il a soulign\u00e9 que le projet de plan national pour le logement 2026-2030, qui est sur le point d&rsquo;\u00eatre mis en \u0153uvre, a pour objectif de cr\u00e9er une base de donn\u00e9es dans le domaine du logement et de la location afin de travailler de mani\u00e8re fiable sur les politiques de logement.<\/p>\n<p class=\"wp-block-paragraph\">\u00ab L&rsquo;objectif est de disposer d&rsquo;informations solides, comparables et transparentes, qui permettent d&rsquo;\u00e9valuer les politiques publiques, de bien planifier et, surtout, de garantir les droits des acheteurs, des vendeurs, des bailleurs, des locataires et de tous ceux qui agissent dans le domaine immobilier et qui sont indispensables pour continuer \u00e0 garantir le droit \u00e0 un logement d\u00e9cent, ad\u00e9quat et abordable \u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">Pour sa part, la pr\u00e9sidente de l&rsquo;INE a soulign\u00e9 la n\u00e9cessit\u00e9 d&rsquo;adapter \u00ab autant que possible \u00bb la production statistique aux besoins des utilisateurs et a indiqu\u00e9 que ces journ\u00e9es marquent le point de d\u00e9part d&rsquo;un nouveau comit\u00e9 technique sectoriel sur les statistiques immobili\u00e8res qui, au sein du Conseil sup\u00e9rieur des statistiques, aura pour mission d&rsquo;\u00e9tudier et d&rsquo;analyser la production statistique en vue de son am\u00e9lioration, en mettant l&rsquo;accent sur le Plan statistique national 2029-2032.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Le nouveau r\u00e8glement sur les statistiques immobili\u00e8res fixera une nouvelle r\u00e9f\u00e9rence pour la disponibilit\u00e9 des statistiques sur les prix \u00e0 l&rsquo;\u00e9chelle europ\u00e9enne<\/strong><\/p>\n<p class=\"wp-block-paragraph\">Au cours de son intervention, M. Manzanera a indiqu\u00e9 que l&rsquo;INE travaille d\u00e9j\u00e0 sur le recensement europ\u00e9en de 2026, devan\u00e7ant ainsi les d\u00e9lais de la r\u00e9glementation europ\u00e9enne, et que le nouveau r\u00e8glement sur les statistiques immobili\u00e8res \u00e9tablira une nouvelle r\u00e9f\u00e9rence en mati\u00e8re de disponibilit\u00e9 des statistiques sur les prix \u00e0 l&rsquo;\u00e9chelle europ\u00e9enne, y compris les donn\u00e9es sur l&rsquo;activit\u00e9 immobili\u00e8re commerciale.<\/p>\n<p class=\"wp-block-paragraph\">Le directeur g\u00e9n\u00e9ral de l&rsquo;\u00e9conomie de la Banque d&rsquo;Espagne a quant \u00e0 lui soulign\u00e9 l&rsquo;importance de disposer de donn\u00e9es immobili\u00e8res pour comprendre l&rsquo;\u00e9conomie espagnole.<\/p>\n<p class=\"wp-block-paragraph\">Source <a href=\"https:\/\/www.ejeprime.com\/residencial\/el-suelo-urbanizado-en-espana-tiene-potencial-para-edificar-unos-500000-inmuebles\" id=\"https:\/\/www.ejeprime.com\/residencial\/el-suelo-urbanizado-en-espana-tiene-potencial-para-edificar-unos-500000-inmuebles\"><mark class=\"has-inline-color has-black-color\">EJEPRIME<\/mark><\/a><\/p>\n<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le minist\u00e8re du Logement r\u00e9clame un syst\u00e8me statistique public sur le logement afin de ne plus d\u00e9pendre des donn\u00e9es priv\u00e9es, tandis que l&rsquo;INE affirme que des am\u00e9liorations des statistiques immobili\u00e8res sont d\u00e9j\u00e0 \u00e0 l&rsquo;\u00e9tude. Les terrains urbanis\u00e9s en Espagne dans les secteurs r\u00e9sidentiels de plus de 1 000 logements ont le potentiel de construire environ [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":66241,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,4506],"tags":[1195,1666],"class_list":["post-66459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-projets-immo","tag-construction-en-espagne","tag-ine"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=66459"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66459\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=66459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=66459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=66459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}