{"id":66452,"date":"2026-03-07T14:36:43","date_gmt":"2026-03-07T14:36:43","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/dubai-holding-rachete-lhotel-jumeirah-port-soller-a-majorque-a-deka-immobilien\/"},"modified":"2026-08-26T15:24:54","modified_gmt":"2026-08-26T15:24:54","slug":"dubai-holding-rachete-lhotel-jumeirah-port-soller-a-majorque-a-deka-immobilien","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/dubai-holding-rachete-lhotel-jumeirah-port-soller-a-majorque-a-deka-immobilien\/","title":{"rendered":"Dubai Holding rach\u00e8te l&rsquo;h\u00f4tel Jumeirah Port S\u00f3ller \u00e0 Majorque \u00e0 Deka Immobilien."},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em>Cette op\u00e9ration renforce le portefeuille d&rsquo;h\u00f4tels de luxe de la soci\u00e9t\u00e9 \u00e9miratie.<\/em><\/p>\n<p class=\"wp-block-paragraph\">Deka Immobilien a annonc\u00e9 la vente de l&rsquo;h\u00f4tel 5 \u00e9toiles Jumeirah Port S\u00f3ller Hotel &amp; Spa, situ\u00e9 \u00e0 Majorque, \u00e0 Dubai Holding LLC, propri\u00e9taire du Jumeirah Group, dans le cadre d&rsquo;une op\u00e9ration qui renforce la pr\u00e9sence du groupe \u00e9mirati dans le segment du luxe en Europe et confirme le fort app\u00e9tit des investisseurs pour les actifs h\u00f4teliers de premier ordre dans des destinations consolid\u00e9es telles que les Bal\u00e9ares. Le montant de la transaction n&rsquo;a pas \u00e9t\u00e9 divulgu\u00e9.<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;actif, situ\u00e9 sur la c\u00f4te nord-ouest de l&rsquo;\u00eele, rejoint le portefeuille de Dubai Holding, qui a annonc\u00e9 l&rsquo;op\u00e9ration dans le cadre de sa strat\u00e9gie de croissance internationale dans le secteur de l&rsquo;h\u00f4tellerie.<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9tablissement compte 121 chambres, dont 15 suites, 58 places de parking et un terrain attenant non am\u00e9nag\u00e9, pouvant \u00eatre utilis\u00e9 comme zone de loisirs locale, r\u00e9serve naturelle ou, de mani\u00e8re limit\u00e9e, \u00e0 des fins agricoles. L&rsquo;h\u00f4tel est lou\u00e9 \u00e0 long terme \u00e0 Jumeirah Port Soller Mallorca, S.L. et continuera d&rsquo;\u00eatre exploit\u00e9 par Jumeirah, la marque h\u00f4teli\u00e8re phare de Dubai Holding, sp\u00e9cialis\u00e9e dans le segment du luxe.<\/p>\n<p class=\"wp-block-paragraph\">L&rsquo;un des \u00e9l\u00e9ments distinctifs de cet h\u00f4tel de luxe est sa certification LEED Platinum, la plus haute distinction en mati\u00e8re d&rsquo;efficacit\u00e9 \u00e9nerg\u00e9tique et de durabilit\u00e9 environnementale, ainsi que son emplacement privil\u00e9gi\u00e9 avec vue sur la M\u00e9diterran\u00e9e et la Serra de Tramuntana, class\u00e9e au patrimoine mondial de l&rsquo;UNESCO.<\/p>\n<p class=\"wp-block-paragraph\">Deka Immobilien explique que ce d\u00e9sinvestissement s&rsquo;inscrit dans le cadre de sa strat\u00e9gie de gestion active de portefeuille, tirant parti du fort int\u00e9r\u00eat du march\u00e9 pour les h\u00f4tels haut de gamme \u00e0 Majorque.<\/p>\n<p class=\"wp-block-paragraph\">De son c\u00f4t\u00e9, Dubai Holding a annonc\u00e9 son intention d&rsquo;investir dans l&rsquo;am\u00e9lioration de l&rsquo;offre de l&rsquo;h\u00f4tel afin de le positionner comme l&rsquo;un des \u00e9tablissements phares de Jumeirah en M\u00e9diterran\u00e9e. Selon Amit Kaushal, PDG du groupe, cette acquisition \u00ab renforce notre portefeuille h\u00f4telier mondial et notre engagement en faveur d&rsquo;actifs de haute qualit\u00e9 g\u00e9n\u00e9rant de la valeur \u00e0 long terme \u00bb.<\/p>\n<p class=\"wp-block-paragraph\">Avec cette op\u00e9ration, Dubai Holding Hospitality \u00e9tend son portefeuille immobilier \u00e0 34 h\u00f4tels et complexes touristiques \u00e0 travers le monde, dont cinq \u00e9tablissements Jumeirah en Europe. Le groupe exploite actuellement 29 h\u00f4tels sous la marque Jumeirah dans des destinations cl\u00e9s et continue de renforcer sa pr\u00e9sence sur le continent, o\u00f9 il poss\u00e8de d\u00e9j\u00e0 des actifs \u00e0 Londres et \u00e0 Capri et pr\u00e9pare l&rsquo;ouverture du Jumeirah Le Richemond Geneva, en Suisse.<\/p>\n<p class=\"wp-block-paragraph\"><mark class=\"has-inline-color has-black-color\">Source: <\/mark><a href=\"https:\/\/www.hosteltur.com\/173787_pinero-abrira-en-primavera-su-primer-establecimiento-urbano-el-terreno-barrio-hotel.html\"><mark class=\"has-inline-color has-black-color\">HOSTELTUR<\/mark><\/a><\/p>\n<\/p>\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette op\u00e9ration renforce le portefeuille d&rsquo;h\u00f4tels de luxe de la soci\u00e9t\u00e9 \u00e9miratie. Deka Immobilien a annonc\u00e9 la vente de l&rsquo;h\u00f4tel 5 \u00e9toiles Jumeirah Port S\u00f3ller Hotel &amp; Spa, situ\u00e9 \u00e0 Majorque, \u00e0 Dubai Holding LLC, propri\u00e9taire du Jumeirah Group, dans le cadre d&rsquo;une op\u00e9ration qui renforce la pr\u00e9sence du groupe \u00e9mirati dans le segment du [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":66257,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212,258,4503],"tags":[4384,4385,4386,4387],"class_list":["post-66452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","category-hotels-living","category-transport","tag-amit-kaushal","tag-dubai-holding","tag-hotel-jumeirah-port-soller","tag-leed-platinum"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=66452"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66452\/revisions"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=66452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=66452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=66452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}