{"id":66445,"date":"2026-03-07T14:31:07","date_gmt":"2026-03-07T14:31:07","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/la-banque-santander-prepare-un-nouveau-fonds-pour-investir-dans-le-developpement-immobilier-2\/"},"modified":"2026-08-26T14:54:06","modified_gmt":"2026-08-26T14:54:06","slug":"la-banque-santander-prepare-un-nouveau-fonds-pour-investir-dans-le-developpement-immobilier-2","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/03\/07\/la-banque-santander-prepare-un-nouveau-fonds-pour-investir-dans-le-developpement-immobilier-2\/","title":{"rendered":"La banque Santander pr\u00e9pare un nouveau fonds pour investir dans le d\u00e9veloppement immobilier."},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"wp-block-paragraph\"><em><em>Avec son nouvel accent mis sur le logement et le d\u00e9veloppement de nouveaux projets immobiliers, l&rsquo;entreprise a d\u00e9j\u00e0 mis en place une strat\u00e9gie visant \u00e0 investir dans le co-living et les h\u00e9bergements temporaires, ainsi qu&rsquo;\u00e0 acqu\u00e9rir des locaux, des centres commerciaux et des parcs commerciaux.<\/em><\/em><\/p>\n<p class=\"wp-block-paragraph\">Santander finalise la mise en place d&rsquo;un nouveau fonds immobilier qui se distingue par le fait qu&rsquo;il est le premier \u00e0 se concentrer sur le d\u00e9veloppement r\u00e9sidentiel. Jusqu&rsquo;\u00e0 pr\u00e9sent, l&rsquo;\u00e9tablissement financier avait mis en place des strat\u00e9gies pour investir dans <em>le coliving <\/em>et les logements temporaires, ainsi qu&rsquo;une autre pour acqu\u00e9rir des locaux, des centres et des parcs commerciaux. Avec ce nouveau v\u00e9hicule, il se concentre sur le logement et le d\u00e9veloppement de nouvelles promotions.<\/p>\n<p class=\"wp-block-paragraph\">Selon <em>Bloomberg<\/em>, ce v\u00e9hicule sera lanc\u00e9 dans les prochains mois et l&rsquo;objectif est de lever environ 200 millions d&rsquo;euros de capitaux, un montant similaire \u00e0 celui des pr\u00e9c\u00e9dents : pour le <em>coliving<\/em>, il a obtenu 220 millions dans deux v\u00e9hicules diff\u00e9rents, et pour les actifs commerciaux, il s&rsquo;est fix\u00e9 un objectif de 150 millions. Dans tous les cas, Santander participe directement, avec un apport financier provenant de son propre bilan et un effet de levier compris entre 50 % et 60 %.<\/p>\n<p class=\"wp-block-paragraph\">Bien qu&rsquo;il s&rsquo;agisse du premier fonds lanc\u00e9 par la soci\u00e9t\u00e9 de gestion de Santander pour le d\u00e9veloppement r\u00e9sidentiel, ce n&rsquo;est pas la seule exposition de la banque au march\u00e9 immobilier. Au-del\u00e0 de son activit\u00e9 de cr\u00e9dit, qu&rsquo;il s&rsquo;agisse de pr\u00eats hypoth\u00e9caires ou de pr\u00eats aux promoteurs et aux entreprises, l&rsquo;\u00e9tablissement dispose \u00e9galement d&rsquo;un fonds de dette immobili\u00e8re.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Par l&rsquo;interm\u00e9diaire de Santander Alternative Investment, il a lanc\u00e9 un fonds d&rsquo;investissement immobilier qui vise \u00e0 lever 150 millions et \u00e0 investir dans le <em>commerce de d\u00e9tail<\/em>.<\/strong><\/p>\n<p class=\"wp-block-paragraph\">Il est le premier actionnaire de l&rsquo;une des plus grandes soci\u00e9t\u00e9s immobili\u00e8res du pays, Metrovacesa, dont il d\u00e9tient 49 % du capital, et de 100 % de LandCo, la plus grande soci\u00e9t\u00e9 priv\u00e9e fonci\u00e8re d&rsquo;Espagne. Comme l&rsquo;avait annonc\u00e9 EjePrime en octobre dernier, la soci\u00e9t\u00e9 dirig\u00e9e par Alberto Quemada se concentre actuellement sur la recherche d&rsquo;un nouveau partenaire pour r\u00e9aliser des co-investissements, apr\u00e8s celui conclu avec Patron Capital l&rsquo;ann\u00e9e derni\u00e8re pour investir 100 millions d&rsquo;euros dans la promotion de plus de 1 300 logements. \u00ab Nous sommes en train de d\u00e9finir le p\u00e9rim\u00e8tre du portefeuille, de pr\u00e9parer les terrains et je pense que nous commencerons bient\u00f4t \u00e0 rechercher un partenaire afin d&rsquo;\u00eatre pr\u00eats au premier trimestre 2026 \u00bb, a d\u00e9clar\u00e9 M. Quemada dans une interview accord\u00e9e \u00e0 ce m\u00e9dia.<\/p>\n<p class=\"wp-block-paragraph\">En dehors du secteur r\u00e9sidentiel, il convient de souligner sa participation dans la socimi Merlin Properties, dont il est le premier actionnaire avec 22,3 % du capital, et dans la soci\u00e9t\u00e9 de d\u00e9tention et de gestion d&rsquo;actifs commerciaux RetailCo. Il y a quelques jours, on a appris que Banco Santander, par l&rsquo;interm\u00e9diaire de Santander Alternative Investment, soci\u00e9t\u00e9 de gestion d\u00e9pendant de Santander Asset Management, a lanc\u00e9 un fonds d&rsquo;investissement immobilier qui vise \u00e0 lever 150 millions d&rsquo;euros et \u00e0 investir jusqu&rsquo;\u00e0 300 millions d&rsquo;euros dans le secteur du commerce de d\u00e9tail. Ce v\u00e9hicule sera g\u00e9r\u00e9 par Retailco, filiale de l&rsquo;entit\u00e9 cr\u00e9\u00e9e en 2021 pour la gestion des locaux des succursales bancaires ferm\u00e9es par la banque.<\/p>\n<p class=\"wp-block-paragraph\">Selon des sources proches de la soci\u00e9t\u00e9 de gestion de la banque, le fonds a d\u00e9j\u00e0 re\u00e7u l&rsquo;accord de la Commission nationale du march\u00e9 des valeurs (Cnmv) depuis d\u00e9cembre dernier et r\u00e9pond \u00e0 l&rsquo;int\u00e9r\u00eat de la banque, d&rsquo;abord pour le secteur immobilier et, plus pr\u00e9cis\u00e9ment, pour le secteur du commerce de d\u00e9tail. Le groupe Santander engagera 30 millions d&rsquo;euros d&rsquo;\u00e9quit\u00e9 dans le v\u00e9hicule, soit environ 20 % du total \u00e0 lever dans le cadre de la collecte de fonds, selon plusieurs m\u00e9dias.<\/p>\n<p class=\"wp-block-paragraph\"><mark class=\"has-inline-color has-black-color\">Source:<\/mark><a href=\"https:\/\/www.ejeprime.com\/mercado\/banco-santander-prepara-un-nuevo-fondo-para-invertir-en-el-desarrollo-inmobiliario\" id=\"https:\/\/www.ejeprime.com\/mercado\/banco-santander-prepara-un-nuevo-fondo-para-invertir-en-el-desarrollo-inmobiliario\"><mark class=\"has-inline-color has-black-color\"> EJEPRIME<\/mark><\/a><\/p>\n<\/p>\n<p class=\"wp-block-paragraph\">\n<p><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec son nouvel accent mis sur le logement et le d\u00e9veloppement de nouveaux projets immobiliers, l&rsquo;entreprise a d\u00e9j\u00e0 mis en place une strat\u00e9gie visant \u00e0 investir dans le co-living et les h\u00e9bergements temporaires, ainsi qu&rsquo;\u00e0 acqu\u00e9rir des locaux, des centres commerciaux et des parcs commerciaux. Santander finalise la mise en place d&rsquo;un nouveau fonds immobilier [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":66271,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[4401,4402,4403],"class_list":["post-66445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-alberto-quemada","tag-banque-santander","tag-developpement-residentiel"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=66445"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/66271"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=66445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=66445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=66445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}