{"id":66320,"date":"2026-02-14T14:39:05","date_gmt":"2026-02-14T14:39:05","guid":{"rendered":"https:\/\/immo.lecourrier.es\/index.php\/2026\/02\/14\/blanq-hotels-renforce-sa-presence-a-valencia-avec-un-nouvel-hotel-en-plein-centre\/"},"modified":"2026-05-08T15:06:48","modified_gmt":"2026-05-08T15:06:48","slug":"blanq-hotels-renforce-sa-presence-a-valencia-avec-un-nouvel-hotel-en-plein-centre","status":"publish","type":"post","link":"https:\/\/immo.lecourrier.es\/index.php\/2026\/02\/14\/blanq-hotels-renforce-sa-presence-a-valencia-avec-un-nouvel-hotel-en-plein-centre\/","title":{"rendered":"L&#8217;investissement h\u00f4telier \u00e0 Barcelone se redresse en 2019 et augmente de 37,5%"},"content":{"rendered":"<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\"><\/p>\n<p class=\"long\">L&#8217;investissement h\u00f4telier \u00e0 Barcelone a atteint 264 millions d&#8217;euros en 2019, soit 37,5 % de plus qu&#8217;en 2018, mais encore loin des chiffres enregistr\u00e9s en 2017, o\u00f9 des op\u00e9rations d&#8217;une valeur de 362 millions ont \u00e9t\u00e9 cl\u00f4tur\u00e9es. (Hosteltur)<\/p>\n<p class=\"long\"><span class=\"times-dropcap\">J<\/span>uan Gallardo, le responsable des h\u00f4tels du promoteur et de la soci\u00e9t\u00e9 de conseil immobilier 3Capital, a expliqu\u00e9 \u00e0 l&#8217;Efe que 2017 \u00e9tait une ann\u00e9e record pour les investissements h\u00f4teliers dans la ville, malgr\u00e9 le fait que le dernier trimestre de l&#8217;ann\u00e9e ait \u00e9t\u00e9 affect\u00e9 par la situation politique en Catalogne.<\/p>\n<p>Selon Gallardo, \u00e0 partir du jour du r\u00e9f\u00e9rendum du 1-O 2017 et des images des charges de la police, &#8220;tout s&#8217;est arr\u00eat\u00e9&#8221; en raison de l&#8217;incertitude qui existait en Catalogne, et son impact n\u00e9gatif sur l&#8217;investissement h\u00f4telier a dur\u00e9 tout au long de l\u2019ann\u00e9e 2018.<\/p>\n<p>Il consid\u00e8re donc que les chiffres atteints en 2019 sont &#8220;bons&#8221; car cela signifie qu&#8217;il y a une reprise, qui a d\u00e9j\u00e0 commenc\u00e9 \u00e0 \u00eatre remarqu\u00e9e en f\u00e9vrier de l&#8217;ann\u00e9e derni\u00e8re.<\/p>\n<p>Les principaux acteurs de l&#8217;investissement h\u00f4telier \u00e0 Barcelone en 2019 \u00e9taient les fonds d&#8217;investissement et les socimis, contrairement aux ann\u00e9es pr\u00e9c\u00e9dentes, o\u00f9 la majorit\u00e9 des op\u00e9rations correspondaient \u00e0 des cha\u00eenes h\u00f4teli\u00e8res d\u00e9tentrices d&#8217;actifs, principalement espagnoles, qui pr\u00e9f\u00e8rent d\u00e9sormais rester dans le domaine de la gestion.<\/p>\n<p>Les investisseurs internationaux repr\u00e9sentent 40 % du total des acquisitions r\u00e9alis\u00e9es dans la ville, bien que ce pourcentage ait \u00e9t\u00e9 influenc\u00e9 par des op\u00e9rations telles que l&#8217;achat de terrains \u00e0 Sant Adri\u00e0 de Bes\u00f2s par ASG o\u00f9 un h\u00f4tel g\u00e9r\u00e9 par Hard Rock ouvrira en 2022.<\/p>\n<p>Selon le responsable des h\u00f4tels de 3Capital, comme il y avait peu de produits dans la ville, les prix de vente par chambre ont augment\u00e9 et la rentabilit\u00e9 moyenne des op\u00e9rations est tomb\u00e9e \u00e0 des &#8220;minima historiques&#8221;.<\/p>\n<p>L&#8217;un des effets du moratoire sur les h\u00f4tels \u00e0 Barcelone et du Plan sp\u00e9cial d&#8217;urbanisme pour l&#8217;h\u00e9bergement touristique (PEUAT) est d&#8217;avoir cr\u00e9\u00e9 une &#8220;inflation soudaine&#8221; et, avant la crise, il existait encore des h\u00f4tels \u00e0 vendre \u00e0 400.000 euros la chambre et dont les prix \u00e9taient exorbitants.<\/p>\n<hr \/>\n<p>Source et suite : <a href=\"https:\/\/www.hosteltur.com\/134605_la-inversion-hotelera-en-barcelona-se-recupera-en-2019-y-crece-un-375.html\">Hosteltur<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;investissement h\u00f4telier \u00e0 Barcelone a atteint 264 millions d&#8217;euros en 2019, soit 37,5 % de plus qu&#8217;en 2018, mais encore loin des chiffres enregistr\u00e9s en 2017, o\u00f9 des op\u00e9rations d&#8217;une valeur de 362 millions ont \u00e9t\u00e9 cl\u00f4tur\u00e9es. (Hosteltur) Juan Gallardo, le responsable des h\u00f4tels du promoteur et de la soci\u00e9t\u00e9 de conseil immobilier 3Capital, a [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":33830,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[212],"tags":[1317,1318],"class_list":["post-66320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breaking-news","tag-investir-a-barcelone","tag-investissement-hotelier-espagne"],"acf":[],"_links":{"self":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/comments?post=66320"}],"version-history":[{"count":0,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/posts\/66320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media\/33830"}],"wp:attachment":[{"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/media?parent=66320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/categories?post=66320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immo.lecourrier.es\/index.php\/wp-json\/wp\/v2\/tags?post=66320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}